{"id":15640,"date":"2018-06-11T11:00:40","date_gmt":"2018-06-11T10:00:40","guid":{"rendered":"http:\/\/leregardlibre.com\/?p=15640"},"modified":"2025-12-13T22:54:49","modified_gmt":"2025-12-13T21:54:49","slug":"wahlen-in-pakistan-unter-spannungen","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/politik\/welt\/wahlen-in-pakistan-unter-spannungen\/","title":{"rendered":"Wahlen in Pakistan unter Spannungen"},"content":{"rendered":"<p><em>Les lundis de l'actualit\u00e9 - Cl\u00e9ment Guntern<\/em><\/p>\n<p>Am 25. Juli dieses Jahres finden in Pakistan Parlamentswahlen statt. Eine Information, die auf den ersten Blick banal erscheinen mag. Allerdings haben sich in diesem 200-Millionen-Einwohner-Land am Rande des afghanischen Schauplatzes noch nie zwei zivile Regierungen nacheinander abgel\u00f6st. Nachdem seit 1947 mindestens 15 Staatsoberh\u00e4upter von der m\u00e4chtigen Armee abgesetzt wurden, sollte sich in der Islamischen Republik Pakistan ein Anschein von Stabilit\u00e4t eingestellt haben?<\/p>\n<p><!--more--><\/p>\n<p>Angesichts der aktuellen Gesetzgebungskampagne scheint es ein Missbrauch der Sprache zu sein, von einer liberalen Demokratie zu sprechen. Tats\u00e4chlich haben die pakistanische Armee und der pakistanische Geheimdienst, \u00e4u\u00dferst m\u00e4chtige Organe im politischen Leben Pakistans, eine Terrorkampagne unter Kritikern der Institution Milit\u00e4r durchgef\u00fchrt. Mehrere Journalisten wurden entf\u00fchrt, darunter Gul Bukhari, ein prominenter Kritiker des Milit\u00e4rs in der pakistanischen Presse. Auch in den sozialen Netzwerken herrscht Zensur; alle Sympathien f\u00fcr die zivile Regierungspartei werden kontrolliert und von der Armee als \u2019staatsfeindliche Aktivit\u00e4ten\u00ab eingestuft. Da der 25. Juli n\u00e4her r\u00fcckt, wird zudem die Zensur in den sozialen Netzwerken und in der Presse versch\u00e4rft. Die englischsprachige Zeitung <em>Dawn<\/em> bekam dies zu sp\u00fcren, als ihr wegen ethischer Verst\u00f6\u00dfe das Erscheinen untersagt wurde, obwohl sie gerade ein Interview mit dem abgesetzten ehemaligen Premierminister ver\u00f6ffentlicht hatte, in dem sie das Milit\u00e4r kritisierte. Dennoch war dieser Druck auf das demokratische Leben in Pakistan schon immer sp\u00fcrbar. Der Unterschied besteht darin, dass die Unterdr\u00fcckung in letzter Zeit an Sichtbarkeit gewonnen hat. Solange in Pakistan eine Art dynastische Politik bestehen bleibt, wird das Milit\u00e4r eine wichtige Stellung im Land behalten.<\/p>\n<p>Diese Wahl ist nicht nur f\u00fcr die innere Stabilit\u00e4t Pakistans von Bedeutung, sondern wird auch die Entscheidungsfindung in der gesamten Region beeinflussen. Zumal in diesem Jahr und 2019 auch in den USA, Indien und Afghanistan, den drei anderen Akteuren in der Region, Wahlen stattfinden werden. Seit Beginn seiner Amtszeit hat Pr\u00e4sident Trump harte Worte gegen die Islamische Republik gefunden. Der US-Pr\u00e4sident beschuldigt sie, ein doppeltes Spiel mit den Taliban zu spielen: Einerseits erh\u00e4lt Pakistan US-Zusch\u00fcsse (die allerdings von drei auf eine Milliarde gek\u00fcrzt wurden), andererseits unterst\u00fctzt Islamabad die afghanischen Taliban. Trump sprach von der Einf\u00fchrung von Sanktionen, um die Pakistaner dazu zu bringen, in Afghanistan mit ihnen zusammenzuarbeiten. Laut dem pakistanischen Milit\u00e4r w\u00fcrden solche Ma\u00dfnahmen das Land nicht destabilisieren, sondern die Armee in ihrer Rolle als Garant der Unabh\u00e4ngigkeit gegen eine internationale Verschw\u00f6rung st\u00e4rken. Die gr\u00f6\u00dfte Gefahr f\u00fcr Islamabad liegt nicht in den Drohungen der USA oder in seiner gro\u00dfen Feindseligkeit gegen\u00fcber seinem Nachbarn Indien, sondern im Kampf gegen die Islamisten.<\/p>\n<p>Denn wenn Pakistan heute gegen Islamisten innerhalb seiner Grenzen und auf der anderen Seite des Zauns in Afghanistan k\u00e4mpft, dann deshalb, weil die Beh\u00f6rden diese Bewegungen instrumentalisiert haben. Sowohl w\u00e4hrend der sowjetischen Invasion in Afghanistan in den 1980er Jahren als auch im indischen Teil der umstrittenen Region Kaschmir unterst\u00fctzte Islamabad islamistische Gruppierungen. Diese Unterst\u00fctzung diente einem doppelten Zweck: Indien entgegenzutreten und eine befreundete Macht in Afghanistan zu haben. Entlang seiner Westgrenze verlor Pakistan die Kontrolle \u00fcber die pakistanischen Taliban, die sich in ihrer Opposition gegen die nationale Armee radikalisierten.<\/p>\n<p>Diese regionale Situation des Kampfes gegen den Islamismus und die Koalition der USA mit den afghanischen Machthabern und Indien l\u00e4sst das Gef\u00fchl einer Verschw\u00f6rung immer st\u00e4rker werden. So besteht die Gefahr, dass ein f\u00fcr die Zukunft Pakistans entscheidender Moment wie die Parlamentswahlen von der Armee, die sich in ihrer nationalen Vorherrschaft bedroht f\u00fchlt, f\u00fcr ihre Zwecke missbraucht wird. Die Repressionen im Vorfeld der Wahlen sind sicherlich ein Symptom daf\u00fcr. Die Demokratie bleibt in allen L\u00e4ndern der Welt leider ein mehr als fragiles Gut.<\/p>\n<p><em>Schreiben Sie dem Autor : <a href=\"mailto:clement.guntern@legardlibre.com\">clement.guntern@legardlibre.com<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Les lundis de l&#8217;actualit\u00e9 &#8211; Cl\u00e9ment Guntern Le 25 juillet de cette ann\u00e9e se tiendront les \u00e9lections l\u00e9gislatives au Pakistan&#8230;.<\/p>","protected":false},"author":325,"featured_media":509875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[644357281],"tags":[4338,98616,61440,189091,97571,26168,3235,1682116],"class_list":["post-15640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde","tag-afghanistan","tag-armee","tag-democratie","tag-donald-trump","tag-inde","tag-journalisme","tag-pakistan","tag-talibans"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elections sous tensions au Pakistan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/politik\/welt\/wahlen-in-pakistan-unter-spannungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elections sous tensions au Pakistan\" \/>\n<meta property=\"og:description\" content=\"Les lundis de l&#039;actualit\u00e9 - Cl\u00e9ment Guntern Le 25 juillet de cette ann\u00e9e se tiendront les \u00e9lections l\u00e9gislatives au Pakistan....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/politik\/welt\/wahlen-in-pakistan-unter-spannungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-11T10:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T21:54:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1-1024x747.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment Guntern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment Guntern\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/\"},\"author\":{\"name\":\"Cl\u00e9ment Guntern\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/30daacd8c04cd92ec59532d74a7b18f8\"},\"headline\":\"Elections sous tensions au Pakistan\",\"datePublished\":\"2018-06-11T10:00:40+00:00\",\"dateModified\":\"2025-12-13T21:54:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg\",\"keywords\":[\"Afghanistan\",\"Arm\u00e9e\",\"D\u00e9mocratie\",\"Donald Trump\",\"Inde\",\"Journalisme\",\"Pakistan\",\"Talibans\"],\"articleSection\":[\"Monde\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/\",\"name\":\"Elections sous tensions au Pakistan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg\",\"datePublished\":\"2018-06-11T10:00:40+00:00\",\"dateModified\":\"2025-12-13T21:54:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg\",\"width\":3089,\"height\":2254,\"caption\":\"A Pakistani Honor Guard prepares for the arrival of U.S. Defense Secretary Robert Gates at the Army\u00d5s Martyrs Monument that honors the sacrifices of security forces and citizens in their fight against extremists in Rawalpindi, Pakistan, Thursday, Jan. 21, 2010. Secretary Gates today met with country\u00d5s top military leadership and his Pakistani counterpart to discuss Washington\u00d5s new Afghan policy and other issues of mutual interests. DoD Photo by U.S. Air Force Master Sgt. Jerry Morrison(RELEASED)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/monde\\\/elections-sous-tensions-au-pakistan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elections sous tensions au Pakistan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/30daacd8c04cd92ec59532d74a7b18f8\",\"name\":\"Cl\u00e9ment Guntern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g\",\"caption\":\"Cl\u00e9ment Guntern\"},\"sameAs\":[\"https:\\\/\\\/leregardlibre.com\\\/\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/clement-guntern\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wahlen in Pakistan unter Spannungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/politik\/welt\/wahlen-in-pakistan-unter-spannungen\/","og_locale":"de_DE","og_type":"article","og_title":"Elections sous tensions au Pakistan","og_description":"Les lundis de l'actualit\u00e9 - Cl\u00e9ment Guntern Le 25 juillet de cette ann\u00e9e se tiendront les \u00e9lections l\u00e9gislatives au Pakistan....","og_url":"https:\/\/leregardlibre.com\/de\/politik\/welt\/wahlen-in-pakistan-unter-spannungen\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2018-06-11T10:00:40+00:00","article_modified_time":"2025-12-13T21:54:49+00:00","og_image":[{"width":1024,"height":747,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1-1024x747.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment Guntern","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Cl\u00e9ment Guntern","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/"},"author":{"name":"Cl\u00e9ment Guntern","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/30daacd8c04cd92ec59532d74a7b18f8"},"headline":"Elections sous tensions au Pakistan","datePublished":"2018-06-11T10:00:40+00:00","dateModified":"2025-12-13T21:54:49+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg","keywords":["Afghanistan","Arm\u00e9e","D\u00e9mocratie","Donald Trump","Inde","Journalisme","Pakistan","Talibans"],"articleSection":["Monde"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/","url":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/","name":"Wahlen in Pakistan unter Spannungen","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg","datePublished":"2018-06-11T10:00:40+00:00","dateModified":"2025-12-13T21:54:49+00:00","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/06\/defense-gov_photo_essay_100121-f-6655m-178-1.jpg","width":3089,"height":2254,"caption":"A Pakistani Honor Guard prepares for the arrival of U.S. Defense Secretary Robert Gates at the Army\u00d5s Martyrs Monument that honors the sacrifices of security forces and citizens in their fight against extremists in Rawalpindi, Pakistan, Thursday, Jan. 21, 2010. Secretary Gates today met with country\u00d5s top military leadership and his Pakistani counterpart to discuss Washington\u00d5s new Afghan policy and other issues of mutual interests. DoD Photo by U.S. Air Force Master Sgt. Jerry Morrison(RELEASED)"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/politique\/monde\/elections-sous-tensions-au-pakistan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Elections sous tensions au Pakistan"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/30daacd8c04cd92ec59532d74a7b18f8","name":"Cl\u00e9ment Guntern","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79a3aae9b5ce6c4dcd8890bc4d3171c7198fe739971f91e509b3f8b98aa66d64?s=96&d=identicon&r=g","caption":"Cl\u00e9ment Guntern"},"sameAs":["https:\/\/leregardlibre.com\/"],"url":"https:\/\/leregardlibre.com\/de\/author\/clement-guntern\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/15640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/325"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=15640"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/15640\/revisions"}],"predecessor-version":[{"id":509874,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/15640\/revisions\/509874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/509875"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=15640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=15640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=15640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}