{"id":17151,"date":"2018-10-01T17:00:57","date_gmt":"2018-10-01T16:00:57","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=17151"},"modified":"2025-12-13T22:47:14","modified_gmt":"2025-12-13T21:47:14","slug":"le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/","title":{"rendered":"\u00abDie dunkle Seite des Lichts\u00bb, oder die Macht nach Oskar Freysinger"},"content":{"rendered":"<p><i>Les lundis de l'actualit\u00e9 - Nicolas Jutzet<\/i><\/p>\n<p><strong>Es ist eine neue, erfrischende \u00dcbung. Durch die Offenheit seines Autors ist das letzte Buch von Oskar Freysinger eine Freude f\u00fcr jeden Politikliebhaber. Im Herzen der Macht verfolgen wir Tag f\u00fcr Tag die Gewalt des Amtes f\u00fcr einen Mann, der aus dem Rahmen f\u00e4llt, der nicht programmiert war. Man hielt ihn f\u00fcr unantastbar, doch man entdeckt ihn als sensiblen, gequ\u00e4lten Mann. Die Leser des <em>Regard Libre<\/em> kennen den K\u00fcnstler Oskar Freysinger<i>, In unserer Ausgabe vom Mai dieses Jahres hat er sich selbst vorgestellt.&nbsp;<\/i>Mit ihrem neuen Buch <em>Die dunkle Seite des Lichts<\/em>, Das Buch gibt uns die M\u00f6glichkeit, den Menschen hinter dem Politiker besser zu verstehen. Das Buch, das zwischen Gedichten und Behauptungen angesiedelt ist, ist zweifellos das Buch des Herbstes in der Schweiz.<\/strong><\/p>\n<p><!--more--><\/p>\n<p><i>\u00abDe loin mon livre le plus personnel. Pour le r\u00e9diger, j\u2019ai exclusivement tremp\u00e9 ma plume dans la sueur, les larmes, l\u2019angoisse et le d\u00e9sespoir de mon propre v\u00e9cu.\u00bb<\/i><\/p>\n<p>Apr\u00e8s sa longue travers\u00e9e du d\u00e9sert, le tribun revient avec parcimonie dans les m\u00e9dias, pour faire conna\u00eetre son livre. Ce t\u00e9moignage de plus de trois cents pages permet de d\u00e9couvrir l\u2019envers du d\u00e9cor. L\u2019autre version de l\u2019histoire, celle du chass\u00e9. Car comme le dit l\u2019adage, l\u2019histoire est \u00e9crite par les vainqueurs. C\u2019est pour tordre le cou \u00e0 cette fatalit\u00e9 et ma\u00eetriser sa sortie que le grandiloquent Savi\u00e9san a d\u00e9cid\u00e9 de se mettre en retrait, d\u2019\u00e9chapper \u00e0 \u00abla b\u00eate m\u00e9diatique\u00bb et de coucher sur papier sa version de la chute, finalement r\u00e9demptrice, que ce livre existe. Chat \u00e9chaud\u00e9 craint l\u2019eau chaude.<\/p>\n<p>Or, comme le relate son r\u00e9cit, en mati\u00e8re de traitement approximatif de la part des m\u00e9dias, le protagoniste en a vu de toutes les couleurs. Avec le recul, un observateur neutre devra admettre que les journalistes se sont parfois fourvoy\u00e9s, par pr\u00e9cipitation ou simplement par malveillance partisane. Evidemment, difficile de passer \u00e0 c\u00f4t\u00e9 d\u2019un proc\u00e8s en hypocrisie pour celui qui a si longtemps tari la soif de la corporation rarement insensible \u00e0 ses bonnes formules, sa gouaille et son talent, av\u00e9r\u00e9, de d\u00e9batteur. Son livre en contient quelques-unes, notamment au sujet du r\u00e9dacteur en chef du <em>Nouvelliste<\/em> Vincent Fragni\u00e8re:<\/p>\n<p><em>\u00abIl est si tol\u00e9rant qu\u2019il tol\u00e8re tous ceux qui pensent comme lui ou ne pensent tout simplement pas, comme lui.\u00bb<\/em><\/p>\n<p>Au fil des lignes, on aper\u00e7oit que, contrairement \u00e0 beaucoup d\u2019autres politiciens \u2013&nbsp;il n\u2019oublie jamais d\u2019\u00e9gratigner ces \u00abfieff\u00e9s coquins\u00bb \u2013 Freysinger a une v\u00e9ritable vision de l\u2019Etat. Louons sa capacit\u00e9 \u00e0 d\u00e9crire et admettre les dangers du pouvoir:<\/p>\n<p><em>\u00abAu lieu de construire un syst\u00e8me bas\u00e9 sur une succession de confrontations, on a mis\u00e9 en Suisse sur la participation de toutes les forces politiques aux affaires de l\u2019Etat, sur la collaboration et la coll\u00e9gialit\u00e9. Les hommes et les femmes en Suisse ne sont pas meilleurs ou plus intelligents que ceux d\u2019autres pays, mais ils ont su compenser leurs faiblesses humaines par des r\u00e8gles qu\u2019ils ont d\u00e9finies eux-m\u00eames. Ils ont aussi su r\u00e9fr\u00e9ner leur soif de pouvoir et construire une organisation collective fixant les devoirs des citoyens tout en leur accordant des droits \u00e9tendus, sans que l\u2019individualit\u00e9 de chacun soit brim\u00e9e ou \u00e9crase les autres.\u00bb<\/em><\/p>\n<p>L\u2019auteur th\u00e9matise \u00e9galement, avec raison, la n\u00e9cessit\u00e9 de sa circonscription. F\u00e9d\u00e9raliste, celui que les m\u00e9dias font passer pour un anti-syst\u00e8me loue pourtant les institutions, leur r\u00e9silience et leur capacit\u00e9 si suisse \u00e0 faire dispara\u00eetre les t\u00eates qui d\u00e9passent, m\u00eame \u00e0 ses d\u00e9pens. Il sait reconna\u00eetre la primaut\u00e9 des droits de l\u2019individu et milite pour une limitation des pouvoirs. Par ailleurs, il loue, sans grande surprise, le mod\u00e8le d\u2019int\u00e9gration qu\u2019il souhaite voir perdurer:<\/p>\n<p><em>\u00abAucun Suisse n\u2019est Suisse de naissance. Il le devient en foulant la terre de ses anc\u00eatres, il le devient parce qu\u2019il est entour\u00e9, choy\u00e9, parce qu\u2019il est port\u00e9 par une histoire, des traditions, un milieu familial. L\u2019\u00e9tranger qui d\u00e9sire joindre cette communaut\u00e9 d\u2019esprit, qui veut faire sien le mythe de notre pays souverain et ind\u00e9pendant, est le bienvenu. Mais il devra faire acte de volont\u00e9, il devra prouver qu\u2019il est digne de devenir membre de la communaut\u00e9 de la croix blanche, qu\u2019il est pr\u00eat \u00e0 reconna\u00eetre les valeurs qui en sont le ferment, pr\u00eat \u00e0 payer de sa personne pour joindre sa pierre \u00e0 l\u2019\u00e9difice. Nous ne demandons \u00e0 personne de renier ses racines, sa lointaine montagne \u00e0 lui, le paysage \u00e9motionnel de son enfance qui l\u2019a fa\u00e7onn\u00e9. Nous lui demandons juste de joindre ses r\u00eaves aux n\u00f4tres, d\u2019enrichir notre paysage culturel du sien, avec respect et sans heurts<\/em>.<em>\u00bb<\/em><\/p>\n<p>Si chaque politicien \u00e0 la petite semaine \u00e9tait capable de th\u00e9oriser de pareille fa\u00e7on sa vision id\u00e9ale de l\u2019Etat, organe qui chapeaute, et trop souvent dicte, notre vie commune, on se d\u00e9barrasserait assur\u00e9ment rapidement de ce constat amer, celui de l\u2019auteur: la politique est une affaire de fieff\u00e9s coquins qui trop souvent oublient de servir l&#8217;int\u00e9r\u00eat g\u00e9n\u00e9ral \u2013&nbsp;pour autant qu\u2019il existe et qu\u2019il doive \u00eatre d\u00e9fendu par des \u00e9lus \u2013 qu\u2019ils n\u2019honorent que de leurs mots, oubliant de passer aux actes. Freysinger rappelle, formule \u00e0 la clef \u2013 <em>\u00abLes conseils d\u2019administrations, c\u2019est comme les chiens: \u00e7a rapporte\u00bb <\/em>\u2013 qu\u2019il a toujours refus\u00e9 de si\u00e9ger dans des conseils d\u2019administration r\u00e9mun\u00e9rateurs.<\/p>\n<p><em>\u00abLes politiciens servent \u2013 souvent en se servant \u2013 et disparaissent, le peuple et les institutions restent.\u00bb<\/em><\/p>\n<h3>La civilisation occidentale en danger<\/h3>\n<p>Au-del\u00e0 de son bilan personnel, l\u2019auteur revient sur les pens\u00e9es qui l\u2019animent. Tout au long de l\u2019expos\u00e9, un certain pessimisme s\u2019impose: <em>\u00abJ\u2019ai de plus en plus l\u2019impression qu\u2019un monde est en train de sombrer, un monde constitu\u00e9 de rep\u00e8res clairement identifiables, de valeurs s\u00fbres, de responsabilit\u00e9, de r\u00e9flexion approfondie. Il c\u00e8de sa place \u00e0 une roue qui tourne trop vite pour \u00eatre honn\u00eate et tend encore \u00e0 s&#8217;acc\u00e9l\u00e9rer en raison de l&#8217;aplanissement de la surface du monde.\u00bb<\/em> Il d\u00e9nonce les d\u00e9rives d\u2019un syst\u00e8me qui se d\u00e9lite&nbsp;: <em>\u00abJe crains que les <\/em>working poor<em> ne soient que l\u2019avant-garde de l\u2019avenir que nous promettent les chevaux fous de la haute finance. Je ne peux m&#8217;emp\u00eacher de penser aux migrants qui, eux, sont choy\u00e9s par le syst\u00e8me, alors que pour la plupart, ils viennent dans le seul but de d\u00e9pecer le cadavre de la vieille Europe tant qu\u2019il y a encore un os \u00e0 ronger<\/em>.<em>\u00bb<\/em><\/p>\n<p>On retrouve ici les th\u00e9matiques ch\u00e8res \u00e0 son parti, mais avec un degr\u00e9 d\u2019alarmisme plus \u00e9lev\u00e9 qu\u2019ailleurs. Face \u00e0 un tel constat, il est difficile de croire, m\u00eame s\u2019il le jure \u00e0 qui veut bien l\u2019entendre, que la politique, c\u2019est vraiment termin\u00e9 pour lui. Si le destin qu\u2019il croit r\u00e9serv\u00e9 \u00e0 l\u2019Europe s\u2019av\u00e8re exact, la volont\u00e9 de se battre contre cette \u00e9volution doit le d\u00e9manger. Voir son monde s\u2019\u00e9tioler et le regarder passivement en tournant la t\u00eate ressemble si peu \u00e0 celui que nous connaissions.&nbsp;C\u2019est&nbsp;sans doute la&nbsp;gestion de cette \u00e9tincelle qui&nbsp;nous dira si l\u2019Oskar d\u2019hier, \u00abmort au combat\u00bb,&nbsp;peut&nbsp;r\u00e9appara\u00eetre et rependre du service. Cette question taraude sans doute tant ses opposants que ses d\u00e9fenseurs.<\/p>\n<h3>Un probl\u00e8me de profil, non de programme?<\/h3>\n<p><em>\u00abMon d\u00e9faut majeur, c\u2019est d\u2019\u00eatre qui je suis, non pas de faire ce que je fais<\/em>.<em>\u00bb<\/em> Comment expliquer la d\u00e9route d\u2019un homme qui pouvait se targuer d\u2019avoir une relation forte avec la population? Est-ce finalement sa strat\u00e9gie politique, lui qui ne voulait pas mourir comme l&#8217;\u00e2ne de Buridan? Est-il mort d\u2019avoir choisi d\u2019agir? En pr\u00e9sentant une liste ouverte, \u00abEnsemble \u00e0 droite\u00bb, Oskar Freysinger esp\u00e9rait r\u00e9\u00e9diter l\u2019exploit de 2013, qui l\u2019avait vu finir en premi\u00e8re place, \u00e0 la surprise de la plupart des observateurs. C\u2019\u00e9tait quitte ou double. Il ne se voyait pas si\u00e9ger dans un coll\u00e8ge qui, faute de majorit\u00e9 favorable, l\u2019aurait sans doute isol\u00e9.<\/p>\n<p>Au final, et il le reconna\u00eet dans son ouvrage, cette strat\u00e9gie s\u2019est sold\u00e9e par un \u00e9chec cuisant, tant par la faute de l\u2019effacement de ses colistiers que de la focalisation sur l\u2019homme \u00e0 abattre qu\u2019il \u00e9tait devenu. D\u00e9grad\u00e9e par des pol\u00e9miques \u00e0 r\u00e9p\u00e9tition, son image \u00e9tait devenue un boulet trop lourd \u00e0 porter. Les crocs aiguis\u00e9s de ses ennemis, ses probl\u00e8mes avec la presse et sa strat\u00e9gie, voil\u00e0 en somme le contenu de ce cocktail explosif. Finalement, il regrette au passage l\u2019\u00e9lection d\u2019un Fr\u00e9d\u00e9ric Favre qu\u2019il juge s\u00e9v\u00e8rement: \u00ab<em>Ainsi donc une boite de pandore vient de s\u2019ouvrir et un signal clair est donn\u00e9: aucun pr\u00e9requis n\u2019est n\u00e9cessaire pour occuper la charge de conseiller d\u2019Etat, n\u2019importe qui fait l\u2019affaire<\/em>.<em>\u00bb<\/em><\/p>\n<h3><strong><em>Quid<\/em> de la suite?<\/strong><\/h3>\n<p><em>\u00abPrendre ma revanche? A quoi bon? Ce serait du temps perdu. Le vide ne se combat pas. Il faut le laisser s\u2019\u00e9tendre jusqu\u2019\u00e0 ce qu\u2019il soit un jour combl\u00e9, comme par enchantement.\u00bb<\/em><\/p>\n<p>Oskar profite de sa \u00abnouvelle\u00bb vie, appr\u00e9ciant notamment le temps qu\u2019elle lui laisse pour \u00e9crire ou partager des moments avec ceux qu\u2019il avait d\u00e9laiss\u00e9s. <em>\u00abAu lieu de me pr\u00e9occuper des grands probl\u00e8mes des \u00e2mes \u00e9triqu\u00e9es, je me penche d\u00e9sormais sur les petits probl\u00e8mes des grandes \u00e2mes. Le temps n\u2019est plus mon ennemi, il est devenu mon alli\u00e9 et je sens m\u00eame qu\u2019il a tendance \u00e0 s\u2019effacer avec gr\u00e2ce devant l\u2019attention accrue que je porte au moment pr\u00e9sent<\/em>.<em>\u00bb<\/em> Sa femme et premier soutien, Ghislaine, est souvent cit\u00e9e, tant dans les po\u00e8mes que dans les nombreuses \u00e9vocations de l\u2019importance de son cercle familial.<\/p>\n<p>A de nombreuses reprises, l\u2019UDC r\u00e9p\u00e8te qu\u2019il ne briguera plus de mandat \u00e9lectif, qu\u2019il en a fini avec cette fa\u00e7on de faire de la politique, sans toutefois pouvoir l\u2019exclure totalement. <em>\u00abTant de gens me croient accro \u00e0 la politique et \u00e0 la notori\u00e9t\u00e9, il vaut mieux que je me m\u00e9fie, au cas o\u00f9 ils auraient raison\u00bb<\/em>. Il reconna\u00eet cependant un autre m\u00e9rite \u00e0 la violence de sa sortie de route: elle rend la tentation d\u2019un retour moins all\u00e9chante. Admettant toutefois que son combat continue, confort\u00e9 dans ses positions par les \u00e9volutions qu\u2019il observe par le monde&nbsp;: <em>\u00abQuant \u00e0 la politique, des options se profilent \u00e0 l\u2019horizon, mais elles sont encore trop incertaines et floues. Il faudra encore un peu de temps pour que les choses se d\u00e9cantent<\/em>.<em>\u00bb<\/em><\/p>\n<p>Tant par son honn\u00eatet\u00e9 que par son phras\u00e9, ce livre qui se veut provocateur (<em>\u00abJe suis en d\u00e9licatesse avec la trousse \u00e0 maquillage, du para\u00eetre et le miroir des faux-semblants\u00bb<\/em>), m\u00e9rite votre lecture. Alliant bons mots et saillies offensives savamment ma\u00eetris\u00e9es, l\u2019ouvrage raconte le pouvoir et la marque qu\u2019il laisse sur les hommes. Au travers de l&#8217;histoire, le pouvoir a br\u00fbl\u00e9 les ailes de certains, subjugu\u00e9 d\u2019autres, mais toujours, il a \u00e9t\u00e9 exerc\u00e9.<\/p>\n<p><em>\u00abLes gens ont beau pr\u00e9tendre vouloir la v\u00e9rit\u00e9, ils ne la supportent pas.\u00bb<\/em><\/p>\n<p>Schreiben Sie dem Autor : <a href=\"mailto:nicolas.jutzet@leregardlibre.com\">nicolas.jutzet@leregardlibre.com<\/a><\/p>\n<p><i>Cr\u00e9dit photo : \u00a9 Loris S.&nbsp;Musumeci&nbsp;pour Le Regard Libre<\/i><\/p>\n<p><strong>Dans notre \u00e9dition papier de novembre, des questions pos\u00e9es \u00e0 Oskar Freysinger sur son livre. <a href=\"https:\/\/goo.gl\/forms\/ksAUgGZ9gUqwcFC73\">Bestellen Sie jetzt ein Exemplar dieser Ausgabe.<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Les lundis de l\u2019actualit\u00e9 \u2013 Nicolas Jutzet C\u2019est un exercice in\u00e9dit, rafra\u00eechissant. Par la franchise de son auteur, le dernier&#8230;<\/p>","protected":false},"author":314,"featured_media":510120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20663],"tags":[79354,4780409,354972,252038,281566],"class_list":["post-17151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature","tag-lumiere","tag-oskar-freysinger","tag-pouvoir","tag-udc","tag-valais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/literatur\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger\" \/>\n<meta property=\"og:description\" content=\"Les lundis de l\u2019actualit\u00e9 \u2013 Nicolas Jutzet C\u2019est un exercice in\u00e9dit, rafra\u00eechissant. Par la franchise de son auteur, le dernier...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/literatur\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T16:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T21:47:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1-1024x740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Jutzet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Jutzet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/\"},\"author\":{\"name\":\"Nicolas Jutzet\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/3446d3a78b45211305188d4401e7719a\"},\"headline\":\"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger\",\"datePublished\":\"2018-10-01T16:00:57+00:00\",\"dateModified\":\"2025-12-13T21:47:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/\"},\"wordCount\":2041,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg\",\"keywords\":[\"Lumi\u00e8re\",\"Oskar Freysinger\",\"Pouvoir\",\"UDC\",\"Valais\"],\"articleSection\":[\"Litt\u00e9rature\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/\",\"name\":\"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg\",\"datePublished\":\"2018-10-01T16:00:57+00:00\",\"dateModified\":\"2025-12-13T21:47:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg\",\"width\":3456,\"height\":2496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/litterature\\\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/3446d3a78b45211305188d4401e7719a\",\"name\":\"Nicolas Jutzet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g\",\"caption\":\"Nicolas Jutzet\"},\"description\":\"Co-fondateur du m\u00e9dia Liber-th\u00e9, Nicolas Jutzet est vice-directeur de l\u2019Institut lib\u00e9ral, en Suisse.\",\"sameAs\":[\"https:\\\/\\\/nicolasjutzet.ch\\\/a-propos\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Le_Regard_libre\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/nicolas-jutzet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00abDie dunkle Seite des Lichts\u00bb, oder die Macht nach Oskar Freysinger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/literatur\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger","og_description":"Les lundis de l\u2019actualit\u00e9 \u2013 Nicolas Jutzet C\u2019est un exercice in\u00e9dit, rafra\u00eechissant. Par la franchise de son auteur, le dernier...","og_url":"https:\/\/leregardlibre.com\/de\/literatur\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2018-10-01T16:00:57+00:00","article_modified_time":"2025-12-13T21:47:14+00:00","og_image":[{"width":1024,"height":740,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1-1024x740.jpg","type":"image\/jpeg"}],"author":"Nicolas Jutzet","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Nicolas Jutzet","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/"},"author":{"name":"Nicolas Jutzet","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/3446d3a78b45211305188d4401e7719a"},"headline":"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger","datePublished":"2018-10-01T16:00:57+00:00","dateModified":"2025-12-13T21:47:14+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/"},"wordCount":2041,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg","keywords":["Lumi\u00e8re","Oskar Freysinger","Pouvoir","UDC","Valais"],"articleSection":["Litt\u00e9rature"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/","url":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/","name":"\u00abDie dunkle Seite des Lichts\u00bb, oder die Macht nach Oskar Freysinger","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg","datePublished":"2018-10-01T16:00:57+00:00","dateModified":"2025-12-13T21:47:14+00:00","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/10\/Oskar-Freysinger-3-21.03.18-\u00a9-Loris-S.-Musumeci-pour-Le-Regard-Libre-1762389553-1538410910398-1.jpg","width":3456,"height":2496},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/litterature\/le-cote-obscur-de-la-lumiere-ou-le-pouvoir-selon-oskar-freysinger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"\u00abLe c\u00f4t\u00e9 obscur de la lumi\u00e8re\u00bb, ou le pouvoir selon Oskar Freysinger"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/3446d3a78b45211305188d4401e7719a","name":"Nicolas Jutzet","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0051d940078d390e50a5e700a6c653e3776f3a164b8878a91d3c09ee3a174239?s=96&d=identicon&r=g","caption":"Nicolas Jutzet"},"description":"Nicolas Jutzet ist Mitbegr\u00fcnder des Mediums Liber-th\u00e9 und Vize-Direktor des Liberalen Instituts in der Schweiz.","sameAs":["https:\/\/nicolasjutzet.ch\/a-propos\/","https:\/\/fr.wikipedia.org\/wiki\/Le_Regard_libre"],"url":"https:\/\/leregardlibre.com\/de\/author\/nicolas-jutzet\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/17151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/314"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=17151"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/17151\/revisions"}],"predecessor-version":[{"id":510119,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/17151\/revisions\/510119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/510120"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=17151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=17151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=17151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}