{"id":18470,"date":"2018-12-25T13:07:39","date_gmt":"2018-12-25T12:07:39","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=18470"},"modified":"2025-11-12T19:16:20","modified_gmt":"2025-11-12T18:16:20","slug":"conversation-avec-miossec","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/musique\/conversation-avec-miossec\/","title":{"rendered":"Gespr\u00e4ch mit Miossec"},"content":{"rendered":"\n<p><em>Article in\u00e9dit \u2013 David Glaser, journaliste radio \u00e0 RTL\u00a0et \u00e0 la\u00a0RTS<\/em><br><br><em><strong>Cet <a href=\"https:\/\/suississimo.com\/2018\/12\/24\/studio-54-conversation-avec-miossec\/\">article<\/a> est \u00e9galement disponible sur <a href=\"https:\/\/suississimo.com\">Suississimo.com<\/a><\/strong><\/em><\/p>\n\n\n\n<p><strong>Pour No\u00ebl, David Glaser, journaliste musical \u00e0 la Radio T\u00e9l\u00e9vision Suisse, reporter \u00e0 RTL, ancien d&#8217;Europe 1 et de France Inter, nous livre une longue discussion t\u00e9l\u00e9phonique avec Miossec, et un r\u00e9cit allant au plus profond de son art.<\/strong><\/p>\n\n\n\n<!--more Lire l'article (en libre acc\u00e8s)-->\n\n\n\n<p>Au d\u00e9part, je voulais vous raconter un conte de No\u00ebl disco dans le genre \u00abIl est n\u00e9 le divin enfant\u00bb, avec des musiques remix\u00e9es des originaux qui font <em>plez&#8217; <\/em>aux <em>fans<\/em> de Santa Claus. Je parle des Nat King Cole, Tony Bennett et autre Dino Martin, des voix, de la <em>croon&#8217;<\/em> \u00e0 fond les ballons en ces temps incertains, histoire de faire dans le d\u00e9paysement classique de fin d&#8217;ann\u00e9e loin des manifs et des pillages, des Brexits et des naufrages d&#8217;immigr\u00e9s, le regard tourn\u00e9 vers New York et sa f\u00e9erie mat\u00e9rialiste &#8211; mais belle &#8211; de No\u00ebl, une histoire avec bons sentiments pour parler de l&#8217;amour dans le monde entre les peuples et les familles, afin de prier ensemble pour que 2019 efface enfin toutes les mis\u00e8res et transforme aussi les gilets en or&#8230; oh que tout cela est tr\u00e8s beau et bienveillant. Mais&nbsp;finalement, non,&nbsp;je veux vous parler de boire et de baiser comme des mammif\u00e8res finist\u00e9riens qui s&#8217;\u00e9treignent ici-bas ici m\u00eame comme en 1964&#8230; pour br\u00fbler des chansons ordinaires par les deux bouts et finir rescap\u00e9s de l&#8217;autodaf\u00e9 musical.<\/p>\n\n\n\n<p>J&#8217;ai cherch\u00e9 la bonne personne pour ce 101<sup>e<\/sup> morceau de <em>Suississimo<\/em> sp\u00e9cial No\u00ebl. Un homme pour raconter la musique qui me turlupine un peu trop en ce moment. Un chanteur pour lequel je voue une sinc\u00e8re admiration depuis plus de vingt ans. C&#8217;est donc un acte d&#8217;engagement et de partage que je signe de ma plume en bas de cette page. Et cette conversation rev\u00eat un caract\u00e8re particulier, elle intervient juste avant sa venue en concert le 26 janvier aux Docks de Lausanne. Le personnage en question est&nbsp;<a href=\"http:\/\/suississimo.com\/2015\/03\/17\/capitaine-sensible\/\">Miossec<\/a>, et apr\u00e8s chaque \u00e9change avec le Brestois,&nbsp; j&#8217;ai cette impression d&#8217;avoir v\u00e9cu quelques trucs <em>sensass<\/em> avec l&#8217;homme le plus marrant de la terre, le plus discret aussi. Un artiste plein, litt\u00e9raire, spirituel et direct, un militant de gauche qui n&#8217;a pas arr\u00eat\u00e9 de penser dans cette direction, mais sans se forcer; c&#8217;est sinc\u00e8re chez lui. Une b\u00eate de sc\u00e8ne tout en nuances, proche des gens sans leur en foutre plein la t\u00eate avec son statut, un homme qui f\u00eate cinquante-quatre ans, de musique qui marque l&#8217;\u00e2me et d&#8217;\u00e9crits bouleversants selon les moments de la vie qu&#8217;on a choisis pour s&#8217;en impr\u00e9gner.<\/p>\n\n\n\n\n\n<p>Enfin, Miossec, n\u00e9 quelques heures avant JC (autre ma\u00eetre-chanteur qui a un peu p\u00each\u00e9) est un ex-<em>punk rocker<\/em> majeur pour ne pas s&#8217;endormir en 2019. On en a besoin vu que Bashung ou Rachid Taha ne sont plus l\u00e0 <em>to represent<\/em>! Le v\u00e9ritable petit artisan breton de la po\u00e9sie musicale franche du collier, de la musique bouleversante sur accords mineurs, des confessions romantiques sur l&#8217;oreiller et donc pour les oreilles est un conteur de folles histoires d&#8217;habitants de villes provinciales (\u00abde petites pr\u00e9fectures\u00bb) \u00e0 peine \u00e9moustill\u00e9s par les coucheries de leurs \u00e9diles, ou \u00e9gay\u00e9s par les demis de bi\u00e8re et les verres de whisky-coke servis trop chers dans les bo\u00eetes de nuit pour <em>didjis<\/em> \u00abrelous\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg\" alt=\"miossec\"\/><figcaption>Miossec \u00a9 Julien T Hamon<\/figcaption><\/figure>\n\n\n\n<p>Dire des conneries \u00e0 tous les spectateurs bretons du Tour de France avec un drapeau fran\u00e7ais sur le toit ouvrant de la voiture \u00e9mettrice de France Inter lors de l&#8217;\u00e9dition 2006 (d\u00e9part de Rennes, arriv\u00e9e \u00e0 Lorient, passage par M\u00fbr-de-Bretagne), \u00e7a on l&#8217;a fait ensemble. Le souvenir est encore vif dans mon esprit. Miossec retombait en enfance \u00e0 l&#8217;occasion de cette \u00e9tape bretonne v\u00e9cue en int\u00e9gralit\u00e9 de la t\u00eate au pied dix heures de suite, une plong\u00e9e dans les souvenirs quand il regardait le Tour de France avec sa famille sur l&#8217;\u00e9cran de t\u00e9l\u00e9 familial ou sur les bords des routes du Penn-Ar-Bed. Le sportif qui a touch\u00e9 aux efforts collectifs UNSS ou de club, vivait ici une autre exp\u00e9rience de groupe, aupr\u00e8s d&#8217;\u00e9quipes de coureurs bien s\u00fbr mais aussi une exp\u00e9rience m\u00e9diatique, une vraie piq\u00fbre de plaisir d&#8217;\u00eatre l\u00e0, \u00abpelotonn\u00e9\u00bb, le cul \u00e0 l&#8217;arri\u00e8re d&#8217;une moto de suiveur de France Inter et le sentiment d&#8217;\u00eatre dans l&#8217;histoire du journal&nbsp;<em>l&#8217;Equipe<\/em>&nbsp;et du sport fran\u00e7ais.<\/p>\n\n\n\n<p>En 2018, <em>Les Rescap\u00e9s<\/em> sort dans les bacs. Nouvel album charg\u00e9 d&#8217;\u00e9mouvantes trouvailles orchestrales, habit\u00e9 d&#8217;une toute nouvelle urgence, face \u00e0 l&#8217;\u00e9cologie m\u00e9pris\u00e9e, face aux peuples qu&#8217;on abandonne au nom de l&#8217;argent, des relations humaines compliqu\u00e9es \u00e0 peine soign\u00e9es par des petites morts furtivement enterr\u00e9es, la vie sentimentale, \u00abcelles qui mangent les couleuvres, celles qui mangent les p\u00e9tales\u00bb, toujours ici chroniqu\u00e9e avec envie et inspiration cette fois dans un album d&#8217;une \u00e9l\u00e9gance sombre et vive \u00e0 la fois (voir mes commentaires et notes titre par titre plus loin). A l&#8217;\u00e9coute de cet <em>opus<\/em>, on retombe sur le Miossec brut de pomme \u00e0 couteau, avec des textes purs et tranchants, un Miossec les poumons gorg\u00e9s d&#8217;oxyg\u00e8ne iod\u00e9e par les embruns de la Mer d&#8217;Iroise, un Miossec conscient de sa responsabilit\u00e9 d&#8217;homme enracin\u00e9 qui en a vu tomber des h\u00e9ros au champ de bataille des addictions et des conneries c\u00e9lestes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avec Mirabelle et Leander en <\/strong>\u00ab<strong>camarades rescap\u00e9s<\/strong>\u00bb<\/h3>\n\n\n\n<p>On aime le \u00abmontage\u00bb de cet onzi\u00e8me album (le deuxi\u00e8me pour la maison de Bob Dylan et Jeff Buckley, la v\u00e9n\u00e9rable Columbia Records, plus japonaise que jamais; c&#8217;est une propri\u00e9t\u00e9 du groupe Sony, faites gaffe de ne pas d\u00e9tourner de l&#8217;argent, la justice nippone est intraitable). La matrice instrumentale est sign\u00e9e par Miossec et ses \u00ab<em>beatmakers<\/em> organiques\u00bb Mirabelle Gilis et Leander Lyons. Les mots sont toujours aussi soigneusement cisel\u00e9s par l&#8217;auteur sur le lit musical. En fr\u00e9n\u00e9tique amateur de Henri Calet et Raymond Carver, des artistes de la m\u00e9taphore et de l&#8217;ellipse, il travaille toujours \u00e0 sculpter les palabres sans gras et le plus pr\u00e8s possible de l&#8217;os.<\/p>\n\n\n\n<p>Aussi <em>Les Rescap\u00e9s<\/em> repr\u00e9sente une parfaite bande-son pour votre r\u00e9veillon-r\u00e9volution anti-syst\u00e8me, un chant des partisans de la d\u00e9croissance et de la responsabilit\u00e9 face aux Macronistes <em>hardcore<\/em> et aux Wauquieziens de tous poils, qui semblent oublier l&#8217;\u00e9cologie et les valeurs de solidarit\u00e9. A peine ragaillardi par la promesse de versement d&#8217;une prime de fin d&#8217;ann\u00e9e, le peuple qui souffre devrait comprendre les propos des <em>Rescap\u00e9s<\/em>. Le disque dresse un certain nombre de constats secs sur la soci\u00e9t\u00e9 fran\u00e7aise de maintenant, et jette quelques regards lucides (parfois bienveillants) sur le monde, mais aussi sur la violence des \u00e9changes, la nature martyris\u00e9e, la morale pi\u00e9tin\u00e9e, les d\u00e9sirs inassouvis de libert\u00e9. Miossec et ses partenaires ont r\u00e9ussi \u00e0 toucher dans le mille avec une nouvelle patte, plus brute, plus m\u00e9canique, aid\u00e9e de vieilles bo\u00eetes \u00e0 rythme et de sons synth\u00e9tiques rarement autant crois\u00e9s dans les chansons du <em>rocker<\/em> d\u00e9froqu\u00e9 depuis les premi\u00e8res collaborations avec Matthieu Ballet, musicien au sein de Oui-Oui dans les ann\u00e9es quatre-vingt et nonante, puis producteur.<\/p>\n\n\n\n<p>Dans un entretien peu classique, on parle de musique avec Miossec, mais aussi de la Suisse qu\u2019il revient fouler avec <em>Les Rescap\u00e9s<\/em> le 26 janvier prochain (d\u00e9j\u00e0 dit mais pas grave). Une terre qu\u2019il conna\u00eet et appr\u00e9cie pour y avoir crois\u00e9 le fer avec quelques autochtones genevois (Polar et Bernard Trontin, le batteur des mythiques Young Gods). On parle d\u2019artistes qui comptent et qui ont compt\u00e9, des h\u00e9ros, des vieillots, des pointures, des personnages un peu ou beaucoup en rupture&#8230; voire morts. L\u2019\u00e2me de Rachid Taha plane sur notre entretien. On aimait tous les deux beaucoup le Monsieur. Des commentaires sur des pistes musicales \u00e0 base de vieilles machines pour compositeurs de tourneries synth\u00e9tiques <em>vintage<\/em> surgissent dans l&#8217;\u00e9change de mots mais elles ne semblent clairement pas importantes, comme si Miossec avait toujours su et pu bifurquer sur une d\u00e9partementale pour aller r\u00e9cup\u00e9rer les vieilles malles de l&#8217;enfance charg\u00e9es de souvenirs nostalgiques sans avoir \u00e0 se justifier.<\/p>\n\n\n\n\n\n<p>Et parmi ces cargaisons de vieilles structures que ne renieraient en rien des musiciens inventeurs comme Jean-Jacques Perrey ou Pierre Henry, ce retour aux bo\u00eetes \u00e0 rythmes est un hommage au pass\u00e9 quand avec le groupe Printemps Noir, ils essayaient de plaire et de cro\u00eetre au beau milieu des ann\u00e9es quatre-vingt. C&#8217;\u00e9tait avec ce genre d\u2019instruments qu&#8217;on composait \u00e0 l&#8217;\u00e9poque, c&#8217;\u00e9tait donc une r\u00e9f\u00e9rence pour les mythiques Marquis de Sade ou le duo g\u00e9nial Kas Product; \u00abon avait d\u2019ailleurs fait leur premi\u00e8re partie \u00e0 Brest\u00bb, se rappelle amus\u00e9 Miossec. La bo\u00eete \u00e0 rythmes sale et envo\u00fbtante, j&#8217;ai alors la sensation d\u2019avoir d\u00e9j\u00e0 vu \u00e7a chez d\u2019autres artistes lors des mes quarante-deux ann\u00e9es pass\u00e9es ici-bas, comme avec Stephan Eicher dans les ann\u00e9es quatre-vingt (mon tout premier concert) \u00e0 l\u2019\u00e9poque de <em>Two People In A Room<\/em>, ou avec David Bowie dans les ann\u00e9es nonante avec <em>Inside<\/em> et <em>Outside<\/em>, voire avec Daniel Darc dans les ann\u00e9es 2000, et maintenant avec Miossec.<\/p>\n\n\n\n<p>Des noms qui claquent, un club des quatre, un <em>Fab Four<\/em> comme un <em>hall of fame<\/em> de po\u00e8tes qui ont aim\u00e9 les mots autant que la guitare, les machines autant que leurs effets sur les mots justement: la boucle est boucl\u00e9e avec <em>Les Rescap\u00e9s<\/em>. Hommage aux disparus Bowie et Darc, respect au Bernois Eicher. Rien de mieux que d&#8217;avoir toujours une volont\u00e9 de produire du son ent\u00eatant (<em>La Ville Blanche<\/em> et <em>On meurt<\/em>, deux morceaux gentiment d\u00e9coup\u00e9s \u00e0 la machine analogique), un son vacillant, un son du sac et du ressac, mais un son m\u00e9lodieux, doux comme du humus sur une plaine d&#8217;Irlande. Une temp\u00eate organis\u00e9e, une certaine id\u00e9e de la f\u00eate un 24 d\u00e9cembre. Bon anniversaire Mioss&#8217;.<\/p>\n\n\n\n<form method=\"post\" action=\"https:\/\/newsletter.infomaniak.com\/external\/submit\" class=\"inf-form\" target=\"_blank\"><input type=\"email\" name=\"email\" style=\"display:none\" \/><input type=\"hidden\" name=\"key\" value=\"eyJpdiI6IlZXRVJGMlRGQUU2alNqUE81bitIUk5adnNVa0c4MllFTStzOHdHT1FQZ3c9IiwidmFsdWUiOiJIYzhwMUVCK1pTNnlhY3MyMmhuZlhReWJqemEwNk93blMxTjFHc0s2VHZrPSIsIm1hYyI6ImVhYTQ5N2I1M2NiYWE4NzBmNjk2NzgzYjliM2Y5NmYzM2E2ZmU3NGQxNTU1ZDFkMTU1MzY5NTdjYjE3ZTJmNTUifQ==\"><input type=\"hidden\" name=\"webform_id\" value=\"7291\"><style> .inf-main_3000311ca56a1cb93397bc676c0b7fff{ background-color:#f5f5f5; padding:25px 20px; margin:25px auto; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-content { margin-top:13px;} .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff span, .inf-main_3000311ca56a1cb93397bc676c0b7fff label, .inf-main_3000311ca56a1cb93397bc676c0b7fff input, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-success p a { color:#555555; font-size:14px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4{ font-size:18px; margin:0px 0px 13px 0px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff label{ font-weight:bold; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input { margin-bottom:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff label { display:block;} .inf-main_3000311ca56a1cb93397bc676c0b7fff input{ height:35px; color:#999999; border: 1px solid #E9E9E9; border:none; padding-left:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error label, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message{ color: #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error input{ border: 1px solid #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input input { width:100%;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message { display: block; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit { text-align:right;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input{ background-color:#777777; color:#ffffff; border:none; font-weight: normal; height:auto; padding:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input.disabled{ opacity: 0.4; } .inf-btn { color: rgb(85, 85, 85); border: medium none; font-weight: normal; height: auto; padding: 7px; display: inline-block; background-color: white; box-shadow: 0px 1px 1px rgba(0, 0, 0, 0.24); border-radius: 2px; line-height: 1em; } .inf-rgpd { margin:25px 0px 15px 0px; color:#555555; } <\/style> <div class=\"inf-main_3000311ca56a1cb93397bc676c0b7fff\"> <h4>NEWSLETTER DU REGARD LIBRE<\/h4> <span>Recevez nos articles chaque dimanche.<\/span> <div class=\"inf-success\" style=\"display:none\"> <h4>Votre inscription \u00e0 notre infolettre hebdomadaire a \u00e9t\u00e9 enregistr\u00e9e avec succ\u00e8s !<\/h4> <p> <a href=\"#\" class=\"inf-btn\">&laquo;<\/a> <\/p> <\/div> <div class=\"inf-content\"> <div class=\"inf-input inf-input-text\"> <input type=\"text\" name=\"inf[1]\" data-inf-meta = \"1\" data-inf-error = \"Merci de renseigner une adresse email\" required=\"required\" placeholder=\"Email\" > <\/div> <div class=\"inf-submit\"> <input type=\"submit\" name=\"\" value=\"S\u2019inscrire\"> <\/div> <\/div> <\/div> <\/form>\n\n\n\n<p>L\u2019affaire des \u00abgilets jaunes\u00bb qui a renvers\u00e9 la France est volontairement laiss\u00e9e de c\u00f4t\u00e9 dans la conversation pour cette fois, la peur de prendre trop de place dans l&#8217;\u00e9change limit\u00e9, comme si le d\u00e9calage \u00e9tait trop grand avec l&#8217;endroit dans lequel j&#8217;ai pris place (bien mauvaise id\u00e9e) pour passer l&#8217;appel, ce pub anglais de Gen\u00e8ve peupl\u00e9 en ce jeudi soir par de riches hommes affaires russes, oreilles viss\u00e9s aux portables, le ventre d\u00e9bordant du <em>jean<\/em>, leurs poules de 185 centim\u00e8tres pleines de blondeur \u00e0 leurs c\u00f4t\u00e9s&#8230; L&#8217;appel se fait dans le brouhaha, les dames prennent la lumi\u00e8re, les hommes \u00e9ructent leurs propos dans un concert de voix dissonant. Et comme \u00e7a parle fort, la communication avec le bureau de Columbia Records \u00e0 Paris a beaucoup de mal \u00e0 passer. Je d\u00e9cide donc de quitter le confort bois\u00e9 de cette <em>public house<\/em> genevoise pour la rue, comme si on sortait de l&#8217;Elys\u00e9e pour un rond-point du Conquet. Et on d\u00e9marre l&#8217;\u00e9change par les derni\u00e8res phrases (frasques) d\u2019un personnage c\u00e9l\u00e8bre de la musique politique dissonante de France.<\/p>\n\n\n\n<p><strong>David Glaser: Tu sais que la France et un de ses plus hauts repr\u00e9sentants ont fait l\u2019actualit\u00e9 ici ces derniers temps\u2026 un Finist\u00e9rien nomm\u00e9 Richard Ferrand a d\u00e9moli le syst\u00e8me politique suisse en quelques phrases du haut de son perchoir l&#8217;\u00e9t\u00e9 dernier. Le pr\u00e9sident de l\u2019Assembl\u00e9e nationale semble ne pas croire dans la d\u00e9mocratie directe helv\u00e8te. Tu as suivi?<\/strong><\/p>\n\n\n\n<p>Christophe Miossec: Oui, j\u2019ai suivi tout \u00e7a. En m\u00eame temps, on le conna\u00eet bien \u00e0 Brest. Richard Ferrand, c\u2019est le genre de type qui offre des b\u00e2timents un peu surdimensionn\u00e9s \u00e0 sa femme, ici m\u00eame \u00e0 Brest. \u00c7a a choqu\u00e9 tout le monde, c\u2019\u00e9tait au d\u00e9but d\u2019En Marche\u2026 Bref, on a \u00e9t\u00e9 concern\u00e9s avant la Suisse.<\/p>\n\n\n\n<p><strong>Qu\u2019as-tu voulu dire avec <em>Les Rescap\u00e9s<\/em>, avec son c\u00f4t\u00e9 brut du fait de l\u2019utilisation de certaines machines?<\/strong><\/p>\n\n\n\n<p>Dans les ann\u00e9es quatre-vingt, on avait d\u00e9j\u00e0 utilis\u00e9 des bo\u00eetes \u00e0 rythmes avec Printemps Noir, mon tout premier groupe. Mon premier album <em>Boire<\/em> \u00e9tait aussi aid\u00e9 d\u2019une bo\u00eete \u00e0 rythmes car nous n\u2019avions pas de batteur. Enfin, l\u2019id\u00e9e \u00e9tait plut\u00f4t de faire un disque qu\u2019on aime jouer, d\u2019avoir cette libert\u00e9 de transposer facilement le tout sur sc\u00e8ne.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2022\/09\/Miossec2.jpg\" alt=\"Miossec2\"\/><\/figure>\n\n\n\n<p><strong>Il faudrait que tu fasses changer les musiques d\u2019attente de Columbia, c\u2019est moyen ce qu\u2019ils passent dans les t\u00e9l\u00e9phones. Comment \u00e7a se passe avec ce grand label mythique?<\/strong><\/p>\n\n\n\n<p>Oh tr\u00e8s bien, je suis tout petit chez Columbia. Du coup, les attentes ne sont pas les m\u00eames que chez PIAS&nbsp;<em>(ndlr: label franco-belge implant\u00e9 aussi au Royaume-Uni)<\/em>&nbsp;avec qui j\u2019ai fait neuf albums. L\u00e0-bas, j\u2019\u00e9tais un gros poisson, il y avait de l\u2019attente et du stress. Il leur fallait absolument des <em>singles<\/em>. Columbia, c&#8217;est donc vraiment plus tranquille. Ils ne sont pas inquiets, ils me laissent faire la musique que je souhaite. C\u00f4t\u00e9 promo, on a le soutien d\u2019une radio surtout, France Inter, et heureusement qu\u2019ils sont l\u00e0 car sans eux, je ne sais pas dans quel m\u00e9dia national je serais diffus\u00e9.<\/p>\n\n\n\n<p><strong>Je viens de voir ton album \u00e0 la Fnac de Lausanne, et des <em>singles<\/em>, il y en a. La maison de disques a mis cinq titres de chansons sur le <em>sticker<\/em> promo France Inter coll\u00e9 sur le CD. On voit l\u00e0 le <em>hitmaker<\/em> que tu es <em>(rires)<\/em>. En plus, les titres sont courts, \u00e7a rentre parfaitement sur l&#8217;autocollant.<\/strong><\/p>\n\n\n\n<p>C\u2019est pour \u00e7a que je les ai faits courts, pour que \u00e7a rentre <em>(rires)<\/em>. C\u2019est s\u00fbr qu\u2019avec les <em>Les bi\u00e8res aujourd&#8217;hui s&#8217;ouvrent manuellement<\/em>, \u00e7a aurait \u00e9t\u00e9 un peu plus dur de tout faire tout rentrer.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Miossec - Nous sommes (Clip officiel)\" width=\"1000\" height=\"563\" src=\"https:\/\/www.youtube.com\/embed\/zVxKIV_OaUU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Plus s\u00e9rieusement, tu suis ce qui se passe strat\u00e9giquement avec les CD qui se vendent moins\u2026 les disques vinyles qui refleurissent. La pochette d&#8217;un 33 tours, pardon d&#8217;un 180 grammes, \u00e7a a du style, non?<\/strong><\/p>\n\n\n\n<p>Oui, l\u2019explosion du vinyle, c\u2019est dingue. On a apport\u00e9, du fait qu&#8217;il y a ce retour du vinyle, un plus grand soin au <em>artwork<\/em> avec cette s\u00e9rigraphie pour la pochette, ce travail graphique et d&#8217;impression fait \u00e0 la main. Dans l&#8217;ensemble, l&#8217;album a ce c\u00f4t\u00e9 \u00abfait-main\u00bb, les instruments synth\u00e9tiques sont utilis\u00e9s \u00e0 l\u2019ancienne, dans un rapport \u00e0 la musique qui ne prend pas forc\u00e9ment uniquement en compte cette id\u00e9e de boucle comme on le fait depuis vingt-cinq ans dans l\u2019\u00e9lectro. Avec tous ces groupes qui utilisent la machine, les musiciens disparaissent aujourd\u2019hui. Ce que je constate, c&#8217;est que tout le monde am\u00e8ne son ordinateur sur sc\u00e8ne ou en studio. Ce n\u2019est pas mon cas.<\/p>\n\n\n\n<p><strong>En grand amateur de sport et d&#8217;exploits humains, venant d&#8217;une famille de sportifs, tu suis un peu les \u00e9v\u00e9nements nationaux. La France a gagn\u00e9 la coupe du Monde de foot, la coupe d&#8217;Europe de hand avec l&#8217;\u00e9quipe f\u00e9minine, \u00e7a t\u2019a fait quoi?<\/strong><\/p>\n\n\n\n<p>Franchement, c\u2019est moins important. Je suis \u00e7a de loin en loin. J\u2019ai bien aim\u00e9 voir la Belgique gagner, en fait <em>(Miossec rigole car il a v\u00e9cu de nombreuses ann\u00e9es en Belgique et y a enregistr\u00e9 plusieurs albums)<\/em>. Mais c&#8217;est vrai que je suis assez heureux de voir les JO d\u00e9barquer \u00e0 Paris, \u00e7a va permettre d\u2019am\u00e9nager de nouveaux espaces pour faire du kayak sur les canaux et d&#8217;autres plans d&#8217;eau, \u00e0 la Villette par exemple. Aujourd&#8217;hui, j&#8217;ai la mer pour moi, j&#8217;habite en Bretagne juste en face de l&#8217;oc\u00e9an.<\/p>\n\n\n\n<p><strong>Sur <em>Les Rescap\u00e9s<\/em>, on entend la voix de Jeanne Added, chanteuse fran\u00e7aise venue du th\u00e9\u00e2tre et du jazz, aujourd&#8217;hui respect\u00e9e pour une carri\u00e8re en pop ind\u00e9 \u00e0 forte tendance synth\u00e9tique. Comment s&#8217;est pass\u00e9e votre rencontre?<\/strong><\/p>\n\n\n\n<p>Jeanne Added, j&#8217;adore sa musique. Je l\u2019ai vue il y a huit ans dans un club \u00e0 Paris. Elle y faisait la premi\u00e8re partie de la premi\u00e8re partie d&#8217;un groupe, seule \u00e0 la basse, et j\u2019\u00e9tais impressionn\u00e9. Je suis all\u00e9 la voir apr\u00e8s ce concert. Elle \u00e9coutait mes albums avant de se lancer. Je pense que ce que fait Jeanne lui va tr\u00e8s bien aujourd&#8217;hui. Chanter en fran\u00e7ais lui va bien aussi, c&#8217;est pour \u00e7a qu&#8217;elle est venue faire des voix sur l&#8217;album.<\/p>\n\n\n\n<p><strong>Jeanne Added avait jou\u00e9 avec Rachid Taha. Toi-m\u00eame, je pense que tu devais travailler avec lui. Il est mort en septembre dernier. Un autre fr\u00e8re de la musique qui s&#8217;en va apr\u00e8s celui que tu as servi pour plusieurs albums avec des textes de chansons: Johnny. Comment vis-tu ces deux disparitions?<\/strong><\/p>\n\n\n\n<p>Oh bah, les grandes stars de la musique, c&#8217;est particulier&#8230; <em>(silence un peu g\u00ean\u00e9)<\/em>. Johnny, c&#8217;est le bordel&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2022\/09\/miossec6.jpg\" alt=\"miossec6\"\/><\/figure>\n\n\n\n<p><strong>Le bordel?<\/strong><\/p>\n\n\n\n<p>Oui, comme toujours avec Johnny, c\u2019est le bordel complet.<\/p>\n\n\n\n<p><strong>Et Rachid?<\/strong><\/p>\n\n\n\n<p>On \u00e9tait partis pour travailler chez lui et on n\u2019a pas travaill\u00e9 <em>(rires)<\/em>. Il y avait notre ami commun Hakim Hamadouche&#8230; facile de se moquer de lui avec un nom pareil, hamadouche&#8230; hamadroite&#8230; C&#8217;est le joueur de oud avec qui Rachid \u00e9tait associ\u00e9 depuis longtemps. C\u2019est toujours tr\u00e8s dr\u00f4le avec Rachid, c\u2019est un homme qui a compris la musique, le rock et les traditions arabes, kabyles mieux que quiconque. Brian Eno ne s\u2019y est pas tromp\u00e9.<\/p>\n\n\n\n<p><strong>Et qu&#8217;en est-il de toi et tes racines?<\/strong><\/p>\n\n\n\n<p>Toujours pas de musiciens bretons autour de moi, mais je suis avant tout brestois. Je dois d\u2019abord rendre fier ma m\u00e8re et mon p\u00e8re qui sont brestois. La culture bretonne bretonnante n&#8217;entre pas en compte.<\/p>\n\n\n\n<p><strong>Le rap est un genre important pour toi?<\/strong><\/p>\n\n\n\n<p>Le rap, \u00e7a me va bien, ils se passent des choses enthousiasmantes\u2026 Beaucoup plus que dans les groupes de rock. Pour moi, Lomepal est une grande r\u00e9v\u00e9lation. Il a des m\u00e9lodies qui tuent. La Squale aussi. J\u2019aime beaucoup, c\u2019est le seul dans le rap fran\u00e7ais qui te parle de la guerre d\u2019Alg\u00e9rie avec d&#8217;aussi bons textes.<\/p>\n\n\n\n<p><strong>Quels rapports entretiens-tu avec la Suisse?<\/strong><\/p>\n\n\n\n<p>Tout d&#8217;abord, Stephan Eicher, on a fait <em>Dispara\u00eetre<\/em> ensemble sur l&#8217;album <em>L&#8217;Envol\u00e9e<\/em>, on a travaill\u00e9 chez lui en Camargue, c\u2019\u00e9tait il y a cinq ou six ans. J\u2019ai aussi jou\u00e9 avec Bernard Trontin des Young Gods et Polar. Une reprise de <em>Ballade de Melody Nelson Nelson<\/em> pour la compilation Pop Sessions. J&#8217;aime beaucoup les Young Gods. Ce groupe a \u00e9t\u00e9 pionnier et ils m\u2019ont donn\u00e9 l\u2019envie de signer chez PIAS; ils y \u00e9taient avec <em>L&#8217;Eau Rouge<\/em> et <em>T.V. Sky<\/em> quand j\u2019ai sign\u00e9 pour ce label.<\/p>\n\n\n\n<p><strong>Merci Christophe et bon anniversaire!<\/strong><\/p>\n\n\n\n<p><em><strong>Dans notre \u00e9dition papier de f\u00e9vrier <a href=\"https:\/\/leregardlibre.com\/produit\/le-regard-libre-n-47\/\">en commande ici<\/a>, les prolongations not\u00e9es de David Glaser sur chacun des onze titres de l&#8217;album!<\/strong><\/em><\/p>\n\n\n\n<p><em>Ecrire \u00e0 l&#8217;auteur: <a href=\"mailto:zieggla@gmail.com\">zieggla@gmail.com<\/a><\/em><a href=\"mailto:zieggla@gmail.com\"><\/a><\/p>\n\n\n\n<p>Cr\u00e9dit photo: \u00a9&nbsp;Docks \/ Julien T Hamon<br><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Miossec<br><\/strong><a href=\"https:\/\/www.deezer.com\/fr\/artist\/1420\"><em><strong>Les Rescap\u00e9s<\/strong><\/em><\/a><em><strong>&nbsp;<\/strong><\/em><strong><br>Columbia\/Sony Music Entertainment<br>2018<br>11 titres<br>34 minutes<\/strong><\/p>\n\n\n\n<p>Miossec sera en concert aux Docks de Lausanne&nbsp;<a href=\"https:\/\/www.docks.ch\/evenement\/concerts\/20190126\/miossec\/\">le samedi 26 janvier avec Baptiste W. Hamon en premi\u00e8re partie.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Article in\u00e9dit \u2013 David Glaser, journaliste radio \u00e0 RTL\u00a0et \u00e0 la\u00a0RTSCet article est \u00e9galement disponible sur Suississimo.com Pour No\u00ebl, David&#8230;<\/p>","protected":false},"author":1,"featured_media":18472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6460],"tags":[644340719,644339057,488322,644340281,11788,644340718,644340716,1433],"class_list":["post-18470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","tag-boites-a-rythmes","tag-chanson","tag-chanson-francaise","tag-electro","tag-interviews","tag-les-rescapes","tag-miossec","tag-rock"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conversation avec Miossec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/musik\/conversation-avec-miossec\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conversation avec Miossec\" \/>\n<meta property=\"og:description\" content=\"Article in\u00e9dit \u2013 David Glaser, journaliste radio \u00e0 RTL\u00a0et \u00e0 la\u00a0RTSCet article est \u00e9galement disponible sur Suississimo.com Pour No\u00ebl, David...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/musik\/conversation-avec-miossec\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-25T12:07:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T18:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Le Regard Libre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Le Regard Libre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"17\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/\"},\"author\":{\"name\":\"Le Regard Libre\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/68aceea2de84966d0928b49556d54101\"},\"headline\":\"Conversation avec Miossec\",\"datePublished\":\"2018-12-25T12:07:39+00:00\",\"dateModified\":\"2025-11-12T18:16:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/\"},\"wordCount\":3394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Miossec.jpg\",\"keywords\":[\"boites \u00e0 rythmes\",\"Chanson\",\"Chanson fran\u00e7aise\",\"Electro\",\"Interview\",\"les rescap\u00e9s\",\"miossec\",\"Rock\"],\"articleSection\":[\"Musique\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/\",\"name\":\"Conversation avec Miossec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Miossec.jpg\",\"datePublished\":\"2018-12-25T12:07:39+00:00\",\"dateModified\":\"2025-11-12T18:16:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Miossec.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Miossec.jpg\",\"width\":2560,\"height\":1806},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/musique\\\/conversation-avec-miossec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conversation avec Miossec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/68aceea2de84966d0928b49556d54101\",\"name\":\"Le Regard Libre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g\",\"caption\":\"Le Regard Libre\"},\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"sameAs\":[\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Le_Regard_libre\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/leregardlibre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gespr\u00e4ch mit Miossec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/musik\/conversation-avec-miossec\/","og_locale":"de_DE","og_type":"article","og_title":"Conversation avec Miossec","og_description":"Article in\u00e9dit \u2013 David Glaser, journaliste radio \u00e0 RTL\u00a0et \u00e0 la\u00a0RTSCet article est \u00e9galement disponible sur Suississimo.com Pour No\u00ebl, David...","og_url":"https:\/\/leregardlibre.com\/de\/musik\/conversation-avec-miossec\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2018-12-25T12:07:39+00:00","article_modified_time":"2025-11-12T18:16:20+00:00","og_image":[{"width":2560,"height":1806,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg","type":"image\/jpeg"}],"author":"Le Regard Libre","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Le Regard Libre","Gesch\u00e4tzte Lesezeit":"17\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/"},"author":{"name":"Le Regard Libre","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/68aceea2de84966d0928b49556d54101"},"headline":"Conversation avec Miossec","datePublished":"2018-12-25T12:07:39+00:00","dateModified":"2025-11-12T18:16:20+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/"},"wordCount":3394,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg","keywords":["boites \u00e0 rythmes","Chanson","Chanson fran\u00e7aise","Electro","Interview","les rescap\u00e9s","miossec","Rock"],"articleSection":["Musique"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/","url":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/","name":"Gespr\u00e4ch mit Miossec","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg","datePublished":"2018-12-25T12:07:39+00:00","dateModified":"2025-11-12T18:16:20+00:00","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2018\/12\/Miossec.jpg","width":2560,"height":1806},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/musique\/conversation-avec-miossec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Conversation avec Miossec"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/68aceea2de84966d0928b49556d54101","name":"Le Regard Libre","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ccf13a262e399e026577c8158b11cbdef98921ac28fa06bc0d43a2d0e2a4a1c0?s=96&d=identicon&r=g","caption":"Le Regard Libre"},"description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","sameAs":["https:\/\/fr.wikipedia.org\/wiki\/Le_Regard_libre"],"url":"https:\/\/leregardlibre.com\/de\/author\/leregardlibre\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/18470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=18470"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/18470\/revisions"}],"predecessor-version":[{"id":510269,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/18470\/revisions\/510269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/18472"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=18470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=18470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=18470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}