{"id":19637,"date":"2019-02-27T09:02:01","date_gmt":"2019-02-27T08:02:01","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=19637"},"modified":"2025-12-04T22:37:22","modified_gmt":"2025-12-04T21:37:22","slug":"die-laster-von-dick-cheney-in-nahaufnahme","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/kino\/filme\/die-laster-von-dick-cheney-in-nahaufnahme\/","title":{"rendered":"Dick Cheneys Laster in Nahaufnahme"},"content":{"rendered":"<p><em>Les mercredis du cin\u00e9ma - Lauriane Pipoz<\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\"><strong>Dick Cheney ist ein Mann des Schattens.\nDurch eine Reihe von Tricks gelang es dem Mann aus dem tiefsten Wyoming, sich still und leise zum Pr\u00e4sidenten\nim Jahr 2001 zum Vizepr\u00e4sidenten auf. Er zog die F\u00e4den hinter einem George W.\nBush, der v\u00f6llig neben sich steht, und will um jeden Preis in den Irak einmarschieren. Die\nDie Anschl\u00e4ge vom 11. September bieten ihm die Gelegenheit dazu. &nbsp;<\/strong><\/p>\n\n\n\n<!--more Lire la critique-->\n\n\n\n<p>Es ist dieses Gesicht\ndes Politikers Dick Cheney, das uns Adam McKay vor Augen f\u00fchrt. Mit einer\nlinksgerichteter Einstellung bietet uns dieser Regisseur eine Biografie, die eine Anklage gegen Cheney darstellt.\nden ehemaligen Vizepr\u00e4sidenten der USA. W\u00e4hrend dieser 132 Minuten ist es praktisch unm\u00f6glich\nunm\u00f6glich, sich zu langweilen. Sein farbenfrohes Portr\u00e4t wird mit Ironie, Witz und Humor gezeichnet.\nschwarzen Humor, schlagkr\u00e4ftigen Metaphern und einer gro\u00dfen Portion \u00dcberraschungen.\n\u00dcberraschung. Und mithilfe eines brillanten Christian Bale, der sich in seiner Rolle unglaublich wohl f\u00fchlt.\nin seiner Rolle als Typ-ordin\u00e4rer-aber-ein-Monster und passt sich\nwunderbar an das sich wandelnde Image seiner Figur anpasst. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sorgf\u00e4ltig ausgew\u00e4hlte Fakten<\/strong><\/h3>\n\n\n\n<p>Um seine Geschichte zu erz\u00e4hlen und sie einem breiten Publikum verst\u00e4ndlich zu machen, hat McKay eine Reihe von Fakten ausgew\u00e4hlt, die er vereinfacht und aussagekr\u00e4ftig arrangiert hat. So vermeidet er es, in die Falle zu tappen, zu viele Elemente in rascher Folge aufzulisten. Die Pl\u00e4ne sind pr\u00e4zise, die Dialoge ausgefeilt und seine Vision sorgf\u00e4ltig ausgearbeitet. So verwendet er Zeitlupen und <em>Zooms<\/em> um sich mit bestimmten Details zu besch\u00e4ftigen. Die Interaktionen zwischen den Figuren sind lang, interessant und trotz des ernsten Themas des Films manchmal sogar richtig lustig.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"VICE Trailer VF (2019) Christian Bale\" width=\"1000\" height=\"563\" src=\"https:\/\/www.youtube.com\/embed\/xN1SYnzMARI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Die Charaktere sind ziemlich stereotyp, wie zum Beispiel der zynische und hysterische Donald Rumsfeld (Steve Carell), der unreife und manipulierbare George Bush (Sam Rockwell) oder die egoistische und machthungrige Lynne Cheney (Amy Adams). Diese Vereinfachung ist jedoch nicht st\u00f6rend: Der Film erhebt keinen Anspruch auf Realismus, sondern versucht, eine Geschichte aus einer Perspektive zu erz\u00e4hlen. Um diesen Standpunkt auf die Leinwand zu bringen, werden Cheneys Lebensgeschichten - nicht immer chronologisch, sondern mit Wiederholungen und Analepsen - mit Bildern kontrastiert, die v\u00f6llig anders gelagert sind. So zum Beispiel die Bilder eines Herzens oder von L\u00f6wen, die sich gegenseitig jagen. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Schock auf Schock<\/strong><\/h3>\n\n\n\n<p>Dieser verwirrende Cocktail hat mehrere Funktionen: Er hebt Aspekte der Geschichte hervor, wie z. B. Cheneys Monstrosit\u00e4t, er l\u00e4sst die Geschichte schneller erscheinen und h\u00e4lt den Zuschauer v\u00f6llig in Atem, da es immer wieder \u00dcberraschungen gibt. Einer der gr\u00f6\u00dften ist sicherlich ein urkomischer falscher Abspann der Art <em>Das kleine Haus in der Wiese<\/em>, Dies passt nicht zum Ton des Films, der in der Mitte des Films angesiedelt ist. Mehr wollen wir an dieser Stelle nicht verraten, denn Sie werden sich diesen unglaublich guten Film ansehen. <\/p>\n\n\n\n<p>Wir m\u00f6chten jedoch darauf hinweisen, dass einige der eingef\u00fcgten Bilder extrem schockierend sind. So werden beispielsweise Bombenexplosionen oder Standbilder von Folter- und Misshandlungsszenen gezeigt. Da die Geschichte ohnehin schon sehr schwer ist, war es wahrscheinlich nicht n\u00f6tig, noch mehr zu schockieren. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Die Geschichte von Dick Cheney, aber nicht nur das<\/strong><\/h3>\n\n\n\n<p>Wie bereits erw\u00e4hnt, wird Dick Cheneys Frau als ehrgeizige Person dargestellt. In der biografischen Erz\u00e4hlung wird immer wieder darauf hingewiesen, dass im Schatten des Mannes die Frau steht. Lynne Cheney spielt eine wichtige Rolle bei der Konstruktion dieses skrupellosen Vizepr\u00e4sidenten. Sie scheint den Mann an die Macht gebracht zu haben, indem sie ihn zu einer wichtigen Person machte, obwohl er mehr an K\u00e4mpfen als an Arbeit dachte.<\/p>\n\n\n\n<p>Ihre Figur ist besonders entsetzlich, vor allem in der Szene, in der ihre Tochter ihnen ihre Homosexualit\u00e4t offenbart: Lynne verliert nie die Fassung und stellt sofort fest, dass diese Tatsache sie die Pr\u00e4sidentschaft kosten k\u00f6nnte. Dick Cheneys Liebe zu seiner Tochter scheint der einzige Punkt zu sein, der ihn noch von einem Monster unterscheidet. Oder, wie es Donald Rumsfelds Figur formuliert, von einem \u00abr\u00fccksichtslosen Arschloch\u00bb, denn das ist das Bild des Vizepr\u00e4sidenten, das dieser formal und inhaltlich \u00e4u\u00dferst gelungene Film bei Ihnen hinterl\u00e4sst.<\/p>\n\n\n\n<p><em>Schreiben Sie dem Autor: <a href=\"mailto:lauriane.pipoz@leregardlibre.com\">lauriane.pipoz@leregardlibre.com<\/a><\/em><\/p>\n\n\n\n<p>Bildnachweis: \u00a9 Ascot Elite Entertainment<\/p>\n\n\n\n<table class=\"wp-block-table\"><thead><tr><th>Vize<\/th><\/tr><\/thead><tbody><tr><td>Vereinigte Staaten, 2019<\/td><\/tr><tr><td><em>Regie:<\/em> Adam McKay<\/td><\/tr><tr><td><em>Drehbuch:<\/em> Adam McKay<\/td><\/tr><tr><td><em>Bild:<\/em> Greig Fraser<\/td><\/tr><tr><td><em>Produktion:<\/em> Brad Pitt, Dede Gardner <em>et al.<\/em><\/td><\/tr><tr><td><em>Verteilung:<\/em> Christian Bale, Amy Adams, Steve Carell<\/td><\/tr><tr><td><em>Dauer:<\/em> 2h12<\/td><\/tr><tr><td><em>Ausgehen:<\/em><strong>&nbsp;13. Februar 2019<\/strong><\/td><\/tr><\/tbody><\/table>","protected":false},"excerpt":{"rendered":"<p>Les mercredis du cin\u00e9ma &#8211; Lauriane Pipoz Dick Cheney est un homme de l\u2019ombre: par une suite de stratag\u00e8mes, cet&#8230;<\/p>","protected":false},"author":102,"featured_media":510373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[644355829],"tags":[644341208,644341207,194221,415599,644339548,644341209,644341218,699,644341215,644341214,26256,644341210,644339707,644341217],"class_list":["post-19637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-adam-mckay","tag-amy-adams","tag-christian-bale","tag-cinema-americain","tag-cinema-engage","tag-dick-cheney","tag-donald-rumsfeld","tag-etats-unis","tag-george-w-bush","tag-guerre-dirak","tag-irak","tag-lynne-cheney","tag-vice","tag-vice-president"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les vices de Dick Cheney en gros plan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/die-laster-von-dick-cheney-in-nahaufnahme\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vices de Dick Cheney en gros plan\" \/>\n<meta property=\"og:description\" content=\"Les mercredis du cin\u00e9ma - Lauriane Pipoz Dick Cheney est un homme de l\u2019ombre: par une suite de stratag\u00e8mes, cet...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/die-laster-von-dick-cheney-in-nahaufnahme\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-27T08:02:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T21:37:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1-1024x429.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lauriane Pipoz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauriane Pipoz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/\"},\"author\":{\"name\":\"Lauriane Pipoz\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/4a90f0c5c8d33c0d6228249a2f2d37f5\"},\"headline\":\"Les vices de Dick Cheney en gros plan\",\"datePublished\":\"2019-02-27T08:02:01+00:00\",\"dateModified\":\"2025-12-04T21:37:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/\"},\"wordCount\":887,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg\",\"keywords\":[\"Adam Mckay\",\"amy adams\",\"Christian Bale\",\"Cin\u00e9ma am\u00e9ricain\",\"Cin\u00e9ma engag\u00e9\",\"dick cheney\",\"donald rumsfeld\",\"Etats-Unis\",\"george w. bush\",\"Guerre d'Irak\",\"Irak\",\"lynne cheney\",\"vice\",\"vice-pr\u00e9sident\"],\"articleSection\":[\"Films\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/\",\"name\":\"Les vices de Dick Cheney en gros plan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg\",\"datePublished\":\"2019-02-27T08:02:01+00:00\",\"dateModified\":\"2025-12-04T21:37:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg\",\"width\":3840,\"height\":1608,\"caption\":\"Christian Bale as Dick Cheney in Adam McKay\u2019s VICE, an Annapurna Pictures release. Credit : Annapurna Pictures 2018 \u00a9 Annapurna Pictures, LLC. All Rights Reserved.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/les-vices-de-dick-cheney-en-gros-plan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les vices de Dick Cheney en gros plan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/4a90f0c5c8d33c0d6228249a2f2d37f5\",\"name\":\"Lauriane Pipoz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g\",\"caption\":\"Lauriane Pipoz\"},\"sameAs\":[\"https:\\\/\\\/leregardlibre.com\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Le_Regard_libre\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/lauriane00\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dick Cheneys Laster in Nahaufnahme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/kino\/filme\/die-laster-von-dick-cheney-in-nahaufnahme\/","og_locale":"de_DE","og_type":"article","og_title":"Les vices de Dick Cheney en gros plan","og_description":"Les mercredis du cin\u00e9ma - Lauriane Pipoz Dick Cheney est un homme de l\u2019ombre: par une suite de stratag\u00e8mes, cet...","og_url":"https:\/\/leregardlibre.com\/de\/kino\/filme\/die-laster-von-dick-cheney-in-nahaufnahme\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2019-02-27T08:02:01+00:00","article_modified_time":"2025-12-04T21:37:22+00:00","og_image":[{"width":1024,"height":429,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1-1024x429.jpg","type":"image\/jpeg"}],"author":"Lauriane Pipoz","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Lauriane Pipoz","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/"},"author":{"name":"Lauriane Pipoz","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/4a90f0c5c8d33c0d6228249a2f2d37f5"},"headline":"Les vices de Dick Cheney en gros plan","datePublished":"2019-02-27T08:02:01+00:00","dateModified":"2025-12-04T21:37:22+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/"},"wordCount":887,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg","keywords":["Adam Mckay","amy adams","Christian Bale","Cin\u00e9ma am\u00e9ricain","Cin\u00e9ma engag\u00e9","dick cheney","donald rumsfeld","Etats-Unis","george w. bush","Guerre d'Irak","Irak","lynne cheney","vice","vice-pr\u00e9sident"],"articleSection":["Films"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/","url":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/","name":"Dick Cheneys Laster in Nahaufnahme","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg","datePublished":"2019-02-27T08:02:01+00:00","dateModified":"2025-12-04T21:37:22+00:00","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/02\/Vice-Szenen-ov-12-Dick-Christian-Bale-1.jpg","width":3840,"height":1608,"caption":"Christian Bale as Dick Cheney in Adam McKay\u2019s VICE, an Annapurna Pictures release. Credit : Annapurna Pictures 2018 \u00a9 Annapurna Pictures, LLC. All Rights Reserved."},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/cinema\/films\/les-vices-de-dick-cheney-en-gros-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Les vices de Dick Cheney en gros plan"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/4a90f0c5c8d33c0d6228249a2f2d37f5","name":"Lauriane Pipoz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a20095942ede01d828f2fc30b63370b5d10612b2f5f1b4099e9dd868b95749d?s=96&d=identicon&r=g","caption":"Lauriane Pipoz"},"sameAs":["https:\/\/leregardlibre.com\/","https:\/\/fr.wikipedia.org\/wiki\/Le_Regard_libre"],"url":"https:\/\/leregardlibre.com\/de\/author\/lauriane00\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/19637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=19637"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/19637\/revisions"}],"predecessor-version":[{"id":510372,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/19637\/revisions\/510372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/510373"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=19637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=19637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=19637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}