{"id":20694,"date":"2019-05-22T12:46:01","date_gmt":"2019-05-22T10:46:01","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=20694"},"modified":"2025-12-04T22:36:25","modified_gmt":"2025-12-04T21:36:25","slug":"schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/kino\/filme\/schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar\/","title":{"rendered":"\u00abSchmerz und Ruhm\u00bb: Pedro Almod\u00f3vars erster Wunsch"},"content":{"rendered":"<p><em>Film-Mittwochs - <a href=\"https:\/\/leregardlibre.com\/de\/tag\/loris-musumeci\/\">Loris S. Musumeci<\/a><\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\">Salvador Mallo hat Ruhm und Ehre erfahren. Von nun an kennt er den Schmerz. Asthma, R\u00fcckenschmerzen, Kopfschmerzen. Auch Depressionen. Denn der gro\u00dfe Filmemacher ist nicht mehr in der Lage, etwas zu schaffen. Er zieht sich in sich selbst zur\u00fcck. Ein Wiedersehen, mit dem er nicht gerechnet hatte, und die Wiederholung seines Erfolgs aus den 80er Jahren, <em>Sabor<\/em>, Doch die Ereignisse f\u00fchren zu einem Wendepunkt in seinem Leben. Er muss \u00fcber den Schmerz hinausgehen, um seinen Weg zum Ruhm zu finden. Er beginnt wieder, ein Drehbuch zu schreiben, das seine Geschichte und sein Unbehagen erz\u00e4hlt, um seine Wunden zu heilen. Um seine Vergangenheit zu heilen.<\/p>\n\n\n\n<!--more Lire la suite de la critique (en libre acc\u00e8s)-->\n\n\n\n<h3 class=\"wp-block-heading\">Hochkar\u00e4tiges Kino<\/h3>\n\n\n\n<p><em>Schmerz und Herrlichkeit<\/em>, Das ist hochkar\u00e4tiges Kino. Das Kino eines Autors. Das Kino eines Meisters. <a href=\"https:\/\/www.imdb.com\/name\/nm0000264\/\">Pedro Almod\u00f2var<\/a> ist sein autobiographischster Text. Mit einem sensiblen und wundersch\u00f6nen Antonio Banderas erz\u00e4hlt er von seiner Kindheit und der Bedeutung, die er der siebten Kunst beimisst; die Bedeutung, die er ihr in seinem Leben beimisst. Es ist also nicht n\u00f6tig, zu urteilen. Denn Almod\u00f2var bietet sich f\u00fcr keine Leistung an und vor allem muss er niemandem etwas beweisen.<\/p>\n\n\n\n\n\n<p>Doch auch wenn man die Handschrift eines selbstbewussten und wirklich k\u00fcnstlerischen Kinos erkennen kann, \u00fcberzeugt der Film nicht unbedingt in allen Punkten. Um genau zu sein, spaltet er. Nicht unbedingt zwischen denen, die ihn lieben und denen, die ihn hassen, sondern eher zwischen der Langeweile und der Leidenschaft, die er ausl\u00f6st. Oder zwischen \u00dcberfluss und Mangel. Das war der Eindruck, mit dem ich aus dem Kino kam.<\/p>\n\n\n\n<figure><iframe src=\"\/\/www.youtube.com\/embed\/ixCIp0CcR5k\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Leidenschaft und Langeweile<\/h3>\n\n\n\n<p>Der erwachsene Salvador begeistert, wenn er wieder zu schreiben beginnt, wenn man ihm in die Tiefe seiner Qualen folgt und wenn er seine Gedanken preisgibt. Der erwachsene Salvador langweilt sich, wenn er immer wieder zu seiner Mutter zur\u00fcckkehrt, wenn er mit seinen Handlungen z\u00f6gert und wenn er sich in selbstgef\u00e4lligem Z\u00f6gern ertr\u00e4nkt. Salvador als Kind zieht das Interesse auf sich, wenn er uns zu seinen W\u00fcnschen mitnimmt, insbesondere zu seinem <em>erster Wunsch<\/em>. Salvador Kind hinterl\u00e4sst jedoch eine bittere Entt\u00e4uschung, da es Details der Kindheit mit F\u00fc\u00dfen tritt, die eine gr\u00f6\u00dfere Ausbeutung verdient h\u00e4tten.<\/p>\n\n\n\n\n\n<p>Einerseits g\u00e4hnt man und langweilt sich angesichts der sich wiederholenden, klagenden und allzu diskursiven Szenen, andererseits bleibt man hungrig, wenn die in den Geschichten der Kindheit gelegten Spuren sofort wieder geschlossen werden, um in das erb\u00e4rmliche Dasein des Erwachsenen zur\u00fcckzukehren. Es ist also kompliziert. Umso mehr, als einige pseudokreative Szenen, wie die des Zeichentrickfilms, der Salvadors Leiden aufz\u00e4hlt, meiner Meinung nach pr\u00e4tenti\u00f6s und geschmacklos sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Entschuldigung Pedro<\/h3>\n\n\n\n<p>Dasselbe gilt f\u00fcr die typisch spanische \u00c4sthetik der Landschaften und Kulissen. Typisch s\u00fcdl\u00e4ndisch. Mit Sonne und wei\u00dfen W\u00e4nden, mit Blumen, Balkonen und Sonnenbrillen. So sehr ich mir bei dieser Art von Ambiente gerne die Augen aussp\u00fclen lasse. In diesem Fall war ich angewidert von diesem \u00dcberma\u00df an Sonne, von diesen \u00fcberm\u00e4\u00dfig geleckten Vierteln und D\u00f6rfern. Tut mir leid, Pedro, aber ich h\u00e4tte gerne mitgemacht.<\/p>\n\n\n\n<form method=\"post\" action=\"https:\/\/newsletter.infomaniak.com\/external\/submit\" class=\"inf-form\" target=\"_blank\"><input type=\"email\" name=\"email\" style=\"display:none\"><input type=\"hidden\" name=\"key\" value=\"eyJpdiI6IlZXRVJGMlRGQUU2alNqUE81bitIUk5adnNVa0c4MllFTStzOHdHT1FQZ3c9IiwidmFsdWUiOiJIYzhwMUVCK1pTNnlhY3MyMmhuZlhReWJqemEwNk93blMxTjFHc0s2VHZrPSIsIm1hYyI6ImVhYTQ5N2I1M2NiYWE4NzBmNjk2NzgzYjliM2Y5NmYzM2E2ZmU3NGQxNTU1ZDFkMTU1MzY5NTdjYjE3ZTJmNTUifQ==\"><input type=\"hidden\" name=\"webform_id\" value=\"7291\"><style> .inf-main_3000311ca56a1cb93397bc676c0b7fff{ background-color:#f5f5f5; padding:25px 20px; margin:25px auto; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-content { margin-top:13px;} .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff span, .inf-main_3000311ca56a1cb93397bc676c0b7fff label, .inf-main_3000311ca56a1cb93397bc676c0b7fff input, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-success p a { color:#555555; font-size:14px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4{ font-size:18px; margin:0px 0px 13px 0px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff label{ font-weight:bold; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input { margin-bottom:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff label { display:block;} .inf-main_3000311ca56a1cb93397bc676c0b7fff input{ height:35px; color:#999999; border: 1px solid #E9E9E9; border:none; padding-left:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error label, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message{ color: #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error input{ border: 1px solid #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input input { width:100%;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message { display: block; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit { text-align:right;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input{ background-color:#777777; color:#ffffff; border:none; font-weight: normal; height:auto; padding:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input.disabled{ opacity: 0.4; } .inf-btn { color: rgb(85, 85, 85); border: medium none; font-weight: normal; height: auto; padding: 7px; display: inline-block; background-color: white; box-shadow: 0px 1px 1px rgba(0, 0, 0, 0.24); border-radius: 2px; line-height: 1em; } .inf-rgpd { margin:25px 0px 15px 0px; color:#555555; } <\/style> <div class=\"inf-main_3000311ca56a1cb93397bc676c0b7fff\"> <h4>NEWSLETTER DES FREIEN BLICKS<\/h4> <span>Erhalten Sie unsere Artikel jeden Sonntag.<\/span> <div class=\"inf-success\" style=\"display:none\"> <h4>Ihre Anmeldung f\u00fcr unseren w\u00f6chentlichen Newsletter wurde erfolgreich registriert!<\/h4> <p> <a href=\"#\" class=\"inf-btn\">\u00ab<\/a> <\/p> <\/div> <div class=\"inf-content\"> <div class=\"inf-input inf-input-text\"> <input type=\"text\" name=\"inf[1]\" data-inf-meta=\"1\" data-inf-error=\"Merci de renseigner une adresse email\" required=\"required\" placeholder=\"E-Mail\"> <\/div> <div class=\"inf-submit\"> <input type=\"submit\" name=\"\" value=\"Anmelden\"> <\/div> <\/div> <\/div> <\/form>\n\n\n\n<p>Schlie\u00dflich gibt es noch zwei Schauspieler, die f\u00fcr ihr Spiel in diesem Film von keiner negativen Kritik ber\u00fchrt werden k\u00f6nnen. Es handelt sich um\u2019<a href=\"https:\/\/www.imdb.com\/name\/nm0000104\/\">Antonio Banderas<\/a> und von <a href=\"https:\/\/leregardlibre.com\/de\/tag\/penelope-cruz\/\">Pen\u00e9lope Cruz<\/a>. Obwohl die beiden nie zusammen spielen - Penelope Cruz spielt die Mutter von Salvador Kind -, bringen sie fast allein den ganzen Spielfilm zum Schwingen. Das Gesicht der einen sagt die ganze sanfte Wut der spanischen M\u00fctter aus, die gleichzeitig Diktatorinnen und Gluckenm\u00fctter sind. Das Gesicht des anderen sagt die ganze tragische Tiefe der spanischen K\u00fcnstler aus, die von einer Kultur durchdrungen sind, die Schmerz und Ruhm feiert.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-scaled.jpg\" alt=\"06\" class=\"wp-image-20696\"\/><\/figure>\n\n\n\n<p><em>Schreiben Sie dem Autor:&nbsp;<a href=\"mailto:loris.musumeci@leregardlibre.com\">loris.musumeci@leregardlibre.com<\/a><\/em><\/p>\n\n\n\n<p>Fotocredit: \u00a9 Path\u00e9 Films<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Schmerz und Ruhm<\/th><\/tr><\/thead><tbody><tr><td>SPANIEN, 2019<\/td><\/tr><tr><td><em>Regie:<\/em>&nbsp;Pedro Almod\u00f2var<\/td><\/tr><tr><td><em>Drehbuch: Pedro Almod\u00f2var<\/em><\/td><\/tr><tr><td><em>Dolmetschen:<\/em>&nbsp;Antonio Banderas, Asier Flores, Penelope Cruz, Asier Etxeandia, Leonardo Sbaraglia, Nora Navas, Julieta Serrano, C\u00e9sar Vicente<\/td><\/tr><tr><td><em>Produktion:<\/em>&nbsp;El Deseo<\/td><\/tr><tr><td><em>Verteilung:<\/em>&nbsp;Path\u00e9 Filme<\/td><\/tr><tr><td><em>Dauer:<\/em>&nbsp;1h52<\/td><\/tr><tr><td><em>Ausgehen:<\/em><strong>&nbsp;17. Mai 2019<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"excerpt":{"rendered":"<p>Les mercredis du cin\u00e9ma \u2013 Loris S. Musumeci Salvador Mallo a connu la gloire. D\u00e9sormais, il conna\u00eet la douleur. Asthme,&#8230;<\/p>","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[644355829],"tags":[644341999,644342008,644342005,644341998,644341146,644341995,357966,209662,940893,644342004,644342002,644342003,422108,33752,644341997],"class_list":["post-20694","post","type-post","status-publish","format-standard","hentry","category-films","tag-antonio-banderas","tag-cannes-2019","tag-cesar-vicente","tag-cineaste","tag-critiques-cinema","tag-douleur-et-gloire","tag-enfance","tag-espagne","tag-festival-de-cannes","tag-julieta-serrano","tag-leonardo-sbaraglia","tag-nora-navas","tag-pedro-almodovar","tag-penelope-cruz","tag-sabor"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var<\/title>\n<meta name=\"description\" content=\"Douleur et gloire, du cin\u00e9ma de haute voltige. Du cin\u00e9ma d\u2019un ma\u00eetre. Pedro Almod\u00f2var signe l\u00e0 son texte le plus autobiographique. Critique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var\" \/>\n<meta property=\"og:description\" content=\"Douleur et gloire, du cin\u00e9ma de haute voltige. Du cin\u00e9ma d\u2019un ma\u00eetre. Pedro Almod\u00f2var signe l\u00e0 son texte le plus autobiographique. Critique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-22T10:46:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T21:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Loris S. Musumeci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loris S. Musumeci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/\"},\"author\":{\"name\":\"Loris S. Musumeci\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/04d80ec47094bca6b1fa22dffad24005\"},\"headline\":\"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var\",\"datePublished\":\"2019-05-22T10:46:01+00:00\",\"dateModified\":\"2025-12-04T21:36:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/06-scaled.jpg\",\"keywords\":[\"Antonio Banderas\",\"Cannes 2019\",\"c\u00e9sar vicente\",\"cin\u00e9aste\",\"Critique cin\u00e9ma\",\"douleur et gloire\",\"Enfance\",\"Espagne\",\"Festival de Cannes\",\"julieta serrano\",\"leonardo sbaraglia\",\"nora navas\",\"Pedro Almod\u00f3var\",\"Penelope Cruz\",\"sabor\"],\"articleSection\":[\"Films\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/\",\"name\":\"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/06-scaled.jpg\",\"datePublished\":\"2019-05-22T10:46:01+00:00\",\"dateModified\":\"2025-12-04T21:36:25+00:00\",\"description\":\"Douleur et gloire, du cin\u00e9ma de haute voltige. Du cin\u00e9ma d\u2019un ma\u00eetre. Pedro Almod\u00f2var signe l\u00e0 son texte le plus autobiographique. Critique\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#primaryimage\",\"url\":\"http:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/06-scaled.jpg\",\"contentUrl\":\"http:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/06-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/04d80ec47094bca6b1fa22dffad24005\",\"name\":\"Loris S. Musumeci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"caption\":\"Loris S. Musumeci\"},\"sameAs\":[\"https:\\\/\\\/leregardlibre.com\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Le_Regard_libre\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/loris-musumeci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00abSchmerz und Ruhm\u00bb: Pedro Almod\u00f3vars erster Wunsch","description":"Schmerz und Ruhm - hochkar\u00e4tiges Kino. Das Kino eines Meisters. Pedro Almod\u00f2var schreibt hier seinen autobiografischsten Text. Kritik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/kino\/filme\/schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var","og_description":"Douleur et gloire, du cin\u00e9ma de haute voltige. Du cin\u00e9ma d\u2019un ma\u00eetre. Pedro Almod\u00f2var signe l\u00e0 son texte le plus autobiographique. Critique","og_url":"https:\/\/leregardlibre.com\/de\/kino\/filme\/schmerz-und-ruhm-der-erste-wunsch-von-pedro-almodovar\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2019-05-22T10:46:01+00:00","article_modified_time":"2025-12-04T21:36:25+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-1024x683.jpg","type":"image\/jpeg"}],"author":"Loris S. Musumeci","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Loris S. Musumeci","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/"},"author":{"name":"Loris S. Musumeci","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/04d80ec47094bca6b1fa22dffad24005"},"headline":"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var","datePublished":"2019-05-22T10:46:01+00:00","dateModified":"2025-12-04T21:36:25+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#primaryimage"},"thumbnailUrl":"http:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-scaled.jpg","keywords":["Antonio Banderas","Cannes 2019","c\u00e9sar vicente","cin\u00e9aste","Critique cin\u00e9ma","douleur et gloire","Enfance","Espagne","Festival de Cannes","julieta serrano","leonardo sbaraglia","nora navas","Pedro Almod\u00f3var","Penelope Cruz","sabor"],"articleSection":["Films"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/","url":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/","name":"\u00abSchmerz und Ruhm\u00bb: Pedro Almod\u00f3vars erster Wunsch","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#primaryimage"},"thumbnailUrl":"http:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-scaled.jpg","datePublished":"2019-05-22T10:46:01+00:00","dateModified":"2025-12-04T21:36:25+00:00","description":"Schmerz und Ruhm - hochkar\u00e4tiges Kino. Das Kino eines Meisters. Pedro Almod\u00f2var schreibt hier seinen autobiografischsten Text. Kritik","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#primaryimage","url":"http:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-scaled.jpg","contentUrl":"http:\/\/leregardlibre.com\/wp-content\/uploads\/2019\/05\/06-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/cinema\/films\/douleur-et-gloire-le-premier-desir-de-pedro-almodovar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"\u00abDouleur et gloire\u00bb: le premier d\u00e9sir de Pedro Almod\u00f2var"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/04d80ec47094bca6b1fa22dffad24005","name":"Loris S. Musumeci","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","caption":"Loris S. Musumeci"},"sameAs":["https:\/\/leregardlibre.com\/","https:\/\/fr.wikipedia.org\/wiki\/Le_Regard_libre"],"url":"https:\/\/leregardlibre.com\/de\/author\/loris-musumeci\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/20694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=20694"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/20694\/revisions"}],"predecessor-version":[{"id":510504,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/20694\/revisions\/510504"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=20694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=20694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=20694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}