{"id":33760,"date":"2020-05-02T19:15:00","date_gmt":"2020-05-02T17:15:00","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=33760"},"modified":"2025-12-04T22:26:48","modified_gmt":"2025-12-04T21:26:48","slug":"la-plateforme-non-explication-du-film","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/kino\/filme\/la-plateforme-non-explication-du-film\/","title":{"rendered":"\u00abThe Platform\u00bb: Nicht-Erkl\u00e4rung des Films"},"content":{"rendered":"<p><em>Der Netflix &amp; Chill des Samstags - Loris S. Musumeci<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abWissen Sie, wozu dieses Loch dient?\u00bb&nbsp;<\/p><\/blockquote>\n\n\n\n<p class=\"has-drop-cap\">Vorbereitung des Buffets. Exquisite Gerichte. Der Koch kontrolliert jedes Gericht bis ins Detail. Es ist fertig und es kann losgehen. Das Essen wird in gro\u00dfen Mengen angerichtet, aber auf einer Betonplattform. Die Plattform f\u00fchrt einen unterirdischen Turm hinunter, der in Ebenen unterteilt ist und eher einem Loch gleicht. Auf jeder Ebene leben zwei Bewohner, die ein paar Augenblicke Zeit haben, ohne die M\u00f6glichkeit, Essen beiseite zu legen, da sie sonst bestraft werden, um sich zu ern\u00e4hren. <em>Tabelle<\/em> der Plattform, die auf jeder Etage stoppt. Um den Abstieg fortzusetzen. Die Bewohner der oberen Stockwerke haben eine gro\u00dfe Auswahl an Essen, aber je weiter die Plattform nach unten f\u00e4hrt, desto weniger bleibt \u00fcbrig. Und was schlie\u00dflich \u00fcbrig bleibt, ist unappetitlich oder sogar eklig. Die Bewohner der oberen Etagen z\u00f6gern nicht, sich zu \u00fcbergeben oder auf das Buffet zu koten, sobald sie sich den Bauch vollgeschlagen oder hier und da die Kr\u00fcmel der Reste abgeleckt haben.<\/p>\n\n\n\n<!--more Lire la suite de la critique-->\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430.jpg\" alt=\"\" class=\"wp-image-33767\" srcset=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430.jpg 1280w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-1170x658.jpg 1170w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-585x329.jpg 585w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-150x84.jpg 150w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-300x169.jpg 300w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-768x432.jpg 768w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-1024x576.jpg 1024w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/films-d-horreur-fantastique-5e846088bf430-600x338.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p>Oui, parce que dans cette tour, il y a une r\u00e8gle qui s\u2019impose en \u00e9vidence: les personnes aux \u00e9tages sup\u00e9rieurs <em>sind <\/em>sup\u00e9rieurs et il est normal qu\u2019ils ne communiquent pas avec les r\u00e9sidents inf\u00e9rieurs, et hors de question de les aider. Et les personnes des \u00e9tages inf\u00e9rieurs <em>sind <\/em>inf\u00e9rieurs. Ils ne m\u00e9ritent que merde et m\u00e9pris. Goreng, nouveau r\u00e9sident, est surpris d\u2019un tel fonctionnement; d\u2019autant plus qu\u2019il est entr\u00e9 volontairement dans ce centre \u2013 une prison, en fait \u2013 pour arr\u00eater de fumer. Autant dire que son tabagisme a cess\u00e9, puisqu\u2019il n\u2019a eu droit d\u2019emporter qu\u2019un seul effet personnel: confinement pour confinement, il pris avec lui le <em>Don Quichotte<\/em> de Cervant\u00e8s.<\/p>\n\n\n\n<p>Mais un livre ne lui est peut-\u00eatre pas de la plus grande n\u00e9cessit\u00e9 dans un milieu qui, au fil des semaines, devient de plus en plus hostile. Le mis\u00e8re devient trop grande et Goreng se r\u00e9volte: il met en \u0153uvre un plan de solidarit\u00e9 pour r\u00e9partir les vivres \u00e9quitablement entre les diff\u00e9rents niveaux. Mais ses moyens sont peu de chose face \u00e0 la m\u00e9canique infernale du trou, face \u00e0 une humanit\u00e9 barbare, soit \u00e9go\u00efste et goinfre, soit affam\u00e9e et violente, qui est capable d\u2019aller jusqu\u2019au cannibalisme.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"La Plateforme | Bande-annonce |\u00a0Netflix\" width=\"1000\" height=\"563\" src=\"https:\/\/www.youtube.com\/embed\/_Ji2qTZXTMA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Un peu trop simple, mais pas si simple<\/h3>\n\n\n\n<p>Tout est simple, tout est clair. <em>La Plateforme<\/em> est une critique du capitalisme, totalitaire et injuste, qui donne trop aux uns et rien aux autres. La tour est une m\u00e9taphore de la soci\u00e9t\u00e9; ses niveaux repr\u00e9sentent les classes sociales: allant des riches bourgeois \u00e9go\u00efstes qui bouffent comme des porcs, sans respect ni pour la nourriture ni pour rien du tout, jusqu\u2019aux mis\u00e9reux qui grattent les plats pour essayer de se mettre quelque chose sous la dent, qui craignent leurs sup\u00e9rieurs qui les oppriment, qui souffrent, tant et tant, qu\u2019ils en arrivent au crime, cons\u00e9quence de leur pauvret\u00e9. Goreng, incarnation de l\u2019id\u00e9al socialiste, de l\u2019homme cultiv\u00e9, de l\u2019esprit \u00e9veill\u00e9 qui prend conscience de l\u2019absurdit\u00e9 de ce syst\u00e8me, choisit la r\u00e9volte pour arr\u00eater la m\u00e9canique destructrice et absurde qui fait de chaque citoyen soit un bourreau soit une victime.<\/p>\n\n\n\n<p>Discussion termin\u00e9e. Merci au revoir! Si le film se pr\u00e9sente effectivement sous la forme d\u2019une m\u00e9taphore qui critique bel est bien le syst\u00e8me capitaliste, il ne saurait pourtant s\u2019y limiter. Une part de la r\u00e9alisation de Galder Gaztelu-Urrutia d\u00e9\u00e7oit cependant. Elle est n\u2019est pas que simpliste, mais elle est aussi un peu simpliste. Par moments trop d\u00e9monstrative, trop insistante, trop cousue de fil blanc. Le sc\u00e9nario dit trop clairement ce qu\u2019il aurait eu avantage \u00e0 sugg\u00e9rer, avec plus de nuance, moins d\u2019\u00e9vidence. Comme lorsque le camarade d\u2019\u00e9tage de Goreng lui reproche ses id\u00e9es de solidarit\u00e9 en lui demandant: \u00abMais alors tu es un sale communiste?\u00bb et Goreng de lui r\u00e9pondre avec une sagesse douteuse: \u00abNon, je suis juste pour l\u2019\u00e9quit\u00e9.\u00bb D\u2019accord, mais c\u2019est un peu facile. Un peu gros, voire id\u00e9ologique.<\/p>\n\n\n\n<p>Le symbole du livre qu\u2019emporte le personnage principal dans la tour parle aussi un peu trop de lui-m\u00eame: forc\u00e9ment, le seul qui a pris un livre est le seul qui ose r\u00e9agir face \u00e0 l\u2019injustice, parce qu\u2019il est cultiv\u00e9 et brave. La culture, c\u2019est le salut; l\u2019\u00e9ducation, le meilleur antidote contre la criminalit\u00e9 et la barbarie. En soi, toutes ces id\u00e9es ne sont pas fausses ou mauvaises, loin de l\u00e0, mais une \u0153uvre de fiction n\u2019est pas un essai philosophique ou soci\u00e9tal. La transmission doit s\u2019op\u00e9rer majoritairement \u00e0 travers l\u2019exp\u00e9rience des personnages, leur \u00e9volution dans la trame, la mise en sc\u00e8ne des plans et des sc\u00e8nes, et une orchestration significative des bruitages et de la musique.<\/p>\n\n\n\n<p>Certaines images et \u00e9l\u00e9ments du d\u00e9cor, bien qu\u2019\u00e0 moindre mesure, veulent trop en montrer: la murs sont gris, parce que la vie dans cette tour est malheureuse, soumise \u00e0 une organisation totalitaire; les carreaux lumineux s\u2019allument pour r\u00e9gler le rythme de la journ\u00e9e entre heure du repas, de sommeil, de la toilette; et l\u2019architecture du bureau d\u2019inscription au centre \u2013 qui appara\u00eet lors d\u2019une seule sc\u00e8ne, la seule hormis la sc\u00e8ne d\u2019ouverture, qui se situe hors de la tour \u2013 se pr\u00e9sente trop \u00e9videmment fasciste, r\u00e9cup\u00e9rant les \u00e9l\u00e9ments formels de l\u2019architecture fasciste qui existe r\u00e9ellement, mais en la modernisant \u00e0 coups de b\u00e9ton et de n\u00e9ons. Comme pour le sc\u00e9nario, le r\u00e9alisateur ne commet ni erreur ni faute de go\u00fbt dans son d\u00e9cor. Il est encore une fois simplement trop insistant. On voit trop la r\u00e9flexion qu\u2019il y a derri\u00e8re le r\u00e9sultat.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1280\" height=\"720\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique.jpg\" alt=\"\" class=\"wp-image-33765\" srcset=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique.jpg 1280w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-1170x658.jpg 1170w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-585x329.jpg 585w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-150x84.jpg 150w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-300x169.jpg 300w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-768x432.jpg 768w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-1024x576.jpg 1024w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-film-netflix-critique-600x338.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Pas si simple, et riche en r\u00e9flexions<\/h3>\n\n\n\n<p>Ce qui n\u2019emp\u00eache pas la photographie de prouver un travail minutieux, intelligent, et tout bonnement efficace. La tour est bien con\u00e7ue, les plans en contre-plong\u00e9e, tr\u00e8s nombreux, r\u00e9v\u00e8lent bien l\u2019\u00e9tat d\u2019\u00e2me des personnages, \u00e9cras\u00e9s par le syst\u00e8me, \u00e9cras\u00e9s par leurs vices. La photographie impressionne particuli\u00e8rement dans sa gestion du temps. Lorsque Goreng passe des journ\u00e9es plut\u00f4t paisibles, la cam\u00e9ra va tr\u00e8s vite, en d\u00e9coupant la sc\u00e8ne en plans brefs qui ne montrent qu\u2019une action. Actions du quotidien, de la vie de chacun, de la vie du consommateur moyen, la vie d\u2019une personne normale en somme. Et l\u2019on passe fr\u00e9n\u00e9tiquement, entre la lumi\u00e8re rouge de la nuit et la lumi\u00e8re \u00abnaturelle\u00bb du jour, des mains qui plongent violemment dans les plats, de la gueule qui engloutit, de la bouteille de vin empoign\u00e9e, du vomissement, au rasage, \u00e0 la masturbation, \u00e0 la gymnastique. L\u2019habilet\u00e9 de la sc\u00e8ne r\u00e9side totalement dans l\u2019identification qu\u2019elle suscite chez le spectateur. Comme si, en quelque sorte, nous vivions tous dans cette tour.<\/p>\n\n\n\n<p>Et puisque <em>La Plateforme<\/em>, dans son propos, n\u2019est pas que simpliste, on voit que la critique plut\u00f4t superficielle du capitalisme est d\u00e9pass\u00e9e par une exploration de l\u2019\u00e2me humaine, et de ce qu\u2019il y a au plus intime de l\u2019\u00e2me: des passions les plus barbares aux aspirations les plus nobles. Sans oublier la philosophie et la th\u00e9ologie qui s\u2019ins\u00e8rent dans l\u2019\u00e9volution de l\u2019histoire, en poussant la r\u00e9flexion jusqu\u2019au statut d\u2019un messie dans une soci\u00e9t\u00e9 \u2013 qui est le sauveur? quel est son r\u00f4le? en a-t-on vraiment besoin? Jusqu\u2019aux paroles du Messie: \u00ab Celui qui mange ma chair et boit mon sang demeure en moi et moi en lui.\u00bb Cette d\u00e9claration du Christ l\u00e9gitime le cannibalisme selon une r\u00e9sidente, mais on comprend que le sens profond de la phrase est biais\u00e9e par la mis\u00e8re des prisonniers, dans la mesure o\u00f9 une parole de Vie devient parole de Mort. Dans la tour, tout est invers\u00e9; \u00e0 l\u2019image de notre soci\u00e9t\u00e9 o\u00f9 tant de paroles d\u2019esp\u00e9rance, de r\u00e9volutions et de v\u0153ux pieux d\u2019\u00e9galit\u00e9 ont pour cons\u00e9quence leur exact oppos\u00e9.<\/p>\n\n\n\n<p>Il est surprenant de voir que les articles d\u2019<em>explication<\/em> du film explosent sur le web, mais que presque aucun ne pousse la r\u00e9flexion plus loin que la critique du capitalisme. D\u2019ailleurs, \u00e0 quoi bon <em>expliquer<\/em> un film? D\u2019autant plus quand c\u2019est pour le faire maladroitement, en limitant le film \u00e0 son apparence. Une \u0153uvre cin\u00e9matographique, \u00e7a s\u2019analyse, \u00e7a s\u2019interpr\u00e8te, \u00e7a m\u00e8ne \u00e0 faire entrer la r\u00e9flexion en r\u00e9sonance avec sa propre exp\u00e9rience, ses connaissances, mais pourquoi l\u2019expliquer? Pourquoi pr\u00e9tendre comme beaucoup avoir la clef pour comprendre la fin du film? Tout cela n\u2019a pas de sens: la fin est ouverte, contrairement \u00e0 la tour. La fin et les commentaires \u00e0 son sujet ne peuvent pas limiter <em>La Plateforme<\/em>: il faut chercher, m\u00e9diter, reconstruire, laisser son c\u0153ur ouvert \u00e0 ce que dit l\u2019\u0153uvre.<\/p>\n\n\n\n<p>Vous avez donc assist\u00e9 par cet article \u00e0 une <em>non-explication<\/em> du film. Si vous ne l\u2019avez pas vu et que le vertige vous tente, regardez-le. Et regardez-vous en lui. Sans rien expliquer.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1920\" height=\"1081\" src=\"http:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere.jpg\" alt=\"\" class=\"wp-image-33766\" srcset=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere.jpg 1920w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-1170x659.jpg 1170w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-585x329.jpg 585w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-150x84.jpg 150w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-300x169.jpg 300w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-768x432.jpg 768w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-1024x577.jpg 1024w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-1536x865.jpg 1536w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/la-plateforme-netflix-fin-explications-film-banniere-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p><em>Schreiben Sie dem Autor:&nbsp;<a href=\"mailto:loris.musumeci@leregardlibre.com\">loris.musumeci@leregardlibre.com<\/a><\/em><\/p>\n\n\n\n<p>Fotocredits: \u00a9 Netflix<\/p>","protected":false},"excerpt":{"rendered":"<p>Sehen Sie sich in \u00abThe Platform\u00bb an\u00bb<\/p>","protected":false},"author":18,"featured_media":33764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[644355829],"tags":[644349304,644349303,615812,644341146,2273843,644349306,644349305,1154770,644349300,644338981,57616,72034,441420,644349302],"class_list":["post-33760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-buffet","tag-cannibalisme","tag-capitalisme","tag-critiques-cinema","tag-dystopie","tag-galder-gaztelu-urrutia","tag-goreng","tag-inegalites","tag-la-plateforme","tag-netflix","tag-nourriture","tag-prison","tag-totalitarisme","tag-trou"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00abLa Plateforme\u00bb: non-explication du film<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/la-plateforme-non-explication-du-film\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLa Plateforme\u00bb: non-explication du film\" \/>\n<meta property=\"og:description\" content=\"Regardez-vous dans \u00abLa Plateforme\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/kino\/filme\/la-plateforme-non-explication-du-film\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-02T17:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T21:26:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Loris S. Musumeci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loris S. Musumeci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/\"},\"author\":{\"name\":\"Loris S. Musumeci\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/04d80ec47094bca6b1fa22dffad24005\"},\"headline\":\"\u00abLa Plateforme\u00bb: non-explication du film\",\"datePublished\":\"2020-05-02T17:15:00+00:00\",\"dateModified\":\"2025-12-04T21:26:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/\"},\"wordCount\":1636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/maxresdefault.jpg\",\"keywords\":[\"buffet\",\"Cannibalisme\",\"Capitalisme\",\"Critique cin\u00e9ma\",\"Dystopie\",\"galder gaztelu-urrutia\",\"goreng\",\"In\u00e9galit\u00e9s\",\"la plateforme\",\"Netflix\",\"Nourriture\",\"prison\",\"Totalitarisme\",\"trou\"],\"articleSection\":[\"Films\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/\",\"name\":\"\u00abLa Plateforme\u00bb: non-explication du film\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/maxresdefault.jpg\",\"datePublished\":\"2020-05-02T17:15:00+00:00\",\"dateModified\":\"2025-12-04T21:26:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/maxresdefault.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/maxresdefault.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/cinema\\\/films\\\/la-plateforme-non-explication-du-film\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLa Plateforme\u00bb: non-explication du film\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/04d80ec47094bca6b1fa22dffad24005\",\"name\":\"Loris S. Musumeci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g\",\"caption\":\"Loris S. Musumeci\"},\"sameAs\":[\"https:\\\/\\\/leregardlibre.com\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Le_Regard_libre\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/loris-musumeci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00abThe Platform\u00bb: Nicht-Erkl\u00e4rung des Films","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/kino\/filme\/la-plateforme-non-explication-du-film\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abLa Plateforme\u00bb: non-explication du film","og_description":"Regardez-vous dans \u00abLa Plateforme\u00bb","og_url":"https:\/\/leregardlibre.com\/de\/kino\/filme\/la-plateforme-non-explication-du-film\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2020-05-02T17:15:00+00:00","article_modified_time":"2025-12-04T21:26:48+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg","type":"image\/jpeg"}],"author":"Loris S. Musumeci","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Loris S. Musumeci","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/"},"author":{"name":"Loris S. Musumeci","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/04d80ec47094bca6b1fa22dffad24005"},"headline":"\u00abLa Plateforme\u00bb: non-explication du film","datePublished":"2020-05-02T17:15:00+00:00","dateModified":"2025-12-04T21:26:48+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/"},"wordCount":1636,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg","keywords":["buffet","Cannibalisme","Capitalisme","Critique cin\u00e9ma","Dystopie","galder gaztelu-urrutia","goreng","In\u00e9galit\u00e9s","la plateforme","Netflix","Nourriture","prison","Totalitarisme","trou"],"articleSection":["Films"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/","url":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/","name":"\u00abThe Platform\u00bb: Nicht-Erkl\u00e4rung des Films","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg","datePublished":"2020-05-02T17:15:00+00:00","dateModified":"2025-12-04T21:26:48+00:00","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2020\/05\/maxresdefault.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/cinema\/films\/la-plateforme-non-explication-du-film\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"\u00abLa Plateforme\u00bb: non-explication du film"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/04d80ec47094bca6b1fa22dffad24005","name":"Loris S. Musumeci","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa476654dadfee0d962e80160d0303549febb2769f8fa26c7a1ebe037f7c7c54?s=96&d=identicon&r=g","caption":"Loris S. Musumeci"},"sameAs":["https:\/\/leregardlibre.com\/","https:\/\/fr.wikipedia.org\/wiki\/Le_Regard_libre"],"url":"https:\/\/leregardlibre.com\/de\/author\/loris-musumeci\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/33760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=33760"}],"version-history":[{"count":1,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/33760\/revisions"}],"predecessor-version":[{"id":511742,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/33760\/revisions\/511742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/33764"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=33760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=33760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=33760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}