{"id":522371,"date":"2024-02-14T06:00:00","date_gmt":"2024-02-14T05:00:00","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=522371"},"modified":"2025-04-06T21:09:14","modified_gmt":"2025-04-06T19:09:14","slug":"les-africains-meritent-de-retrouver-la-liberte-economique","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/wirtschaft\/les-africains-meritent-de-retrouver-la-liberte-economique\/","title":{"rendered":"Afrikaner verdienen es, wieder wirtschaftliche Freiheit zu erlangen"},"content":{"rendered":"<p class=\"has-drop-cap\"><strong>Der Kontinent hatte jahrhundertelang freien Handel und dezentralisierte Institutionen, bevor die Kolonialherren kamen. Heute liegt die Wiederbelebung Afrikas in den H\u00e4nden seiner B\u00fcrger.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><em><em>L\u2019<a href=\"https:\/\/schweizermonat.ch\/afrikaner-muessen-ihre-wirtschaftliche-freiheit-zurueckgewinnen\/\">Originalartikel<\/a><a href=\"https:\/\/schweizermonat.ch\/die-bewaffnete-neutralitaet-ist-ein-friedensangebot\/\">&nbsp;<\/a>ist auf Deutsch erschienen in&nbsp;<\/em><\/em>Schweizer Monat<em><em>.<\/em><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p>F\u00fcr viele scheint es, als w\u00fcrde die Geschichte Afrikas mit der Ankunft der Europ\u00e4er und sp\u00e4ter der Amerikaner beginnen. Dabei hat Afrika schon Tausende von Jahren vor diesen Ereignissen gro\u00dfe Zivilisationen beherbergt. Ich freue mich, dass Henry Louis Gates, ein ber\u00fchmter Harvard-Professor, k\u00fcrzlich einen sechsst\u00fcndigen Dokumentarfilm f\u00fcr den Sender PBS mit dem Titel Africa's Great Civilizations (\u00abAfrikas gro\u00dfe Zivilisationen\u00bb) produziert hat. Die Dokumentation gibt einen \u00dcberblick \u00fcber mehr als 200.000 Jahre afrikanischer Geschichte und pr\u00e4sentiert diese auf eine angenehme und farbenfrohe Weise. Das ist ein unsch\u00e4tzbarer Vorteil, denn die meisten anderen verf\u00fcgbaren Ressourcen sind akademisch und daher oft langweilig oder sogar abschreckend.<\/p>\n\n\n\n<p>Gates betont zum Beispiel, dass alle Menschen afrikanische Wurzeln haben. Alle acht Milliarden von uns sind Cousins! Gates betont auch, dass vieles von dem, was uns zu Menschen macht, aus Afrika stammt, einschlie\u00dflich Schrift, Kunst und Musik.<\/p>\n\n\n\n<p>Nehmen wir zum Beispiel Mansa Musa, den Kaiser von Mali im 14. Jahrhundert. Jahrhundert. Zu dieser Zeit war er der reichste Mann der Welt - und wahrscheinlich auch aller Zeiten. Mansa Musa kam vor allem durch den Handel mit Gold und Salz zu seinem Reichtum, den er nutzte, um neue L\u00e4ndereien zu erobern, aber auch, um in Timbuktu nicht nur ein gro\u00dfes Handelszentrum, sondern auch eine Stadt der Universit\u00e4ten und Gelehrten zu errichten.<\/p>\n\n\n\n<p>W\u00e4hrend die erste Universit\u00e4t der Welt 859 n. Chr. in Fes gegr\u00fcndet wurde (und damit mindestens hundert Jahre vor Oxford), entwickelte sich die Sankore-Universit\u00e4t in Timbuktu (im heutigen Mali) aus einer 989 n. Chr. gegr\u00fcndeten Moschee und baute unter Mansa Musa eine der gr\u00f6\u00dften Bibliotheken der Welt auf - die gr\u00f6\u00dfte in Afrika seit der Bibliothek von Alexandria.<\/p>\n\n\n\n<p>Wie Gates sagt, sind diese und andere gro\u00dfartige Errungenschaften ein \u00abtiefgreifender Widerspruch\u00bb zu dem Glauben, dass Afrika vor der Ankunft der Europ\u00e4er keine Geschichte hatte: \u00abDieser Kontinent war schon immer dynamisch, vernetzt und ein Teil der Weltgeschichte\u00bb.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-l-afrique-et-le-libre-echange-vont-de-pair\">Afrika und Freihandel gehen Hand in Hand<\/h3>\n\n\n\n<p>Diese Verbindung wurde aufgebaut und aufrechterhalten, wie sie es auch heute noch tut: durch Austausch und Handel. Die afrikanischen Zivilisationen entwickelten sich an der Ostk\u00fcste durch den Handel mit Asien. Zwischen 800 und 1600 n. Chr. wurden sch\u00e4tzungsweise 500 Tonnen Gold, von denen ein Gro\u00dfteil aus dem Inneren des Kontinents stammte, \u00fcber die H\u00e4fen im Osten transportiert. Die Westk\u00fcste verband sich mit Europa und Nord- und S\u00fcdamerika und der Handel verhalf unseren fr\u00fchen Imperien zu Wohlstand.<\/p>\n\n\n\n<p>Und jetzt haben die afrikanischen Staaten alle hohe Zollschranken. Was stimmt an diesem Bild nicht? Das afrikanische Freihandelsabkommen, das in den letzten Jahren von den meisten afrikanischen Staaten unterzeichnet wurde, wird endlich die Handelsbarrieren abbauen (wenn es tats\u00e4chlich umgesetzt wird, wie es die afrikanischen F\u00fchrer versprochen haben). Aber wirklich, warum mussten wir bis 2021 warten, um den Freihandel innerhalb Afrikas zu erhalten, der unser Geburtsrecht war?<\/p>\n\n\n\n<p>Schlimmer noch, dieses Abkommen betrifft nur den Handel <em>im Inneren<\/em> aus dem afrikanischen Kontinent. Im Gegensatz zu den ehemaligen Gro\u00dfk\u00f6nigreichen Afrikas, die weltweit Handel trieben, werden die afrikanischen Nationen h\u00f6chstwahrscheinlich weiterhin hohe Z\u00f6lle auf Waren von au\u00dferhalb Afrikas beibehalten.<\/p>\n\n\n\n<p>Wie der verstorbene Wirtschaftswissenschaftler George Ayittey schrieb, bestand die Handelsfreiheit schon Jahrhunderte vor der Ankunft der Kolonialherren und war eine grundlegende Lebensweise f\u00fcr fast alle Menschen in Subsahara-Afrika. Das Blut der pers\u00f6nlichen Freiheit flie\u00dft durch die Adern der afrikanischen Geschichte, seit die afrikanischen St\u00e4mme eine dezentralisierte Regierungsstruktur verwendeten, die sich von der des modernen afrikanischen Staates (der im Wesentlichen ein europ\u00e4ischer Kolonialimport ist) v\u00f6llig unterscheidet.<\/p>\n\n\n\n<form method=\"post\" action=\"https:\/\/newsletter.infomaniak.com\/external\/submit\" class=\"inf-form\" target=\"_blank\"><input type=\"email\" name=\"email\" style=\"display:none\" \/><input type=\"hidden\" name=\"key\" value=\"eyJpdiI6IlZXRVJGMlRGQUU2alNqUE81bitIUk5adnNVa0c4MllFTStzOHdHT1FQZ3c9IiwidmFsdWUiOiJIYzhwMUVCK1pTNnlhY3MyMmhuZlhReWJqemEwNk93blMxTjFHc0s2VHZrPSIsIm1hYyI6ImVhYTQ5N2I1M2NiYWE4NzBmNjk2NzgzYjliM2Y5NmYzM2E2ZmU3NGQxNTU1ZDFkMTU1MzY5NTdjYjE3ZTJmNTUifQ==\"><input type=\"hidden\" name=\"webform_id\" value=\"7291\"><style> .inf-main_3000311ca56a1cb93397bc676c0b7fff{ background-color:#f5f5f5; padding:25px 20px; margin:25px auto; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-content { margin-top:13px;} .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff span, .inf-main_3000311ca56a1cb93397bc676c0b7fff label, .inf-main_3000311ca56a1cb93397bc676c0b7fff input, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-success p a { color:#555555; font-size:14px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4{ font-size:18px; margin:0px 0px 13px 0px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff label{ font-weight:bold; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input { margin-bottom:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff label { display:block;} .inf-main_3000311ca56a1cb93397bc676c0b7fff input{ height:35px; color:#999999; border: 1px solid #E9E9E9; border:none; padding-left:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error label, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message{ color: #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error input{ border: 1px solid #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input input { width:100%;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message { display: block; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit { text-align:right;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input{ background-color:#777777; color:#ffffff; border:none; font-weight: normal; height:auto; padding:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input.disabled{ opacity: 0.4; } .inf-btn { color: rgb(85, 85, 85); border: medium none; font-weight: normal; height: auto; padding: 7px; display: inline-block; background-color: white; box-shadow: 0px 1px 1px rgba(0, 0, 0, 0.24); border-radius: 2px; line-height: 1em; } .inf-rgpd { margin:25px 0px 15px 0px; color:#555555; } <\/style> <div class=\"inf-main_3000311ca56a1cb93397bc676c0b7fff\"> <h4>NEWSLETTER DES FREIEN BLICKS<\/h4> <span>Erhalten Sie unsere Artikel jeden Sonntag.<\/span> <div class=\"inf-success\" style=\"display:none\"> <h4>Ihre Anmeldung f\u00fcr unseren w\u00f6chentlichen Newsletter wurde erfolgreich registriert!<\/h4> <p> <a href=\"#\" class=\"inf-btn\">\u00ab<\/a> <\/p> <\/div> <div class=\"inf-content\"> <div class=\"inf-input inf-input-text\"> <input type=\"text\" name=\"inf[1]\" data-inf-meta = \"1\" data-inf-error = \"Merci de renseigner une adresse email\" required=\"required\" placeholder=\"E-Mail\" > <\/div> <div class=\"inf-submit\"> <input type=\"submit\" name=\"\" value=\"Anmelden\"> <\/div> <\/div> <\/div> <\/form>\n\n\n\n<p>Menschen aus der ganzen Welt kommen, um das Schloss von Versailles zu bestaunen. Aber wenn \u00fcber Afrika berichtet wird, geht es immer nur um die schlechten Seiten. Stellen Sie sich vor, wie das Image Frankreichs gewesen w\u00e4re, wenn sich alle Artikel \u00fcber das Land auf seine schlechten Seiten konzentriert h\u00e4tten.<\/p>\n\n\n\n<p>Die vorherrschende Sichtweise ist heute: Europa ist sch\u00f6n, Amerika ist cool, Afrika ist ein Rattenloch. Ich habe es mir daher zur Aufgabe gemacht, mich auf die vergessenen Teile der Geschichte zu konzentrieren. Ich will der Welt einen wundersch\u00f6nen Ort zeigen, mit St\u00e4dten und D\u00f6rfern, die so zivilisiert sind wie jeder andere Ort auf der Erde. Ich m\u00f6chte zeigen, dass die Afrikaner ihrer Zeit oftmals voraus waren. Ich will deutlich machen, dass wir den Rest der Welt immer wieder h\u00e4tten \u00fcberholen k\u00f6nnen, wenn wir nicht durch Sklaverei und Kolonialismus in unserem Elan unterbrochen worden w\u00e4ren. Ich spreche nicht von einem imagin\u00e4ren Wakandan, wie in dem Film <em>Black Panther<\/em> von Marvel. Ich meine einen Ort, an dem die Menschen sowohl unvollkommen als auch gut sind und an dem wir vielleicht Ideen geschaffen h\u00e4tten, die die Welt ver\u00e4ndert h\u00e4tten. Vielleicht h\u00e4tten wir eine Regierung aufgebaut, die der Demokratie, wie wir sie heute kennen, \u00fcberlegen gewesen w\u00e4re.<\/p>\n\n\n\n<p>Als die Europ\u00e4er nach Somalia kamen, fanden sie eine Kultur vor, die in vielerlei Hinsicht der ihren \u00e4hnelte. Sie fanden St\u00e4mme vor, die zusammenarbeiteten. Haben sie manchmal gek\u00e4mpft? Nat\u00fcrlich haben sie das. Wir sind Menschen. Aber die meiste Zeit wurde der Frieden gewahrt. Es gab K\u00f6nigsh\u00f6fe und die K\u00f6nigreiche wurden durch strategische Heiraten vergr\u00f6\u00dfert. Das ist nicht mit dem vergleichbar, was wir heute kennen.<\/p>\n\n\n\n<p>Aber als die europ\u00e4ischen Kolonialherren kamen, sagten sie: \u00abOh, ihr Wilden, wir werden euch die Zivilisation bringen.\u00bb Wir gingen also von einem ausgekl\u00fcgelten dezentralisierten System, das die Herrschaft starker M\u00e4nner verhinderte, zu Nationalstaaten \u00fcber, die von den Kolonialherren entworfen wurden. Sie f\u00fchrten zentralisierte Kontrollsysteme, formale Grenzen und allgemeine Gesetze ein, die anf\u00e4llig f\u00fcr Korruption waren und immer noch sind.<\/p>\n\n\n\n<p>Die neuen Kolonialgrenzen entsprachen nicht den Stammesgrenzen, sondern waren und sind v\u00f6llig willk\u00fcrlich. Wer innerhalb der neuen Grenzen die Macht an sich rei\u00dft, bekommt die Diamanten, das \u00d6l, die ausl\u00e4ndische Hilfe und alles, was wertvoll ist, in die H\u00e4nde - auch die der anderen St\u00e4mme. So wird die Demokratie zu einem sektiererischen oder ethnischen Schlachtfeld.<\/p>\n\n\n\n<p>In den Vereinigten Staaten glauben wir im Allgemeinen, dass Recht das ist, was der Gesetzgeber beschlie\u00dft. Aber f\u00fcr Menschen, die das <em>Common Law<\/em>, insbesondere den Briten, wird das Gesetz von Richtern im Laufe der Jahrhunderte ausgearbeitet. Die meisten afrikanischen Gesetze waren urspr\u00fcnglich viel n\u00e4her an einem Rechtssystem von <em>Common Law<\/em>. Die neu auferlegten kolonialen \u00abGesetze\u00bb standen v\u00f6llig im Gegensatz zu unseren Traditionen, wodurch ein unnat\u00fcrlicher Druck entstand. Damals gingen wir von den St\u00e4mmen zum Tribalismus \u00fcber, dem heutigen ethnischen Konflikt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-un-cadre-de-revitalisation-pour-l-afrique\"><strong>Ein Rahmen f\u00fcr die Wiederbelebung Afrikas<\/strong><\/h3>\n\n\n\n<p>Das ist die Geschichte, die wir \u00fcber Afrika lehren m\u00fcssen: Vor der Ankunft der Kolonialherren und Sklavenh\u00e4ndler verf\u00fcgte Afrika \u00fcber ein funktionierendes System freier M\u00e4rkte, das mit den wichtigsten Handelsrouten in Europa und Asien verbunden war. Dieses System wurde absichtlich zerst\u00f6rt. Es kann und sollte heute zum Wohle jeder Generation von Afrikanern wieder errichtet werden.<\/p>\n\n\n\n<p>Lassen Sie mich es f\u00fcr Sie zusammenfassen. Nennen Sie es mein Manifest:<\/p>\n\n\n\n<p><strong>1.<\/strong><strong>&nbsp;<\/strong>Alle wohlhabenden Nationen erm\u00f6glichen ihren B\u00fcrgern die Wertsch\u00f6pfung durch Unternehmen. Alle Nationen sch\u00fctzen die Eigentumsrechte, damit B\u00fcrger und Unternehmer nicht bef\u00fcrchten m\u00fcssen, dass Kriminelle oder die Regierung sich willk\u00fcrlich ihres Eigentums bem\u00e4chtigen. Alle Nationen erm\u00f6glichen ihren B\u00fcrgern die freie Gr\u00fcndung von Unternehmen ohne \u00fcberm\u00e4\u00dfige Einschr\u00e4nkungen durch die Beh\u00f6rden. Alle Nationen erm\u00f6glichen es ihren B\u00fcrgern und Unternehmen, in einem stabilen rechtlichen Rahmen mit relativ unparteiischen Gesetzen und Gerichten zu arbeiten, die in der Lage sind, Streitigkeiten fair zu behandeln. Die meisten afrikanischen L\u00e4nder gew\u00e4hren Unternehmen diese grundlegenden Rechte nicht. In internationalen Rankings zur wirtschaftlichen Freiheit und zu Gesch\u00e4ftspraktiken geh\u00f6rt nur Mauritius, eine winzige Inselnation, die heute ein fast europ\u00e4isches Wohlstandsniveau erreicht hat, zu den Spitzenreitern. Einige andere Nationen, darunter Botswana und Ruanda, machen Fortschritte in die richtige Richtung. Die meisten afrikanischen Nationen befinden sich in der unteren H\u00e4lfte oder sogar im unteren Drittel. Unsere Nationen sind im Hinblick auf die wirtschaftliche Freiheit weltweit am schlechtesten aufgestellt.<\/p>\n\n\n\n<p><strong>2.<\/strong>&nbsp;Afrika sollte voller wohlhabender Nationen sein, aber warum? Warum sollten wir uns f\u00fcr Afrika interessieren? Hier ist ein Grund, der f\u00fcr mich und f\u00fcr Sie sehr interessant ist: Eine steigende Flut hebt alle Boote an. Wenn Afrika unterproduktiv ist, und das ist es ganz offensichtlich, dann sind die B\u00fcrger des Kontinents nicht die einzigen Verlierer. In den USA wird oft gesagt, dass unsere gr\u00f6\u00dfte Ressource unsere Menschen sind. Im Zeitalter der Globalisierung ist der Verlust der Talente und der Energie von mehr als einer Milliarde Menschen unkalkulierbar. Was k\u00f6nnte ein befreites Afrika auf allen Ebenen des menschlichen Handelns bewirken? Wir haben K\u00fcnstler, Philosophen, Akademiker, Gesch\u00e4ftsleute, Denker und Macher aller Art, die nur darauf warten, ihre Talente der Welt zu offenbaren. Ich bin der Meinung, dass es acht Milliarden Genies auf der Welt gibt. Jeder von uns ist mit einem einzigartigen Genie auf diese Erde gekommen, und dieses Genie ist ein Teil der L\u00f6sung f\u00fcr die Probleme der Menschheit. Jedes Mal, wenn einem Menschen die M\u00f6glichkeit genommen wird, sein Talent zu zeigen, wird die gesamte Menschheit geschw\u00e4cht.<\/p>\n\n\n\n<p><strong>3.<\/strong>&nbsp;Afrika muss eine Mentalit\u00e4t der Freiwilligkeit an den Tag legen und auf die Erreichung der Wohlstandsziele durch einen positiven kapitalistischen Weg hinarbeiten. Wir d\u00fcrfen nicht einer Opfermentalit\u00e4t verfallen. Sowohl Nichtregierungsorganisationen (NGOs) als auch Antikapitalisten k\u00f6nnen diese Opfermentalit\u00e4t f\u00f6rdern. W\u00e4hrend einige NGOs sich auf echtes Empowerment konzentrieren, betrachten andere Afrikaner allzu oft als erb\u00e4rmliche Objekte, die einen wei\u00dfen Retter brauchen. Sie kommunizieren diese Botschaft sowohl offen als auch indirekt. Ja, das kann aufgrund mangelnder M\u00f6glichkeiten schwierig sein. Antikapitalistische Intellektuelle in Afrika und im Ausland wiederholen unerm\u00fcdlich einen Opferdiskurs, wonach Afrika wegen der Sklaverei, des Kolonialismus und der st\u00e4ndigen Ausbeutung arm sei. Ja, Afrika war ein Opfer. Aber solange dieselben intellektuellen Kr\u00e4fte nicht den positiven kapitalistischen Weg formuliert und gebilligt haben, der es uns erm\u00f6glicht, diese Vergangenheit hinter uns zu lassen, sind sie Teil des Problems und nicht der L\u00f6sung. <em>Sie sind die B\u00f6sen.<\/em><\/p>\n\n\n\n<p>Zum Schluss noch ein paar pers\u00f6nliche Worte. Ich wollte aus zwei Gr\u00fcnden Produkte in Afrika herstellen: Erstens, weil ich sehr an der Schaffung von Arbeitspl\u00e4tzen in meinem Land interessiert bin, insbesondere an hochwertigen Produkten, die beweisen, dass wir die Decke \u00fcber dem Strohdach durchbrechen k\u00f6nnen. Ich muss sagen, dass es trotz meines Wagemuts eine Weile gedauert hat, bis ich mich mit der Herstellung von Produkten in Afrika wohlgef\u00fchlt habe.<\/p>\n\n\n\n<p>Der zweite Grund, warum ich Produkte in Afrika herstellen wollte, ist zugegebenerma\u00dfen idealistischer: Wenn wir nicht nach der W\u00fcrde des afrikanischen Volkes schreien, wer dann? Wenn Sie und ich uns nicht f\u00fcr den Wohlstand Afrikas einsetzen, wer soll es dann tun? Die meisten afrikanischen F\u00fchrer wollen sich nur die Taschen f\u00fcllen. Die meisten derjenigen, die internationale Hilfsorganisationen leiten, sind nicht bereit, Afrikas Unternehmergeist, Unabh\u00e4ngigkeit und Selbstachtung zu verteidigen. Auch heute noch ist ein herablassender Ansatz des Mitleids gegen\u00fcber den Afrikanern die Norm. Wir m\u00fcssen <em>F\u00fchrungspers\u00f6nlichkeiten<\/em> Die meisten Menschen, die sich f\u00fcr diese alternative Bewegung einsetzen, haben sich in den letzten Jahren zu einer der gr\u00f6\u00dften und am l\u00e4ngsten anhaltenden Gruppen entwickelt.<\/p>\n\n\n\n<p>Meine gr\u00f6\u00dfte Hoffnung ist, dass wir uns endlich darauf einigen k\u00f6nnen, dass die Afrikaner ein Gesch\u00e4ftsumfeld von Weltklasse und kapitalistische Institutionen von Weltklasse verdienen, wie sie die B\u00fcrger D\u00e4nemarks, Neuseelands, der Schweiz und der Vereinigten Staaten von Amerika genie\u00dfen. Ich bitte Sie, wenn Ihnen die Schwarzen Afrikas wirklich am Herzen liegen, wenn Sie sich wirklich um uns sorgen, sich mir als hartn\u00e4ckige Verfechter der wirtschaftlichen Freiheit in Afrika anzuschlie\u00dfen.<\/p>\n\n\n\n<p><em>Dieser Text ist ein \u00fcberarbeiteter Auszug aus dem neuen Buch von Magatte Wade, <\/em>The Heart of a Cheetah <em>(\u00abDas Herz eines Geparden\u00bb), ein Auszug, der urspr\u00fcnglich in der deutschsprachigen Zeitschrift <\/em>Schweizer Monat<em>, davon <\/em>Le Regard Libre<em> \u00fcbersetzt Artikel im Laufe der Ausgaben.<\/em><\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-vous-venez-de-lire-une-tribune-tiree-de-notre-notre-edition-papier-le-regard-libre-nbsp-n-103\">Sie haben gerade einen Gastbeitrag aus unserer Printausgabe gelesen (<a href=\"https:\/\/leregardlibre.com\/de\/cpt-editions\/le-regard-libre-n103-dossier-transport\/\"><em>Le Regard Libre<\/em>&nbsp;N\u00b0103<\/a>).<\/h6>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:18% auto\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"333\" height=\"500\" src=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/200090088.jpg\" alt=\"\" class=\"wp-image-522374 size-full\" srcset=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/200090088.jpg 333w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/200090088-200x300.jpg 200w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/200090088-100x150.jpg 100w, https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/200090088-300x450.jpg 300w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Magatte Wade<br><em>The Heart of a Cheetah<br><\/em>Cheetah Press<br>November 2023<br>242 Seiten<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.magattewade.com\/book\">Das Buch bestellen<\/a><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kontinent hatte jahrhundertelang freien Handel und dezentralisierte Institutionen, bevor die Kolonialherren kamen. Heute liegt die Wiederbelebung Afrikas in den H\u00e4nden seiner B\u00fcrger.<\/p>","protected":false},"author":718,"featured_media":522385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27371],"tags":[61519,615812,153704,501212,146581,644356564],"class_list":["post-522371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","tag-afrique","tag-capitalisme","tag-colonies","tag-libre-echange","tag-ong","tag-tribunes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique<\/title>\n<meta name=\"description\" content=\"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/wirtschaft\/les-africains-meritent-de-retrouver-la-liberte-economique\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique\" \/>\n<meta property=\"og:description\" content=\"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/wirtschaft\/les-africains-meritent-de-retrouver-la-liberte-economique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-06T19:09:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-1024x683.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Magatte Wade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Magatte Wade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/\"},\"author\":{\"name\":\"Magatte Wade\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/5fcb350199c42757c33be0414e275774\"},\"headline\":\"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique\",\"datePublished\":\"2024-02-14T05:00:00+00:00\",\"dateModified\":\"2025-04-06T19:09:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/\"},\"wordCount\":2441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg\",\"keywords\":[\"Afrique\",\"Capitalisme\",\"Colonies\",\"Libre-\u00e9change\",\"ONG\",\"Tribune\"],\"articleSection\":[\"Economie\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/\",\"name\":\"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg\",\"datePublished\":\"2024-02-14T05:00:00+00:00\",\"dateModified\":\"2025-04-06T19:09:14+00:00\",\"description\":\"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg\",\"width\":1920,\"height\":1280,\"caption\":\"Magatte Wade, femme d'affaires se\u0301ne\u0301galaise, dirige dirige le Centre pour la prosp\u00e9rit\u00e9 africaine au sein du r\u00e9seau Atlas, la principale organisation de groupes de r\u00e9flexion sur l\u2019\u00e9conomie de march\u00e9 en Afrique. \u00a9 Carla Taylor Photographer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/economie\\\/les-africains-meritent-de-retrouver-la-liberte-economique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/5fcb350199c42757c33be0414e275774\",\"name\":\"Magatte Wade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g\",\"caption\":\"Magatte Wade\"},\"description\":\"La femme d\u2019affaires s\u00e9n\u00e9galaise Magatte Wade dirige le Centre pour la prosp\u00e9rit\u00e9 africaine au sein du r\u00e9seau Atlas, la principale organisation de groupes de r\u00e9flexion sur l\u2019\u00e9conomie de march\u00e9 en Afrique.\",\"sameAs\":[\"http:\\\/\\\/magattewade.com\"],\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/magatte-wade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Afrikaner verdienen es, wieder wirtschaftliche Freiheit zu erlangen","description":"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/wirtschaft\/les-africains-meritent-de-retrouver-la-liberte-economique\/","og_locale":"de_DE","og_type":"article","og_title":"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique","og_description":"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.","og_url":"https:\/\/leregardlibre.com\/de\/wirtschaft\/les-africains-meritent-de-retrouver-la-liberte-economique\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2024-02-14T05:00:00+00:00","article_modified_time":"2025-04-06T19:09:14+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-1024x683.jpeg","type":"image\/jpeg"}],"author":"Magatte Wade","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Magatte Wade","Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/"},"author":{"name":"Magatte Wade","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/5fcb350199c42757c33be0414e275774"},"headline":"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique","datePublished":"2024-02-14T05:00:00+00:00","dateModified":"2025-04-06T19:09:14+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/"},"wordCount":2441,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg","keywords":["Afrique","Capitalisme","Colonies","Libre-\u00e9change","ONG","Tribune"],"articleSection":["Economie"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/","url":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/","name":"Afrikaner verdienen es, wieder wirtschaftliche Freiheit zu erlangen","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg","datePublished":"2024-02-14T05:00:00+00:00","dateModified":"2025-04-06T19:09:14+00:00","description":"L\u2019Afrique a connu le libre-\u00e9change avant l\u2019arriv\u00e9e des colonisateurs. La revitalisation du continent est entre les mains de ses citoyens.","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/02\/magatte-wade-femme-daffaires-senegalaise--carla-taylor-photographer-e1707850354980.jpeg","width":1920,"height":1280,"caption":"Magatte Wade, femme d'affaires se\u0301ne\u0301galaise, dirige dirige le Centre pour la prosp\u00e9rit\u00e9 africaine au sein du r\u00e9seau Atlas, la principale organisation de groupes de r\u00e9flexion sur l\u2019\u00e9conomie de march\u00e9 en Afrique. \u00a9 Carla Taylor Photographer"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/economie\/les-africains-meritent-de-retrouver-la-liberte-economique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Les Africains m\u00e9ritent de retrouver la libert\u00e9 \u00e9conomique"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/5fcb350199c42757c33be0414e275774","name":"Magatte Wade","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c2247f6a1c27e1aa4456d52fd49cc72e90b239589f0d3aaf749f84f29f8dc24?s=96&d=identicon&r=g","caption":"Magatte Wade"},"description":"Die senegalesische Gesch\u00e4ftsfrau Magatte Wade leitet das Zentrum f\u00fcr afrikanischen Wohlstand innerhalb des Atlas-Netzwerks, der f\u00fchrenden Organisation marktwirtschaftlicher Think Tanks in Afrika.","sameAs":["http:\/\/magattewade.com"],"url":"https:\/\/leregardlibre.com\/de\/author\/magatte-wade\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/522371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/718"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=522371"}],"version-history":[{"count":2,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/522371\/revisions"}],"predecessor-version":[{"id":522386,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/522371\/revisions\/522386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/522385"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=522371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=522371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=522371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}