{"id":523270,"date":"2024-04-29T06:00:00","date_gmt":"2024-04-29T04:00:00","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=523270"},"modified":"2024-04-29T20:20:53","modified_gmt":"2024-04-29T18:20:53","slug":"andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/politik\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/","title":{"rendered":"Andy Ngo: \u00abMein Angriff wurde von der radikalen Linken gefeiert\u00bb.\u00bb"},"content":{"rendered":"<p class=\"has-drop-cap\"><strong>Der Undercover-Journalist Andy Ngo wurde wegen seiner Berichterstattung \u00fcber politische Demonstrationen zum Feind der Antifa-Bewegung und wurde mehrfach verpr\u00fcgelt. Er warnt die Schweizer vor Naivit\u00e4t.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><em>L\u2019<a href=\"https:\/\/schweizermonat.ch\/der-angriff-gegen-mich-wurde-von-der-radikalen-linken-gefeiert\/\">Originalartikel<\/a><strong>\u00a0<\/strong>ist auf Deutsch erschienen in\u00a0<\/em>Schweizer Monat<em>.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-andy-vous-avez-grandi-a-portland-dans-l-oregon-beaucoup-de-gens-connaissent-la-ville-grace-a-la-serie-televisee-portlandia-la-ville-etait-autrefois-connue-dans-le-monde-entier-comme-le-coeur-de-la-politique-democrate-ou-vivent-les-hipsters-de-gauche-comment-portland-a-t-elle-evolue-au-cours-des-vingt-dernieres-annees\">Andy, vous avez grandi \u00e0 Portland, dans l\u2019Oregon; beaucoup de gens connaissent la ville gr\u00e2ce \u00e0 la s\u00e9rie t\u00e9l\u00e9vis\u00e9e <em>Portlandia<\/em>. La ville \u00e9tait autrefois connue dans le monde entier comme le c\u0153ur de la politique d\u00e9mocrate, o\u00f9 vivent les hipsters de gauche. Comment Portland a-t-elle \u00e9volu\u00e9 au cours des vingt derni\u00e8res ann\u00e9es?<\/h6>\n\n\n\n<p>\u00abPortlandia\u00bb a contribu\u00e9 \u00e0 faire conna\u00eetre les belles choses de Portland au grand public. Les gens aimaient le fait que c\u2019\u00e9tait d\u00e9cal\u00e9 et \u00e9trange et qu\u2019il y avait un sentiment de politique de gauche exag\u00e9r\u00e9, mais aussi attachant d\u2019une certaine mani\u00e8re. Les choses ont pris une tournure critique en 2016 lorsque Donald Trump est devenu le candidat pr\u00e9sidentiel du Parti r\u00e9publicain et a organis\u00e9 des rassemblements \u00e9lectoraux \u00e0 travers le pays. La presse et ses critiques se sont ralli\u00e9s \u00e0 l\u2019accusation et au discours selon lequel il \u00e9tait un candidat fasciste et que son programme et ses rassemblements politiques \u00e9taient bas\u00e9s sur le racisme et la supr\u00e9matie blanche. Dans ce contexte, cette affirmation s\u2019est r\u00e9pandue \u00e0 travers les Etats-Unis. Cependant, elle \u00e9tait plus r\u00e9pandue \u00e0 Portland qu\u2019ailleurs, car la ville poss\u00e8de une monoculture sociale de gauche homog\u00e8ne.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-comment-cette-monoculture-s-est-elle-manifestee\">Comment cette monoculture s\u2019est-elle manifest\u00e9e?<\/h6>\n\n\n\n<p>Apr\u00e8s qu\u2019il fut devenu clair que Trump remporterait les \u00e9lections de 2016, des milliers d\u2019habitants de Portland sont descendus dans les rues du centre-ville et Portland a \u00e9t\u00e9 le th\u00e9\u00e2tre de certaines des plus grandes manifestations des Etats-Unis \u00e0 propos des r\u00e9sultats des \u00e9lections. Bien que des violences politiques de gauche aient d\u00e9j\u00e0 eu lieu, c\u2019\u00e9tait la premi\u00e8re fois que moi-m\u00eame et la majorit\u00e9 des habitants de Portland \u00e9tions t\u00e9moins d\u2019une violence politique de grande ampleur perp\u00e9tr\u00e9e par le mouvement d\u2019extr\u00eame gauche Antifa.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-vous-avez-decide-d-embarquer-votre-camera-et-de-filmer-les-manifestations-pour-savoir-ce-qui-se-passait-pourquoi\">Vous avez d\u00e9cid\u00e9 d\u2019embarquer votre cam\u00e9ra et de filmer les manifestations pour savoir ce qui se passait. Pourquoi?<\/h6>\n\n\n\n<p>J\u2019\u00e9tais r\u00e9dacteur pour le journal \u00e9tudiant de l\u2019Universit\u00e9 d\u2019Etat de Portland. Mon r\u00e9dacteur en chef m\u2019a demand\u00e9 de prendre des vid\u00e9os ou des photos des manifestations. Je suis donc sorti avec mon iPhone pour immortaliser les \u00e9v\u00e9nements. Il \u00e9tait extr\u00eamement choquant de constater le niveau de violence et de destruction qui r\u00e9gnait dans le centre-ville: incendies, vitres bris\u00e9es, voitures fracass\u00e9es, la police \u00e9tait compl\u00e8tement d\u00e9bord\u00e9e. Portland est devenu un haut lieu aux Etats-Unis pour les combats de rue et les bagarres entre la gauche et la droite.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-donc-la-droite-aussi-a-agi-violemment\">Donc la droite aussi a agi violemment?<\/h6>\n\n\n\n<p>Bien qu\u2019il n\u2019existe pas de mouvement de droite organis\u00e9 \u00e0 Portland, certains partisans du pr\u00e9sident Trump des villes voisines ont d\u00e9cid\u00e9 d\u2019exercer leur droit \u00e0 la libert\u00e9 d\u2019expression et de le soutenir. Ils se sont d\u00e9lib\u00e9r\u00e9ment rendus dans des endroits o\u00f9 ils n\u2019\u00e9taient pas les bienvenus \u2013 et cela incluait Portland. Chaque fois qu\u2019ils sont venus, des milliers de contre-manifestants se sont pr\u00e9sent\u00e9s, et les antifas se sont montr\u00e9s explicitement violents. La police a eu du mal \u00e0 contenir ce type de violence, en particulier au cours des \u00e9t\u00e9s 2017 \u00e0 2019. Les procureurs de Portland ont principalement cibl\u00e9 les individus de droite qui se livraient \u00e0 des violences criminelles. Leur excuse pour cette approche s\u00e9lective \u00e9tait qu\u2019ils ne pouvaient pas identifier ceux qui avaient le visage couvert, \u00e0 savoir les antifas. Au fil du temps, les violents manifestants d\u2019extr\u00eame gauche ont rencontr\u00e9 peu de r\u00e9sistance.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-comment-le-gouvernement-devrait-il-traiter-avec-antifa\">Comment le gouvernement devrait-il traiter avec Antifa?<\/h6>\n\n\n\n<p>Les citoyens, les journalistes et les hommes politiques ne peuvent tol\u00e9rer la violence politique. Le recours \u00e0 la violence extrajudiciaire, pour quelque raison que ce soit, ne peut \u00eatre tol\u00e9r\u00e9. J\u2019ai vu cette violence militaris\u00e9e aux Etats-Unis pour des raisons pr\u00e9sent\u00e9es comme particuli\u00e8rement nobles. C\u2019est pourquoi l\u2019extr\u00eame gauche est si manipulatrice, trompeuse et efficace. Leur violence \u00e9tait au nom de la lutte pour la vie des Noirs \u2013 et contre le racisme, la supr\u00e9matie blanche, les armes et le fascisme. Malheureusement, de nombreuses personnes et politiciens ont trouv\u00e9 cela acceptable; ils \u00e9taient tellement d\u2019accord avec la cause qu\u2019ils ont accept\u00e9 ces actions violentes.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-que-faut-il-savoir-sur-le-mouvement-antifa\">Que faut-il savoir sur le mouvement Antifa?<\/h6>\n\n\n\n<p>Antifa lui-m\u00eame fonctionne tr\u00e8s diff\u00e9remment d\u2019un pays \u00e0 l\u2019autre. La culture politique de la soci\u00e9t\u00e9 dans laquelle elle s\u2019organise, ainsi que la l\u00e9gislation pertinente, affectent ses objectifs et ses tactiques. L\u2019Antifa am\u00e9ricain s\u2019inspire de l\u2019Antifa le plus violent au monde, qui \u2013 historiquement et actuellement \u2013 \u200b\u200bvient d\u2019Allemagne. Sa tactique consiste \u00e0 d\u00e9truire publiquement les biens. Aux Etats-Unis, selon la ville dans laquelle ils se trouvaient \u2013 de mani\u00e8re tr\u00e8s efficace et sans entrave \u00e0 Portland et \u00e0 Seattle et, dans une moindre mesure, \u00e0 New York et \u00e0 Oakland \u2013 ils ont pu commettre des actes de violence. Ce sont des villes de gauche o\u00f9 les d\u00e9mocrates sont majoritaires et tol\u00e8rent ce genre de violence. Antifa a \u00e9galement tent\u00e9 son arnaque dans des villes plus mod\u00e9r\u00e9es avec un certain succ\u00e8s.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-aussi-en-suisse\">Aussi en Suisse?<\/h6>\n\n\n\n<p>Je sais qu\u2019en Suisse, Antifa est organis\u00e9 \u00e0 Berne, mais jusqu\u2019\u00e0 pr\u00e9sent, le mouvement n\u2019a pas \u00e9t\u00e9 aussi violent qu\u2019en Allemagne. Cela a beaucoup \u00e0 voir avec la culture helv\u00e9tique, o\u00f9 tout est ordonn\u00e9 et se d\u00e9roule bien. En Suisse, ces militants radicaux auraient de grandes difficult\u00e9s \u00e0 s\u2019organiser, car l\u2019opinion publique et m\u00eame la gauche suisse ne tol\u00e9reraient pas la destruction massive des biens. La Suisse dispose \u00e9galement d\u2019une presse plus \u00e9quilibr\u00e9e, avec un bon \u00e9quilibre entre les m\u00e9dias de centre droit et de centre gauche.<\/p>\n\n\n\n<form method=\"post\" action=\"https:\/\/newsletter.infomaniak.com\/external\/submit\" class=\"inf-form\" target=\"_blank\"><input type=\"email\" name=\"email\" style=\"display:none\" \/><input type=\"hidden\" name=\"key\" value=\"eyJpdiI6IlZXRVJGMlRGQUU2alNqUE81bitIUk5adnNVa0c4MllFTStzOHdHT1FQZ3c9IiwidmFsdWUiOiJIYzhwMUVCK1pTNnlhY3MyMmhuZlhReWJqemEwNk93blMxTjFHc0s2VHZrPSIsIm1hYyI6ImVhYTQ5N2I1M2NiYWE4NzBmNjk2NzgzYjliM2Y5NmYzM2E2ZmU3NGQxNTU1ZDFkMTU1MzY5NTdjYjE3ZTJmNTUifQ==\"><input type=\"hidden\" name=\"webform_id\" value=\"7291\"><style> .inf-main_3000311ca56a1cb93397bc676c0b7fff{ background-color:#f5f5f5; padding:25px 20px; margin:25px auto; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-content { margin-top:13px;} .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff span, .inf-main_3000311ca56a1cb93397bc676c0b7fff label, .inf-main_3000311ca56a1cb93397bc676c0b7fff input, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-success p a { color:#555555; font-size:14px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4{ font-size:18px; margin:0px 0px 13px 0px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff label{ font-weight:bold; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input { margin-bottom:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff label { display:block;} .inf-main_3000311ca56a1cb93397bc676c0b7fff input{ height:35px; color:#999999; border: 1px solid #E9E9E9; border:none; padding-left:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error label, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message{ color: #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error input{ border: 1px solid #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input input { width:100%;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message { display: block; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit { text-align:right;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input{ background-color:#777777; color:#ffffff; border:none; font-weight: normal; height:auto; padding:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input.disabled{ opacity: 0.4; } .inf-btn { color: rgb(85, 85, 85); border: medium none; font-weight: normal; height: auto; padding: 7px; display: inline-block; background-color: white; box-shadow: 0px 1px 1px rgba(0, 0, 0, 0.24); border-radius: 2px; line-height: 1em; } .inf-rgpd { margin:25px 0px 15px 0px; color:#555555; } <\/style> <div class=\"inf-main_3000311ca56a1cb93397bc676c0b7fff\"> <h4>NEWSLETTER DES FREIEN BLICKS<\/h4> <span>Erhalten Sie unsere Artikel jeden Sonntag.<\/span> <div class=\"inf-success\" style=\"display:none\"> <h4>Ihre Anmeldung f\u00fcr unseren w\u00f6chentlichen Newsletter wurde erfolgreich registriert!<\/h4> <p> <a href=\"#\" class=\"inf-btn\">\u00ab<\/a> <\/p> <\/div> <div class=\"inf-content\"> <div class=\"inf-input inf-input-text\"> <input type=\"text\" name=\"inf[1]\" data-inf-meta = \"1\" data-inf-error = \"Merci de renseigner une adresse email\" required=\"required\" placeholder=\"E-Mail\" > <\/div> <div class=\"inf-submit\"> <input type=\"submit\" name=\"\" value=\"Anmelden\"> <\/div> <\/div> <\/div> <\/form>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-a-quand-remonte-la-derniere-fois-que-vous-avez-parle-a-quelqu-un-d-antifa\">A quand remonte la derni\u00e8re fois que vous avez parl\u00e9 \u00e0 quelqu\u2019un d\u2019Antifa?<\/h6>\n\n\n\n<p>J\u2019ai parl\u00e9 \u00e0 des gens qui sympathisent avec cette id\u00e9ologie, mais pas \u00e0 des membres actifs. Quiconque est pleinement ancr\u00e9 dans cette id\u00e9ologie et y joue un r\u00f4le organisationnel actif ne me parlera pas, parce qu\u2019il me consid\u00e8re comme un ennemi. Parler \u00e0 \u00ab\u2009l\u2019ennemi\u2009\u00bb est une des mani\u00e8res d\u2019\u00eatre excommuni\u00e9 de cette communaut\u00e9. Ils appellent r\u00e9guli\u00e8rement \u00e0 attaquer physiquement les \u00ab\u2009tra\u00eetres\u2009\u00bb en guise de vengeance. Ils sont religieusement fondamentalistes et voient le monde de mani\u00e8re binaire\u2009: \u00ab\u2009Vous \u00eates de notre c\u00f4t\u00e9 ou vous ne l\u2019\u00eates pas\u2009; vous \u00eates fasciste ou vous \u00eates antifasciste.\u2009\u00bb<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-les-grands-medias-americains-ont-rendu-compte-des-troubles-a-portland-et-dans-d-autres-villes-ces-titres-ont-ils-rempli-leur-mission\">Les grands m\u00e9dias am\u00e9ricains ont rendu compte des troubles \u00e0 Portland et dans d\u2019autres villes. Ces titres ont-ils rempli leur mission?<\/h6>\n\n\n\n<p>Pendant des ann\u00e9es, les grands m\u00e9dias ont d\u00e9crit la violence politique de gauche comme \u00abdes manifestations essentiellement pacifiques\u00bb, \u00abquelques actes de violence mineurs\u00bb ou \u00abquelques d\u00e9g\u00e2ts mat\u00e9riels\u00bb \u2013 m\u00eame lorsqu\u2019elles \u00e9taient extr\u00eamement violentes. Ces m\u00e9dias ne se sont pas int\u00e9ress\u00e9s aux raisons pour lesquelles les gens descendaient dans la rue pour d\u00e9truire des biens. Ils ont d\u00e9crit ces foules comme des mobilisations \u00e9clair de personnes qui sortaient et devenaient spontan\u00e9ment violentes. Pourtant, elles \u00e9taient organis\u00e9es et portaient des armes, des outils et des uniformes.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-quelles-solutions-existe-t-il-au-probleme-des-antifas\">Quelles solutions existe-t-il au probl\u00e8me des antifas?<\/h6>\n\n\n\n<p>Il s\u2019agit de cr\u00e9er un changement dans la culture. Bien entendu, les Etats-Unis ont des lois contre les meurtres, les agressions, les incendies criminels, etc. Mais les lois deviennent un d\u00e9tail inutile lorsque la soci\u00e9t\u00e9 ne les consid\u00e8re plus comme l\u00e9gitimes. Pour de nombreux gauchistes traditionnels, des choses comme la petite d\u00e9linquance, le vol \u00e0 l\u2019\u00e9talage ou le camping en public ne sont plus des d\u00e9lits. Ils consid\u00e8rent ces choses comme sans importance et jugent ceux qui adoptent un tel comportement comme des victimes m\u00e9ritant de la compassion.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-les-medias-et-l-establishment-donnent-ils-carte-blanche-a-antifa-et-tentent-ils-egalement-de-censurer-ou-de-reprimer-les-groupes-de-droite-qui-deviennent-parfois-violents-lors-des-manifestations-de-rue\">Les m\u00e9dias et l\u2019establishment donnent-ils carte blanche \u00e0 Antifa et tentent-ils \u00e9galement de censurer ou de r\u00e9primer les groupes de droite qui deviennent parfois violents lors des manifestations de rue?<\/h6>\n\n\n\n<p>Aux Etats-Unis, les organisations nationales ne peuvent pas \u00eatre interdites sur la base de leur id\u00e9ologie. C\u2019est pourquoi il peut y avoir des groupes islamistes, n\u00e9onazis et antifas. Le premier amendement prot\u00e8ge leur droit de s\u2019organiser et de s\u2019exprimer librement. Cependant, pour de nombreux politiciens am\u00e9ricains de gauche, cela est assez frustrant. Ils d\u00e9l\u00e8guent donc la censure des opinions de droite \u00e0 la soci\u00e9t\u00e9 civile, par exemple aux r\u00e9seaux sociaux. Les \u00abfichiers Twitter\u00bb ont r\u00e9v\u00e9l\u00e9 un haut niveau de coordination entre les responsables du Parti d\u00e9mocrate et l\u2019ancien r\u00e9gime de Twitter. Quant aux m\u00e9dias, si le public \u00e9tait correctement inform\u00e9 du caract\u00e8re extr\u00e9miste et violent de certains de ces groupes de gauche, ils seraient beaucoup plus critiques \u00e0 l\u2019\u00e9gard de leur pouvoir de recrutement et de leurs id\u00e9es. En revanche, la soci\u00e9t\u00e9 civile sait tr\u00e8s bien d\u00e9truire les organisations de droite.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-vous-avez-ete-severement-agresse-par-antifa-pouvez-vous-nous-en-parler\">Vous avez \u00e9t\u00e9 s\u00e9v\u00e8rement agress\u00e9 par Antifa. Pouvez-vous nous en parler?<\/h6>\n\n\n\n<p>En 2019, j\u2019ai \u00e9t\u00e9 rou\u00e9 de coups dans le centre-ville de Portland lors d\u2019une manifestation Antifa que je couvrais. J\u2019ai \u00e9t\u00e9 frapp\u00e9 \u00e0 plusieurs reprises \u00e0 la t\u00eate et battu par une foule de manifestations tout pr\u00e8s du commissariat de police. Ensuite, ils ont vol\u00e9 mon mat\u00e9riel photo parce qu\u2019ils ne voulaient pas que je divulgue les vid\u00e9os que j\u2019avais prises de leurs actions ce jour-l\u00e0. J\u2019\u00e9tais seul et j\u2019ai d\u00fb appeler la police, monter dans une ambulance et me rendre \u00e0 l\u2019h\u00f4pital.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-avez-vous-subi-des-dommages-physiques-ou-psychologiques-graves\">Avez-vous subi des dommages physiques ou psychologiques graves?<\/h6>\n\n\n\n<p>On m\u2019a diagnostiqu\u00e9 une h\u00e9morragie c\u00e9r\u00e9brale. Ce type de blessure entra\u00eene un taux de mortalit\u00e9 \u00e9lev\u00e9, j\u2019ai donc \u00e9t\u00e9 hospitalis\u00e9 et j\u2019ai eu beaucoup de chance de survivre. Mais j\u2019avais des probl\u00e8mes cognitifs et physiques qui ont n\u00e9cessit\u00e9 plusieurs mois de th\u00e9rapie en milieu m\u00e9dical. L\u2019agression que j\u2019ai subie a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e sur les r\u00e9seaux sociaux par la gauche radicale. Ils \u00e9taient sans filtre et c\u00e9l\u00e9braient la violence. Ils ont affirm\u00e9 que j\u2019avais simul\u00e9 mes blessures.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-je-suppose-que-ce-n-etait-pas-la-derniere-fois-que-vous-avez-ete-attaque\">Je suppose que ce n\u2019\u00e9tait pas la derni\u00e8re fois que vous avez \u00e9t\u00e9 attaqu\u00e9?<\/h6>\n\n\n\n<p>Antifa examine la forme du corps des gens, leur taille, leur posture, leurs chaussures et m\u00eame le type de t\u00e9l\u00e9phone portable dont ils disposent \u2013 \u200b\u200bils mettent toutes ces informations en ligne. A Portland, j\u2019ai \u00e9t\u00e9 confront\u00e9 \u00e0 un groupe qui exigeait que j\u2019enl\u00e8ve mon masque, ce que je n\u2019ai pas fait. L\u2019un d\u2019eux l\u2019a arrach\u00e9e. J\u2019ai couru et couru dans les rues du centre-ville. Ils m\u2019ont violemment battu, m\u2019ont oblig\u00e9 \u00e0 implorer ma vie et m\u2019ont tenu dans un \u00e9tau. J\u2019\u00e9tais compl\u00e8tement couvert de sang lors de cette premi\u00e8re attaque, puis j\u2019ai couru vers un h\u00f4tel voisin. Le personnel ne voulait pas appeler la police, j\u2019ai donc d\u00fb appeler la police moi-m\u00eame. C\u2019\u00e9tait la deuxi\u00e8me racl\u00e9e grave que j\u2019ai subie et qui m\u2019a pouss\u00e9 \u00e0 \u00e9migrer au Royaume-Uni. Je ne peux pas vivre en s\u00e9curit\u00e9 dans une ville am\u00e9ricaine dans un tel climat politique.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-quel-est-votre-message-a-la-suisse\">Quel est votre message \u00e0 la Suisse?<\/h6>\n\n\n\n<p>Le peuple suisse ne doit pas se reposer sur ses lauriers et penser que ce dont il dispose aujourd\u2019hui durera \u00e9ternellement. Regardez simplement vos pays voisins. En France et en Allemagne, il existe des mouvements politiques radicaux qui commettent beaucoup de violence en public. Ils sont motiv\u00e9s par une id\u00e9ologie politique qui peut transcender les fronti\u00e8res. C\u2019est pourquoi je suis un peu inquiet \u00e0 propos de l\u2019organisation Antifa \u00e0 Berne. Oui, ils se comportent l\u00e9galement en ce moment\u2009: les gens brandissent des banderoles, crient des slogans politiques, etc. Mais c\u2019est ainsi que les radicaux de gauche ont commenc\u00e9 aux Etats-Unis. En m\u00eame temps, j\u2019ai confiance dans les institutions politiques suisses. Le syst\u00e8me politique suisse est assez unique, car il oblige les rivaux politiques \u00e0 travailler ensemble, ce qui favorise la stabilit\u00e9.<\/p>\n\n\n\n<p><em>Nach Zahlen, <\/em>Le Regard Libre<em> \u00fcbersetzt Artikel aus dem deutschsprachigen Magazin <\/em>Schweizer Monat<em>. Ronnie Grob est son r\u00e9dacteur en chef.<\/em><\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-vous-venez-de-lire-un-article-en-libre-acces-nbsp-debats-analyses-actualites-culturelles-nbsp-abonnez-vous-nbsp-a-notre-media-de-reflexion-pour-nous-soutenir-et-avoir-acces-a-tous-nos-contenus\">Sie haben gerade einen frei zug\u00e4nglichen Artikel gelesen. Debatten, Analysen, Kulturnachrichten:&nbsp;<a href=\"https:\/\/leregardlibre.com\/de\/abonnement\/\">abonnieren Sie<\/a>&nbsp;um uns zu unterst\u00fctzen und Zugang zu all unseren Inhalten zu erhalten!<\/h6>","protected":false},"excerpt":{"rendered":"<p>Der Undercover-Journalist Andy Ngo wurde wegen seiner Berichterstattung \u00fcber politische Demonstrationen zum Feind der Antifa-Bewegung und wurde mehrfach verpr\u00fcgelt. Er warnt die Schweizer vor Naivit\u00e4t.<\/p>","protected":false},"author":619,"featured_media":523271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1001],"tags":[699,737546,11788,26168,644356898,538],"class_list":["post-523270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-etats-unis","tag-extreme-gauche","tag-interviews","tag-journalisme","tag-militantisme","tag-violence"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb<\/title>\n<meta name=\"description\" content=\"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/politik\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb\" \/>\n<meta property=\"og:description\" content=\"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/politik\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T18:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ronnie Grob\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronnie Grob\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/\"},\"author\":{\"name\":\"Ronnie Grob\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/d32d688410d4358b9764251360991ba3\"},\"headline\":\"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb\",\"datePublished\":\"2024-04-29T04:00:00+00:00\",\"dateModified\":\"2024-04-29T18:20:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/\"},\"wordCount\":2198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kill-andy-ngo--andy-ngo.jpg\",\"keywords\":[\"Etats-Unis\",\"Extr\u00eame gauche\",\"Interview\",\"Journalisme\",\"Militantisme\",\"Violence\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/\",\"name\":\"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kill-andy-ngo--andy-ngo.jpg\",\"datePublished\":\"2024-04-29T04:00:00+00:00\",\"dateModified\":\"2024-04-29T18:20:53+00:00\",\"description\":\"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kill-andy-ngo--andy-ngo.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/kill-andy-ngo--andy-ngo.jpg\",\"width\":1024,\"height\":880,\"caption\":\"L\u2019une des nombreuses inscriptions \u00abKill Andy Ngo\u00bb (\u00abTuez Andy Ngo\u00bb) \u00a9 DR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/politique\\\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/d32d688410d4358b9764251360991ba3\",\"name\":\"Ronnie Grob\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g\",\"caption\":\"Ronnie Grob\"},\"description\":\"R\u00e9dacteur en chef de \u00abSchweizer Monat\u00bb\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/ronnie-grob\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Andy Ngo: \u00abMein Angriff wurde von der radikalen Linken gefeiert\u00bb.\u00bb","description":"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/politik\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/","og_locale":"de_DE","og_type":"article","og_title":"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb","og_description":"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.","og_url":"https:\/\/leregardlibre.com\/de\/politik\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2024-04-29T04:00:00+00:00","article_modified_time":"2024-04-29T18:20:53+00:00","og_image":[{"width":1024,"height":880,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg","type":"image\/jpeg"}],"author":"Ronnie Grob","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Ronnie Grob","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/"},"author":{"name":"Ronnie Grob","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/d32d688410d4358b9764251360991ba3"},"headline":"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb","datePublished":"2024-04-29T04:00:00+00:00","dateModified":"2024-04-29T18:20:53+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/"},"wordCount":2198,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg","keywords":["Etats-Unis","Extr\u00eame gauche","Interview","Journalisme","Militantisme","Violence"],"articleSection":["Politique"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/","url":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/","name":"Andy Ngo: \u00abMein Angriff wurde von der radikalen Linken gefeiert\u00bb.\u00bb","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg","datePublished":"2024-04-29T04:00:00+00:00","dateModified":"2024-04-29T18:20:53+00:00","description":"Le journaliste am\u00e9ricain infiltr\u00e9 Andy\u00a0Ngo, battu \u00e0 plusieurs reprises par des militants antifas, met en garde les Suisses contre la na\u00efvet\u00e9.","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2024\/04\/kill-andy-ngo--andy-ngo.jpg","width":1024,"height":880,"caption":"L\u2019une des nombreuses inscriptions \u00abKill Andy Ngo\u00bb (\u00abTuez Andy Ngo\u00bb) \u00a9 DR"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/politique\/andy-ngo-mon-agression-a-ete-celebree-par-la-gauche-radicale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Andy\u00a0Ngo: \u00abMon agression a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par la gauche radicale\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/d32d688410d4358b9764251360991ba3","name":"Ronnie Grob","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41bfb7a1bd513d8e271a75b435327b2b71804e4444ed942a3b6d10ff0a5c5cdd?s=96&d=identicon&r=g","caption":"Ronnie Grob"},"description":"Chefredaktor \u00abSchweizer Monat\u00bb","url":"https:\/\/leregardlibre.com\/de\/author\/ronnie-grob\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/523270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/619"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=523270"}],"version-history":[{"count":2,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/523270\/revisions"}],"predecessor-version":[{"id":523280,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/523270\/revisions\/523280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/523271"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=523270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=523270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=523270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}