{"id":532589,"date":"2026-05-31T07:30:00","date_gmt":"2026-05-31T05:30:00","guid":{"rendered":"https:\/\/leregardlibre.com\/?p=532589"},"modified":"2026-05-31T16:02:39","modified_gmt":"2026-05-31T14:02:39","slug":"bon-vivant-analyse","status":"publish","type":"post","link":"https:\/\/leregardlibre.com\/de\/societe\/bon-vivant-analyse\/","title":{"rendered":"Der Lebemann im Zeitalter des gesunden Lebens"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><strong>Face aux injonctions de la vie saine, le bon vivant surgit comme un contre-mod\u00e8le. L\u2019occasion de r\u00e9explorer cette figure bien plus riche qu\u2019une simple posture de r\u00e9sistance.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Il suffit d\u2019arpenter quelques rues dans n\u2019importe quelle grande ville occidentale pour constater que les corps sont devenus un projet. Un studio de Pilates au coin de la rue, un restaurant aux menus promettant \u00e9quilibre et vitalit\u00e9, un centre de soins o\u00f9 l\u2019on combat les effets du vieillissement\u2026 La sc\u00e8ne se r\u00e9p\u00e8te \u00e0 New York, Paris ou Zurich avec une r\u00e9gularit\u00e9 certaine. Rien de tr\u00e8s&nbsp;surprenant:&nbsp;le march\u00e9 ne fait que suivre la demande. La tendance est au contr\u00f4le de soi, \u00e0 la discipline du corps et \u00e0 la limitation des exc\u00e8s.<\/p>\n\n\n\n<p>Une \u00e9tude du cabinet McKinsey men\u00e9e en 2024 aupr\u00e8s de plus de 5000 personnes aux Etats-Unis, au Royaume-Uni et en Chine confirme ce que l\u2019on observe \u00e0 l\u2019\u0153il&nbsp;nu:&nbsp;les nouvelles g\u00e9n\u00e9rations, en particulier la Gen Z (1995-2008), contr\u00f4lent fortement leur alimentation et investissent davantage dans le sport et la nutrition que leurs a\u00een\u00e9s. Aux Etats-Unis, le march\u00e9 du bien-\u00eatre conna\u00eet m\u00eame une croissance annuelle comprise entre 5 et 10\u2009%.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-resistance-du-bon-vivant\"><strong>La r\u00e9sistance du bon vivant<\/strong><\/h2>\n\n\n\n<p>Face \u00e0 ces tendances, le temps du bon vivant appartient-il au&nbsp;pass\u00e9?&nbsp;C\u2019est du moins le sentiment qui affleure parfois dans le d\u00e9bat public.&nbsp;\u00abQui&nbsp;veut la peau du bon&nbsp;vivant?&nbsp;Comment r\u00e9sister \u00e0 la tyrannie des nouveaux&nbsp;moralisateurs\u00bb, titrait l\u2019hebdomadaire fran\u00e7ais&nbsp;<em>Le Point<\/em>&nbsp;en d\u00e9cembre 2019. Deux ans plus tard, le journal \u00e9conomique&nbsp;<em>Les Echos<\/em>&nbsp;retra\u00e7ait l\u2019aventure de&nbsp;\u00abGueuleton\u00bb, un groupe de jeunes entrepreneurs ayant b\u00e2ti un r\u00e9seau de restaurants et de traiteurs autour d\u2019un imaginaire assum\u00e9 du bon vivant.&nbsp;\u00abUn&nbsp;art de vivre \u00e0 part enti\u00e8re, une vision de la bonne ch\u00e8re \u00e0 la fois rajeunie et d\u00e9complex\u00e9e, o\u00f9 la po\u00eal\u00e9e de c\u00e8pes l\u2019emporte d\u2019office sur le&nbsp;quinoa\u00bb, r\u00e9sumait le quotidien hexagonal.<\/p>\n\n\n\n<p>La figure du bon vivant est ainsi convoqu\u00e9e comme un contre-mod\u00e8le, un instrument de r\u00e9sistance face \u00e0 une \u00e9poque per\u00e7ue comme trop normative. Contact\u00e9, le psychiatre genevois Michel Kummer, auteur de&nbsp;<em>L\u2019Histoire de France sur le divan<\/em>, livre cette&nbsp;analyse:&nbsp;\u00abIl&nbsp;y a aujourd\u2019hui une forme d\u2019exc\u00e8s de moralit\u00e9 et de contr\u00f4le, une tyrannie du sain, une qu\u00eate de puret\u00e9 physique. Cela renvoie aussi \u00e0 des ressorts plus profonds et&nbsp;philosophiques:&nbsp;la peur du vieillissement, le fantasme de la vie \u00e9ternelle, l\u2019illusion que l\u2019on peut tout anticiper et tout diriger dans nos existences.\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-present-sans-angoisse\"><strong>Un pr\u00e9sent sans angoisse<\/strong><\/h2>\n\n\n\n<p>Sur un plan plus symbolique, le bon vivant renvoie \u00e0 un go\u00fbt du plaisir et une abondance devenues suspectes dans une \u00e8re marqu\u00e9e par la restriction et la peur de l\u2019avenir. Il donne le sentiment d\u2019un monde encore stable, o\u00f9 l\u2019on ne calcule pas tous ses faits et gestes. Il r\u00e9conforte, d\u00e9complexe et offre une exp\u00e9rience presque&nbsp;extatique:&nbsp;celle d\u2019un pr\u00e9sent sans angoisse, lib\u00e9r\u00e9 des injonctions \u00e0 la performance et au contr\u00f4le de soi.<\/p>\n\n\n\n<p>Historiquement, il s\u2019est aussi construit en opposition aux normes morales d\u00e9finies par les pouvoirs religieux. Au XVI<sup>e&nbsp;<\/sup>si\u00e8cle, par exemple, Rabelais c\u00e9l\u00e9brait les connaissances et plaisirs et du corps avec ses personnages Pantagruel et Gargantua, bousculant la rigidit\u00e9 de l\u2019Eglise et de l\u2019\u00e9ducation scholastique.&nbsp;\u00abLa&nbsp;figure du bon vivant a toujours inqui\u00e9t\u00e9 les religions, tout comme les formes contemporaines d\u2019asc\u00e8se qui s\u2019y substituent, rappelle Michel Kummer. Il existe un vieux combat contre le plaisir, o\u00f9 le bon vivant est vu comme un \u00eatre dangereux, glouton et malsain.\u00bb<\/p>\n\n\n\n<form method=\"post\" action=\"https:\/\/newsletter.infomaniak.com\/external\/submit\" class=\"inf-form\" target=\"_blank\"><input type=\"email\" name=\"email\" style=\"display:none\" \/><input type=\"hidden\" name=\"key\" value=\"eyJpdiI6IlZXRVJGMlRGQUU2alNqUE81bitIUk5adnNVa0c4MllFTStzOHdHT1FQZ3c9IiwidmFsdWUiOiJIYzhwMUVCK1pTNnlhY3MyMmhuZlhReWJqemEwNk93blMxTjFHc0s2VHZrPSIsIm1hYyI6ImVhYTQ5N2I1M2NiYWE4NzBmNjk2NzgzYjliM2Y5NmYzM2E2ZmU3NGQxNTU1ZDFkMTU1MzY5NTdjYjE3ZTJmNTUifQ==\"><input type=\"hidden\" name=\"webform_id\" value=\"7291\"><style> .inf-main_3000311ca56a1cb93397bc676c0b7fff{ background-color:#f5f5f5; padding:25px 20px; margin:25px auto; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-content { margin-top:13px;} .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff span, .inf-main_3000311ca56a1cb93397bc676c0b7fff label, .inf-main_3000311ca56a1cb93397bc676c0b7fff input, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-success p a { color:#555555; font-size:14px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4{ font-size:18px; margin:0px 0px 13px 0px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff h4, .inf-main_3000311ca56a1cb93397bc676c0b7fff label{ font-weight:bold; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input { margin-bottom:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff label { display:block;} .inf-main_3000311ca56a1cb93397bc676c0b7fff input{ height:35px; color:#999999; border: 1px solid #E9E9E9; border:none; padding-left:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error label, .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message{ color: #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error input{ border: 1px solid #cc0033; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input input { width:100%;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-input.inf-error span.inf-message { display: block; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit { text-align:right;} .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input{ background-color:#777777; color:#ffffff; border:none; font-weight: normal; height:auto; padding:7px; } .inf-main_3000311ca56a1cb93397bc676c0b7fff .inf-submit input.disabled{ opacity: 0.4; } .inf-btn { color: rgb(85, 85, 85); border: medium none; font-weight: normal; height: auto; padding: 7px; display: inline-block; background-color: white; box-shadow: 0px 1px 1px rgba(0, 0, 0, 0.24); border-radius: 2px; line-height: 1em; } .inf-rgpd { margin:25px 0px 15px 0px; color:#555555; } <\/style> <div class=\"inf-main_3000311ca56a1cb93397bc676c0b7fff\"> <h4>NEWSLETTER DU REGARD LIBRE<\/h4> <span>Recevez nos articles chaque dimanche.<\/span> <div class=\"inf-success\" style=\"display:none\"> <h4>Votre inscription \u00e0 notre infolettre hebdomadaire a \u00e9t\u00e9 enregistr\u00e9e avec succ\u00e8s !<\/h4> <p> <a href=\"#\" class=\"inf-btn\">&laquo;<\/a> <\/p> <\/div> <div class=\"inf-content\"> <div class=\"inf-input inf-input-text\"> <input type=\"text\" name=\"inf[1]\" data-inf-meta = \"1\" data-inf-error = \"Merci de renseigner une adresse email\" required=\"required\" placeholder=\"Email\" > <\/div> <div class=\"inf-submit\"> <input type=\"submit\" name=\"\" value=\"S\u2019inscrire\"> <\/div> <\/div> <\/div> <\/form>\n\n\n\n\n<p>L\u2019habit a chang\u00e9, la m\u00e9fiance est&nbsp;rest\u00e9e:&nbsp;hier dict\u00e9e par le salut de l\u2019\u00e2me, la discipline du corps r\u00e9pond aujourd\u2019hui aux exigences du bien-\u00eatre, de la long\u00e9vit\u00e9 et de l\u2019optimisation de soi. De nouveaux codes moraux tout aussi prescriptifs ont pris le relais. Tant sur le plan symbolique qu\u2019historique, il n\u2019est donc pas surprenant que la figure du bon vivant fasse actuellement office de contre-mod\u00e8le.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-plus-qu-un-instrument-de-resistance\"><strong>Plus qu\u2019un instrument de r\u00e9sistance<\/strong><\/h2>\n\n\n\n<p>Reste que le recours \u00e0 cet art de vivre comporte un&nbsp;risque:&nbsp;le r\u00e9duire \u00e0 un culte de l\u2019exc\u00e8s affranchi de toute morale ou \u00e0 une simple posture de r\u00e9sistance reviendrait \u00e0 l\u2019appauvrir. En effet, en miroir de la tendance au bien-\u00eatre, la contre-tendance des vid\u00e9os m\u00ealant viande, vin et mise en sc\u00e8ne masculiniste est tout aussi performative. La jouissance affich\u00e9e y est moins une fin qu\u2019un signal presque tribal, adress\u00e9 \u00e0 une communaut\u00e9, dirig\u00e9 contre une autre.<\/p>\n\n\n\n<p>Le bon vivant n\u2019est pas condamn\u00e9 \u00e0 devenir le&nbsp;\u00abviandard\u00bb&nbsp;contre le&nbsp;\u00abgar\u00e7on&nbsp;soja\u00bb&nbsp;ni l\u2019ivrogne face \u00e0 l\u2019abstinent. Ces caricatures s\u2019\u00e9loignent fortement d\u2019une v\u00e9ritable \u00e9thique \u2013 et esth\u00e9tique \u2013 du plaisir.&nbsp;Etre&nbsp;un bon vivant engage aussi une&nbsp;morale:&nbsp;une qu\u00eate du bien-vivre, une mani\u00e8re d\u2019habiter sa propre existence sans la r\u00e9duire \u00e0 la seule performance \u2013 ce qui reviendrait \u00e0 imiter la course \u00e0 l\u2019optimisation propre \u00e0 l\u2019obsession sanitaire \u2013 ni \u00e0 la st\u00e9rile provocation, qui fracture et renforce les bulles id\u00e9ologiques et culturelles.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-a-lire-aussi-la-sante-n-est-pas-notre-bien-le-plus-precieux\">A lire aussi | <a href=\"https:\/\/leregardlibre.com\/philosophie\/sante-olivier-massin\/\" type=\"post\" id=\"532483\">La sant\u00e9 n\u2019est pas notre bien le plus pr\u00e9cieux<\/a><\/h6>\n\n\n\n<p>D\u2019Epicure \u00e0 la tradition humaniste, en passant par le&nbsp;<em>convivium<\/em>&nbsp;romain, le plaisir s\u2019est construit sur une recherche du go\u00fbt juste, un sens de la mesure, un \u00e9veil des sens, un art du temps et du lien. Montaigne, dans ses&nbsp;<em>Essais<\/em>, l\u2019a saisi mieux que&nbsp;quiconque:&nbsp;\u00abC\u2019est&nbsp;une absolue perfection, et comme divine, de savoir jouir loyalement de son \u00eatre.\u00bb<\/p>\n\n\n\n<p><em>Journaliste et consultant, <strong>Pablo S\u00e1nchez<\/strong> est r\u00e9dacteur au&nbsp;<\/em>Regard&nbsp;Libre<em>.<\/em><\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-vous-venez-de-lire-une-analyse-tiree-de-notre-dossier-le-plaisir-face-a-la-sante-publie-dans-notre-edition-papier-le-regard-libre-n-126\">Vous venez de lire une analyse tir\u00e9e de notre dossier \u00abLe plaisir face \u00e0 la sant\u00e9\u00bb, publi\u00e9 dans notre \u00e9dition papier (<a href=\"https:\/\/leregardlibre.com\/cpt-editions\/le-regard-libre-126-plaisir-sante\/\" type=\"link\" id=\"https:\/\/leregardlibre.com\/cpt-editions\/le-regard-libre-126-plaisir-sante\/\"><em>Le Regard Libre <\/em>N\u00b0126<\/a>).<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Angesichts der Anordnungen, gesund zu leben, taucht der Lebemann als Gegenmodell auf. Eine Gelegenheit, diese Figur, die viel mehr ist als eine einfache Widerstandshaltung, neu zu erforschen.<\/p>","protected":false},"author":735,"featured_media":532591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8796],"tags":[9472,644339483,25921],"class_list":["post-532589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-analyses","tag-plaisir","tag-sante"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine<\/title>\n<meta name=\"description\" content=\"Face aux injonctions de la vie saine, le bon vivant surgit comme un contre-mod\u00e8le. L\u2019occasion de r\u00e9explorer cette figure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/de\/gesellschaft\/bon-vivant-analyse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine\" \/>\n<meta property=\"og:description\" content=\"Face aux injonctions de la vie saine, le bon vivant surgit comme un contre-mod\u00e8le. L\u2019occasion de r\u00e9explorer cette figure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/de\/gesellschaft\/bon-vivant-analyse\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leregardlibre\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-31T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-31T14:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/\"},\"author\":{\"name\":\"Pablo S\u00e1nchez\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/44629bb0ecb67ddea1fc4c5d4447095f\"},\"headline\":\"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine\",\"datePublished\":\"2026-05-31T05:30:00+00:00\",\"dateModified\":\"2026-05-31T14:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/\"},\"wordCount\":1091,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/camille-brodard--unsplash-scaled-e1780154715875.jpg\",\"keywords\":[\"Analyse\",\"Plaisir\",\"Sant\u00e9\"],\"articleSection\":[\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/\",\"name\":\"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/camille-brodard--unsplash-scaled-e1780154715875.jpg\",\"datePublished\":\"2026-05-31T05:30:00+00:00\",\"dateModified\":\"2026-05-31T14:02:39+00:00\",\"description\":\"Face aux injonctions de la vie saine, le bon vivant surgit comme un contre-mod\u00e8le. L\u2019occasion de r\u00e9explorer cette figure.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/camille-brodard--unsplash-scaled-e1780154715875.jpg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/camille-brodard--unsplash-scaled-e1780154715875.jpg\",\"width\":2560,\"height\":1442,\"caption\":\"La figure du bon vivant est convoqu\u00e9e comme un contre-mod\u00e8le face \u00e0 une \u00e9poque per\u00e7ue comme trop normative. Photo: Camille Brodard (via Unsplash)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/societe\\\/bon-vivant-analyse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/person\\\/44629bb0ecb67ddea1fc4c5d4447095f\",\"name\":\"Pablo S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g\",\"caption\":\"Pablo S\u00e1nchez\"},\"url\":\"https:\\\/\\\/leregardlibre.com\\\/de\\\/author\\\/pablo-sanchez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der Lebemann im Zeitalter des gesunden Lebens","description":"Angesichts der Aufforderungen, gesund zu leben, taucht der Lebemann als Gegenmodell auf. Eine Gelegenheit, diese Figur neu zu erforschen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/de\/gesellschaft\/bon-vivant-analyse\/","og_locale":"de_DE","og_type":"article","og_title":"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine","og_description":"Face aux injonctions de la vie saine, le bon vivant surgit comme un contre-mod\u00e8le. L\u2019occasion de r\u00e9explorer cette figure.","og_url":"https:\/\/leregardlibre.com\/de\/gesellschaft\/bon-vivant-analyse\/","og_site_name":"Le Regard Libre","article_publisher":"https:\/\/www.facebook.com\/leregardlibre\/","article_published_time":"2026-05-31T05:30:00+00:00","article_modified_time":"2026-05-31T14:02:39+00:00","og_image":[{"width":2560,"height":1442,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg","type":"image\/jpeg"}],"author":"Pablo S\u00e1nchez","twitter_card":"summary_large_image","twitter_creator":"@LeRegardLibre","twitter_site":"@LeRegardLibre","twitter_misc":{"Verfasst von":"Pablo S\u00e1nchez","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#article","isPartOf":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/"},"author":{"name":"Pablo S\u00e1nchez","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/44629bb0ecb67ddea1fc4c5d4447095f"},"headline":"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine","datePublished":"2026-05-31T05:30:00+00:00","dateModified":"2026-05-31T14:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/"},"wordCount":1091,"commentCount":0,"publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"image":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg","keywords":["Analyse","Plaisir","Sant\u00e9"],"articleSection":["Soci\u00e9t\u00e9"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/","url":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/","name":"Der Lebemann im Zeitalter des gesunden Lebens","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#primaryimage"},"image":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg","datePublished":"2026-05-31T05:30:00+00:00","dateModified":"2026-05-31T14:02:39+00:00","description":"Angesichts der Aufforderungen, gesund zu leben, taucht der Lebemann als Gegenmodell auf. Eine Gelegenheit, diese Figur neu zu erforschen.","breadcrumb":{"@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#primaryimage","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2026\/05\/camille-brodard--unsplash-scaled-e1780154715875.jpg","width":2560,"height":1442,"caption":"La figure du bon vivant est convoqu\u00e9e comme un contre-mod\u00e8le face \u00e0 une \u00e9poque per\u00e7ue comme trop normative. Photo: Camille Brodard (via Unsplash)"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/societe\/bon-vivant-analyse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"Le bon vivant\u00a0\u00e0 l\u2019heure de la vie saine"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Erste Schweizer Monatszeitschrift f\u00fcr Debatten","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre ist eine Schweizer Monatszeitschrift f\u00fcr intellektuelle und kulturelle Debatten. Seine Redaktion ist jung, ehrenamtlich, liberal und pluralistisch. Das Magazin erscheint online und in gedruckter Form. Seine Sprache ist Franz\u00f6sisch.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"},{"@type":"Person","@id":"https:\/\/leregardlibre.com\/#\/schema\/person\/44629bb0ecb67ddea1fc4c5d4447095f","name":"Pablo S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/042ba7a969c76812b47949be3b376ebea3869c370353c327e7b19305a9698e65?s=96&d=identicon&r=g","caption":"Pablo S\u00e1nchez"},"url":"https:\/\/leregardlibre.com\/de\/author\/pablo-sanchez\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/532589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/users\/735"}],"replies":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/comments?post=532589"}],"version-history":[{"count":3,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/532589\/revisions"}],"predecessor-version":[{"id":532606,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/posts\/532589\/revisions\/532606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media\/532591"}],"wp:attachment":[{"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/media?parent=532589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/categories?post=532589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leregardlibre.com\/de\/wp-json\/wp\/v2\/tags?post=532589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}