{"id":644355549,"count":1,"description":"","link":"https:\/\/leregardlibre.com\/en\/tag\/michael-league\/","name":"michael league","slug":"michael-league","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>michael league | Le Regard Libre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leregardlibre.com\/en\/tag\/michael-league\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"michael league | Le Regard Libre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leregardlibre.com\/en\/tag\/michael-league\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Regard Libre\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/11\/rl_logo_1a-e1762609033480.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2154\" \/>\n\t<meta property=\"og:image:height\" content=\"1264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LeRegardLibre\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/tag\\\/michael-league\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/tag\\\/michael-league\\\/\",\"name\":\"michael league | Le Regard Libre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/tag\\\/michael-league\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/tag\\\/michael-league\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/leregardlibre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"michael league\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#website\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"name\":\"Le Regard Libre\",\"description\":\"Premier mensuel suisse de d\u00e9bat\",\"publisher\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leregardlibre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#organization\",\"name\":\"Le Regard Libre\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"contentUrl\":\"https:\\\/\\\/leregardlibre.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-rl-icone-neg.jpeg\",\"width\":557,\"height\":556,\"caption\":\"Le Regard Libre\"},\"image\":{\"@id\":\"https:\\\/\\\/leregardlibre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leregardlibre\\\/\",\"https:\\\/\\\/x.com\\\/LeRegardLibre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-regard-libre\",\"https:\\\/\\\/www.instagram.com\\\/leregardlibre\\\/\",\"http:\\\/\\\/t.me\\\/leregardlibre\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UC6HzGPomj1LsUmlz-sJtITQ\"],\"description\":\"Le Regard Libre est un mensuel suisse de d\u00e9bat intellectuel et culturel. Sa r\u00e9daction est jeune, b\u00e9n\u00e9vole, lib\u00e9rale et pluraliste. Le magazine para\u00eet en ligne et sous forme papier. Sa langue est le fran\u00e7ais.\",\"email\":\"redaction@leregardlibre.com\",\"legalName\":\"Le Regard Libre\",\"foundingDate\":\"2014-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/leregardlibre.com\\\/a-propos\\\/notre-manifeste\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/leregardlibre.com\\\/mentions-legales\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/leregardlibre.com\\\/conditions-generales-de-vente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"michael league | Le Regard Libre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leregardlibre.com\/en\/tag\/michael-league\/","og_locale":"en_US","og_type":"article","og_title":"michael league | Le Regard Libre","og_url":"https:\/\/leregardlibre.com\/en\/tag\/michael-league\/","og_site_name":"Le Regard Libre","og_image":[{"width":2154,"height":1264,"url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/11\/rl_logo_1a-e1762609033480.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@LeRegardLibre","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/leregardlibre.com\/tag\/michael-league\/","url":"https:\/\/leregardlibre.com\/tag\/michael-league\/","name":"michael league | Le Regard Libre","isPartOf":{"@id":"https:\/\/leregardlibre.com\/#website"},"breadcrumb":{"@id":"https:\/\/leregardlibre.com\/tag\/michael-league\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/leregardlibre.com\/tag\/michael-league\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/leregardlibre.com\/"},{"@type":"ListItem","position":2,"name":"michael league"}]},{"@type":"WebSite","@id":"https:\/\/leregardlibre.com\/#website","url":"https:\/\/leregardlibre.com\/","name":"Le Regard Libre","description":"Switzerland's first monthly debate magazine","publisher":{"@id":"https:\/\/leregardlibre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leregardlibre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leregardlibre.com\/#organization","name":"Le Regard Libre","url":"https:\/\/leregardlibre.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/","url":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","contentUrl":"https:\/\/leregardlibre.com\/wp-content\/uploads\/2025\/08\/logo-rl-icone-neg.jpeg","width":557,"height":556,"caption":"Le Regard Libre"},"image":{"@id":"https:\/\/leregardlibre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leregardlibre\/","https:\/\/x.com\/LeRegardLibre","https:\/\/www.linkedin.com\/company\/le-regard-libre","https:\/\/www.instagram.com\/leregardlibre\/","http:\/\/t.me\/leregardlibre","https:\/\/youtube.com\/channel\/UC6HzGPomj1LsUmlz-sJtITQ"],"description":"Le Regard Libre is a Swiss monthly magazine for intellectual and cultural debate. Its editorial team is young, voluntary, liberal and pluralist. The magazine appears online and in print. Its language is French.","email":"redaction@leregardlibre.com","legalName":"Le Regard Libre","foundingDate":"2014-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/leregardlibre.com\/a-propos\/notre-manifeste\/","ownershipFundingInfo":"https:\/\/leregardlibre.com\/mentions-legales\/","actionableFeedbackPolicy":"https:\/\/leregardlibre.com\/conditions-generales-de-vente\/"}]}},"_links":{"self":[{"href":"https:\/\/leregardlibre.com\/en\/wp-json\/wp\/v2\/tags\/644355549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leregardlibre.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leregardlibre.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leregardlibre.com\/en\/wp-json\/wp\/v2\/posts?tags=644355549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}